{"id":2142,"date":"2009-03-19T18:40:20","date_gmt":"2009-03-19T17:40:20","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/torta-di-carote-argoviese\/"},"modified":"2024-04-08T15:52:26","modified_gmt":"2024-04-08T13:52:26","slug":"svizzera_torta-carote-argoviese","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2009\/03\/19\/svizzera_torta-carote-argoviese\/","title":{"rendered":"Torta di carote argoviese"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Buona festa dei papa&#8217;<\/strong>.<!--more--><\/p>\n<p style=\"text-align: justify;\">Qui a Patatolandia non la festa del papa&#8217; non viene festeggia oggi, 19 marzo, ma a maggio.<br \/>\nCosi&#8217; facendo Stephan sara&#8217; doppiamente festeggiato.<br \/>\nLo so.<\/p>\n<p style=\"text-align: justify;\">La mia intenzione era quella di spegnere il forno per torte e dolci vari ma&#8230; ha nevischiato ancora!<\/p>\n<p style=\"text-align: justify;\">La ricettina di questa &#8220;<strong>Torta di carote argoviese<\/strong>&#8221; di oggi l&#8217;ho presa da Cucina di Stagione e, al momento, siamo ancora in fase di &#8220;raffreddamento&#8221;.<\/p>\n<figure id=\"attachment_10584\" aria-describedby=\"caption-attachment-10584\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10584\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6618.jpg\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6618.jpg 400w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6618-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6618-300x225.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-10584\" class=\"wp-caption-text\">Torta di carote argoviese<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Torta di carote argoviese &#8211; <\/strong>Per 12 fette; teglia a cerniera di 28cm.<\/p>\n<pre style=\"text-align: justify;\"><strong>Pasta frolla:<\/strong>\r\n 40gr biscotti petit beurre\r\n 60gr burro morbido\r\n 60gr zucchero\r\n 30gr nocciole macinate\r\n 1 presa di sale\r\n 1 uovo\r\n 150gr di farina\r\n 0.5 dl di acqua\r\n\r\n<strong>Impasto di carote<\/strong>\r\n 400 g di carote pesate mondate\r\n 1 limone bio\r\n 2 uova\r\n 80gr di zucchero\r\n 150gr di burro morbido\r\n 100gr di nocciole macinate\r\n 1\/4 di cucchiaino di cannella\r\n 170gr di farina\r\n 1 bustina di lievito in polvere\r\n\r\n<strong>Decorazione<\/strong>\r\n 4 cucchiai di confettura d'albicocche\r\n 200gr di zucchero a velo\r\n 6 cucchiai di succo di limone\r\n 50gr di croccante di nocciole o nocciole macinate\r\n 12 carote di marzapane<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Per la pasta frolla<\/strong>, macinate i petit beurre nel tritatutto.<br \/>\nTrasferiteli in una scodella con il burro, lo zucchero, le nocciole e il sale.<br \/>\nSfregate il tutto tra le dita fino a ottenere un impasto bricioloso. Sbattete l&#8217;uovo, mescolatene met\u00c3\u00a0 con l&#8217;impasto sbricioloso e unite l&#8217;acqua.<br \/>\nL&#8217;altra met\u00c3\u00a0 serve per l&#8217;impasto di carote. Incorporate la farina e impastate.<\/p>\n<p style=\"text-align: justify;\">Foderate la teglia con carta da forno.<br \/>\nStendete la pasta frolla a uno spessore di ca. 4 mm e accomodatela sul fondo della teglia. Tagliate la pasta in eccesso, fissate il bordo dello stampo e imburrate.<br \/>\nScaldate il forno 180 \u00c2\u00b0 C.<br \/>\nMettete in fresco lo stampo.<\/p>\n<p style=\"text-align: justify;\"><strong>Per l&#8217;impasto di carote<\/strong>, grattugiate le carote con la grattugia per bircher. Unite la scorza di limone grattugiata fine.<br \/>\nSeparate le uova. Montate a neve ferma gli albumi. Unite a pioggia lo zucchero. Continuate a montare finch\u00c3\u00a9 la massa brilla.<br \/>\nMontate a spuma il burro. Unite gli albumi e il mezzo uovo messo da parte. Incorporate le carote, le nocciole e la cannella. Aggiungete la farina e il lievito e mescolate.<br \/>\nAmalgamate gli albumi in due volte. Versate l&#8217;impasto nella teglia e livellatelo. Cuocete per ca. 45 minuti al centro del forno.<br \/>\nSfornate e staccate il bordo dello stampo.<br \/>\nCapovolgete la torta su uno strofinaccio da cucina e lasciatela raffreddare per ca. 2 ore.<\/p>\n<p style=\"text-align: justify;\">Con l&#8217;aiuto di un piatto capovolgete la torta, in modo che lo strato di pasta frolla sia di nuovo sul fondo.<br \/>\nScaldate la confettura, passatela attraverso un colino e spalmatene uno strato fine sulla torta. Mescolate lo zucchero a velo con il succo di limone fino a ottenere una glassa densa.<br \/>\nSpalmate abbondantemente di glassa la torta, bordo compreso.<br \/>\nCospargete il bordo di croccante e decorate con le carote di marzapane.<\/p>\n<p style=\"text-align: justify;\">Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buona festa dei papa&#8217;.<\/p>\n","protected":false},"author":2,"featured_media":10584,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,168,22,79],"tags":[241,123,88],"class_list":["post-2142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-europa","category-food","category-torte","tag-europa_ovest","tag-festa","tag-frutta_secca"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2142"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2142\/revisions"}],"predecessor-version":[{"id":44759,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2142\/revisions\/44759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/10584"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}