{"id":21350,"date":"2020-03-27T15:39:17","date_gmt":"2020-03-27T14:39:17","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=21350"},"modified":"2020-03-27T12:42:39","modified_gmt":"2020-03-27T11:42:39","slug":"pane-di-segale-fatto-in-casa","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/03\/27\/pane-di-segale-fatto-in-casa\/","title":{"rendered":"Pane di Segale fatto in casa"},"content":{"rendered":"<p style=\"text-align: justify;\">Siamo a casa.<br \/>\nChi piu&#8217; chi meno resta in quarantena (voluta o autovoluta), causata da questo Coronavirus.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Che fare?<br \/>\nIn attesa che il mio licoli (Vera) si risvegli dal torpore, ho del lievito di birra (LdB) in frigo.<\/p>\n<p style=\"text-align: justify;\">Casualmente un mio amico pubblica questo <em><strong><a href=\"https:\/\/www.unsertirol24.com\/2020\/03\/18\/una-montagna-di-sapori-la-riscoperta-del-pane-fatto-in-casa\">link<\/a><\/strong><\/em> su Facebook e&#8230; una luce mi si accende: ecco come usare della farina di segale che giace da tempo nello stipetto.<\/p>\n<p>Eccomi qui, dunque, a proporvi &#8230;.<\/p>\n<p><strong>Ingredienti per il Pane di Segale<\/strong><\/p>\n<pre><strong>Per la biga:\r\n<\/strong>240 g\u00c2\u00a0farina di segale (Roggen per i tedeschi)\r\n190 ml\u00c2\u00a0acqua a 40\u00c2\u00b0C\r\n5 g\u00c2\u00a0Lievito di birra fresco\r\n\r\n<strong>Per l\u00e2\u20ac\u2122impasto:\r\n<\/strong>la biga precedentemente preparata\r\n360 g\u00c2\u00a0farina di segale\r\n400 g\u00c2\u00a0Farina 00 (Rieper Blu)\r\n20g Lievito di birra fresco\r\n490 ml acqua a 35\u00c2\u00b0C\r\n20 g\u00c2\u00a0Sale fino\r\n20 g mix di spezie macinate (cumino, semi di finocchio, trigonella e coriandolo).<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">In una terrina mettete l\u00e2\u20ac\u2122acqua e il lievito e fatelo sciogliere bene.<br \/>\nAggiungete la farina, mescolate con una forchetta.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21361\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_092400-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_092400-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_092400-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_092400-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_092400-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nCoprite con pellicola da cucina e lasciate a lievitare per 2 ore.<\/p>\n<p>Sciogliete il restante lievito in parte dell\u00e2\u20ac\u2122acqua indicata e aggiungete il tutto alla biga, mescolate con una forchetta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21360\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_113037-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_113037-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_113037-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_113037-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_113037-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nUnite le due farine, le spezie e l\u00e2\u20ac\u2122acqua e mescolate sempre con l\u00e2\u20ac\u2122aiuto di una forchetta, infine aggiungete il sale.<\/p>\n<p style=\"text-align: justify;\">Rovesciate l\u00e2\u20ac\u2122impasto sulla spianatoia leggermente infarinata e lavoratelo energicamente per una decina di minuti.<br \/>\nOppure usate un aiutante, come nel mio caso \ud83d\ude42<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21359\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_114555-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_114555-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_114555-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_114555-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_114555-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21358\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_114819-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_114819-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_114819-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_114819-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_114819-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nRiponetelo nuovamente nella terrina, copritelo con pellicola da cucina e fatelo lievitare fino al raddoppio, ci vorranno circa 2-3 ore.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21357\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_114835-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_114835-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_114835-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_114835-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_114835-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21356\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_135055-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_135055-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_135055-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_135055-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_135055-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Riprendete l\u00e2\u20ac\u2122impasto, adagiatelo sulla spianatoia leggermente infarinata, dividetelo in due parti, datene la forma di filoncino non troppo lungo, deve essere abbastanza cicciotto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21355\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_135810-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_135810-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_135810-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_135810-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_135810-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<div class=\"recipe-steps\">\n<p style=\"text-align: justify;\">Foderate una teglia con un foglio di carta forno, infarinatela leggermente con farina di segale ed adagiateci sopra delicatamente i due filoncini.<br \/>\nCoprite con un canovaccio e lasciate lievitare fuori dal forno per circa 30 minuti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21354\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_141742-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_141742-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_141742-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_141742-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_141742-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Accendete il forno in modalit\u00c3\u00a0 statica a 240\u00c2\u00b0C insieme ad un pentolino pieno di acqua, infornate il pane e dopo 5 minuti abbassate la temperatura a 220\u00c2\u00b0C e proseguite per altri 40 minuti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21353\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_141747-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_141747-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_141747-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_141747-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_141747-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Una volta cotto, lasciate raffreddare il pane su una gratella.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21352\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_151703-e1584973415711-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_151703-e1584973415711-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_151703-e1584973415711-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_151703-e1584973415711-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200323_151703-e1584973415711-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Come vedete, la mia unica aggiunta sono stati i tagli e l&#8217;aggiunta di semi di finocchio sulla superficie.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Siamo a casa. Chi piu&#8217; chi meno resta in quarantena (voluta o autovoluta), causata da questo Coronavirus.<\/p>\n","protected":false},"author":2,"featured_media":21354,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,90,91],"tags":[116],"class_list":["post-21350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-lievitati","category-pane","tag-ldb"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=21350"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21350\/revisions"}],"predecessor-version":[{"id":21437,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21350\/revisions\/21437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/21354"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=21350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=21350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=21350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}