{"id":2129,"date":"2009-05-04T18:40:20","date_gmt":"2009-05-04T16:40:20","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/asparagi-con-salsa-alla-senape\/"},"modified":"2022-02-28T15:21:47","modified_gmt":"2022-02-28T14:21:47","slug":"asparagi-con-salsa-alla-senape","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2009\/05\/04\/asparagi-con-salsa-alla-senape\/","title":{"rendered":"Asparagi con salsa alla senape"},"content":{"rendered":"<p style=\"text-align: justify;\">Ecco un modo diverso per gustarsi gli asparagi con le uova.<br \/>\nQuesta volta le uova non sono al tegamino, ma sode.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Qui a Patatolandia si trovano prevalentemente asparagi bianchi, pare che siano piu&#8217; ricercati di quelli verdi.<br \/>\nCosi&#8217; i piatti preparati sono un po&#8217; &#8220;spenti&#8221; e bisogna trovare qualche soluzione per dar loro colore.<br \/>\nNon certo con il nostro asparago verde brillante!<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti per 4:<\/strong><\/p>\n<pre>800gr asparagi bianchi\r\n 40gr burro\r\n 4 upva\r\n olio di oliva\r\n 1 cucchiaino di senape\r\n 1\/2 succo di limone\r\n 20ml di aceto bianco\r\n 10 fili di erba cipollina\r\n 3 gambi prezzemolo\r\n pepe -sale<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Spuntate gli asparagi eliminando la parte dura e legnosa.<br \/>\nPulite il gambo, lavateli e sgocciolateli.<\/p>\n<p style=\"text-align: justify;\">Disponete le uova in un tegamino, copritele di acqua e fatele rassodare 8 minuti dall&#8217;ebollizione.<\/p>\n<p style=\"text-align: justify;\">Lavate il prezzemolo, sgrondatelo, raccogliete le foglie, tritatele finemente.<\/p>\n<p style=\"text-align: justify;\">Pulite con carta assorbente da cucina inumidita le foglie di erba cipollina, tagliuzzatele con le forbici.<br \/>\nSpremete il succo del limone e filtratelo.<\/p>\n<p style=\"text-align: justify;\">Disponete gli asparagi in una teglia che li contenga in piedi in modo adeguato. Aggiungete il burro a dadini e copriteli con acqua fino a coprirli lasciando scoperte le punte.<br \/>\nCoprite e lessate 15 minuti: devono diventare teneri<\/p>\n<p style=\"text-align: justify;\">[<em> Ho usato la vaporiera, 15 minuti ed ho omesso il burro..<\/em>. <em>ho cotto anche le punte. Magari si possono tagliare e cuocerle a parte in <\/em><em>un tempo inferiore<\/em>]<\/p>\n<p>Scolate le uova, raffreddatele sotto l&#8217;acqua fredda, sgusciatele.<br \/>\nTagliatele a meta&#8217;, raccogliete i tuorli, passateli al setaccio raccogliendoli in una ciotola.<\/p>\n<p style=\"text-align: justify;\">Aggiungete la senape, l&#8217;olio, il succo di limone, l&#8217;aceto, l&#8217;erba cipollina, sale e pepe.<\/p>\n<p style=\"text-align: justify;\">Tritate grossolanamente gli albumi e aggiungeteli alla salsa.<br \/>\nMescolate bene!<\/p>\n<p style=\"text-align: justify;\">Riprendete la teglia di cottura degli asparagi, scolateli in un piatto da portata adeguato, prelevate 150ml di fondo di cottura.<\/p>\n<p style=\"text-align: justify;\">Fate restringere il fondo di cottura a fuoco dolce 2 minuti in un padellino.<br \/>\nCospargete gli spinaci con la salsa, irrorateli di fondo di cottura.<\/p>\n<p style=\"text-align: justify;\">Servite subito.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ecco un modo diverso per gustarsi gli asparagi con le uova. Questa volta le uova non sono al tegamino, ma sode.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,60,61],"tags":[85,256],"class_list":["post-2129","post","type-post","status-publish","format-standard","hentry","category-food","category-secondi_piatti","category-uova-formaggio","tag-vaporiera","tag-vegetariano"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2129"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2129\/revisions"}],"predecessor-version":[{"id":19297,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2129\/revisions\/19297"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}