{"id":2124,"date":"2009-05-11T18:40:20","date_gmt":"2009-05-11T17:40:20","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/pomelo-scorzette-candite\/"},"modified":"2019-11-28T18:01:22","modified_gmt":"2019-11-28T17:01:22","slug":"pomelo-scorzette-candite","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2009\/05\/11\/pomelo-scorzette-candite\/","title":{"rendered":"Pomelo: scorzette candite"},"content":{"rendered":"<p style=\"text-align: justify;\">Tempo fa avevo parlato\/scritto del <a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2006\/11\/il-pomelo-questo-sconosciuto\/\">pomelo<\/a> (come frutto)&#8230; questo sconosciuto.<!--more--><\/p>\n<p style=\"text-align: justify;\">Proprio l&#8217;altro giorno, nel supermercato sotto casa, mi sono imbattuta in questa confezione di scorzette di pomelo ricoperte di cioccolato.<\/p>\n<figure id=\"attachment_9296\" aria-describedby=\"caption-attachment-9296\" style=\"width: 150px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9296\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6802.jpg\" alt=\"\" width=\"150\" height=\"200\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6802.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6802-113x150.jpg 113w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><figcaption id=\"caption-attachment-9296\" class=\"wp-caption-text\">Pomelo: scorzette candite<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Come resistere alla tentazione del loro acquisto?<br \/>\nE poi.. erano anche scontate!!<\/p>\n<p style=\"text-align: justify;\">Quindi&#8230; ecco un delizioso utilizzo del frutto.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tempo fa avevo parlato\/scritto del pomelo (come frutto)&#8230; questo sconosciuto.<\/p>\n","protected":false},"author":2,"featured_media":9296,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,22],"tags":[84,107],"class_list":["post-2124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-food","tag-cioccolato","tag-frutta"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2124"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2124\/revisions"}],"predecessor-version":[{"id":9715,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2124\/revisions\/9715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/9296"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}