{"id":21223,"date":"2020-03-16T18:48:43","date_gmt":"2020-03-16T17:48:43","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=21223"},"modified":"2020-03-14T19:16:35","modified_gmt":"2020-03-14T18:16:35","slug":"forza","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/03\/16\/forza\/","title":{"rendered":"Forza!"},"content":{"rendered":"<p style=\"text-align: justify;\">Oramai stiamo tutti, chi piu&#8217; e chi meno, <strong>impazzendo<\/strong> a causa di questa pandemia.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Impazzendo, dato che le persone agiscono in maniera diversa: chi si lascia prendere dal panico, chi resta impassibile, chi assalta supermercati aizzandosi e zuffandosi con gli altri, ed e&#8217; possibile vedere ancora un&#8217;infinita&#8217; di sfaccettature delle caratteristiche umane.<\/p>\n<p style=\"text-align: justify;\">Qui a Patatolandia le uniche decisioni che sono state prese dal Governo sono quelle relative alla chiusura delle scuole (per 3 settimane + 2 settimane di Pasqua), la chiusura di eventi con piu&#8217; di 100 visitatori e, al momento, poche ulteriori restrizioni.<br \/>\nPersonalmente spero solo che prendano esempio dall&#8217;Italia&#8230;<br \/>\nHo visto che i letti negli ospedali sono in un numero elevato rispetto al bel paese, ma onestamente non mi andrebbe di provarli.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-21228\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/posti_letto1.jpg\" alt=\"\" width=\"727\" height=\"826\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/posti_letto1.jpg 727w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/posti_letto1-132x150.jpg 132w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/posti_letto1-264x300.jpg 264w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21229\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/posti_letto.jpg\" alt=\"\" width=\"525\" height=\"405\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/posti_letto.jpg 860w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/posti_letto-150x116.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/posti_letto-300x232.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/posti_letto-768x593.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Con Tobias a casa, abbiamo deciso di comune accordo di vivere normalmente la nostra giornate, tentando di limitare &#8211; per quanto possibile &#8211; i contatti con le persone esterne e le uscite.<br \/>\nPer fortuna abbiamo un giardino, cosi&#8217; da poter prendere una boccata di aria ogni tanto.<\/p>\n<p style=\"text-align: justify;\">E poi?<br \/>\nE poi non ci resta che leggere i vari commenti postati su FB, leggere gli articoli di giornale o sentire la televisione, sperando che tutto si risolva al piu&#8217; presto posibile.<br \/>\nMa non ci vogliamo rattristare, cosi&#8217; magari cucineremo e cercheremo di fare altre cose.<\/p>\n<p>In rete si trovano molte vignette, piu&#8217; o meno simpatiche, ma fino ad ora penso che la migliore per me sia la seguente<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-21224\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/corona.jpg\" alt=\"\" width=\"720\" height=\"808\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/corona.jpg 720w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/corona-134x150.jpg 134w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/corona-267x300.jpg 267w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n<p>Stringiamo i denti ed andiamo avanti.<\/p>\n<p style=\"text-align: justify;\">Sicuramente molte persone di qui non capiranno immediatamente la mia decisione &#8211; che comprende anche Tobias &#8211; di mantenere un poco le distanza ed allontanarci dalle relazioni sociali, e questo mi rattrista molto.<br \/>\nAnche per il mio ragazzo, costretto a casa e senza molti amici intorno &#8211; mi mette maliconia&#8230;<\/p>\n<p>Speriamo solo che tutto vada per il meglio.<\/p>\n<p>&nbsp;<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oramai stiamo tutti, chi piu&#8217; e chi meno, impazzendo a causa di questa pandemia.<\/p>\n","protected":false},"author":2,"featured_media":21225,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-21223","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-life","post_format-post-format-image"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=21223"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21223\/revisions"}],"predecessor-version":[{"id":21230,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21223\/revisions\/21230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/21225"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=21223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=21223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=21223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}