{"id":21217,"date":"2020-03-18T19:31:35","date_gmt":"2020-03-18T18:31:35","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=21217"},"modified":"2022-01-22T17:36:37","modified_gmt":"2022-01-22T16:36:37","slug":"kiribati_te-bua-toro-ni-baukin","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/03\/18\/kiribati_te-bua-toro-ni-baukin\/","title":{"rendered":"# 42 &#8211; Repubblica di Kiribati. Te bua toro ni baukin"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Kiribati<\/strong> (IPA [&#8216;kiribas]), ufficialmente <strong>Republic of Kiribati<\/strong>, \u00c3\u00a8 uno stato insulare dell&#8217;Oceania di circa 120000 abitanti.<\/p>\n<p style=\"text-align: justify;\"><!--more--><br \/>\nL&#8217;ordinamento dello Stato \u00c3\u00a8 una repubblica parlamentare, membro del Commonwealth delle nazioni e l&#8217;attuale presidente \u00c3\u00a8 Taneti Maamau.<br \/>\nLa capitale \u00c3\u00a8 <em>Tarawa Sud<\/em>.<br \/>\nLe lingue ufficiali ivi parlate sono l&#8217;inglese e il gilbertese: il nome del Paese, infatti, \u00c3\u00a8 il modo di dire e di scrivere Gilberts (da Gilbert&#8217;s Islands) in tale lingua.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-30388\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/australasia-e1618405900634.png\" alt=\"\" width=\"500\" height=\"375\" \/><br \/>\n<strong>Ingredienti &#8211; <em><a href=\"https:\/\/www.196flavors.com\/kiribati-te-bua-toro-ni-baukin\/\">Te bua toro ni baukin <\/a><\/em>&#8211;<br \/>\n<\/strong><\/p>\n<pre>1 tazza di farina\r\n1 cucchiaini di lievito in polvere\r\n6 cucchiai di latte in polvere \/\/ latte di soia\r\n1\u00c2\u00bd lb di zucca grattugiata (circa 300gr)\r\n1\u00c2\u00bd lb di cavolo tritato (circa 300gr) \r\n1 limone\r\n\u00c2\u00bd lb di carne in lattina\/in scatola SPAM (circa 200gr)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Sbucciate la zucca e grattugiate la carne in un piatto.<br \/>\nSe la zucca \u00c3\u00a8 grande, potete tagliare la parte superiore e scolpire l&#8217;interno.<br \/>\nScolare l&#8217;acqua in eccesso dalla zucca grattugiata.<\/p>\n<p style=\"text-align: justify;\">Tritate il cavolo e aggiungetelo alla zucca grattugiata.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-22216\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200214_092210-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200214_092210-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200214_092210-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200214_092210-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200214_092210-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Aggiungete la farina, la carne in scatola (magari tagliata a cubetti, dipende dalla consistenza), il latte in polvere (o latte di soia), il cavolo ed lievito in polvere al mix di zucca-cavolo.<br \/>\nMescolate tutti gli ingredienti insieme.<\/p>\n<p style=\"text-align: justify;\">Aggiungete sale, pepe ed il succo di limone.<br \/>\nMettete il composto in una teglia unta con burro o olio.<br \/>\nCuocete in forno a 350 F (circa 180gradi) fino a doratura.<\/p>\n<figure id=\"attachment_21281\" aria-describedby=\"caption-attachment-21281\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21281 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200318_190124-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200318_190124-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200318_190124-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200318_190124-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200318_190124-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-21281\" class=\"wp-caption-text\">Kiribati. Te bua toro ni baukin<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ci vorranno circa 45-50 minuti di cottura.<\/p>\n<figure id=\"attachment_21280\" aria-describedby=\"caption-attachment-21280\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21280 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200318_190636-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200318_190636-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200318_190636-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200318_190636-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200318_190636-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-21280\" class=\"wp-caption-text\">Kiribati. Te bua toro ni baukin<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\">Non potendo uscire molto da casa, per via della autoimposta &#8220;quarantena&#8221;, ho usato della zucca surgelata.<\/li>\n<li style=\"text-align: justify;\">Non ho utilizzato il latte in polvere, ma ho inserito 6 cucchiai di latte normale.<\/li>\n<li style=\"text-align: justify;\">La farina aggiunta era circa 150gr.<\/li>\n<li style=\"text-align: justify;\">Nonostante tutto, non ho capito l&#8217;utilita&#8217; del lievito.<\/li>\n<li style=\"text-align: justify;\">Inoltre aggiunto un goccio di acqua, per riuscire a mischiare il composto, essendo troppo asciutto<\/li>\n<li style=\"text-align: justify;\">Per sbaglio ho eliminato le foto scattate durante il procedimento, mi mangerei le mani, dato che sono riuscita piu&#8217; a trovarle.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<hr \/>\n<p style=\"text-align: justify;\">La cucina delle isole <strong>Kiribati<\/strong> ( pronunciato come Kear-a-bus, NOT Kear-a-bah-ti!) risente dell\u00e2\u20ac\u2122influsso di quella polinesiana e di quella micronesiana, con piatti prevalentemente a base di pesce fresco cotto ed arrostito e accompagnato da riso, patate dolci o da salse pi\u00c3\u00b9 o meno piccanti.<\/p>\n<p style=\"text-align: justify;\">Il piatto tipico del paese \u00c3\u00a8 il <strong>taro<\/strong>, accanto al quale si trovano ottimi crostacei e frutti di mare.<\/p>\n<p style=\"text-align: justify;\">Di buona qualit\u00c3\u00a0 anche la frutta tropicale, come il cocco, le banane o la papaia.<\/p>\n<p style=\"text-align: justify;\">Tra le bevande si segnalano soprattutto i succhi di frutta fresca, veramente saporiti, mentre per ci\u00c3\u00b2 che riguarda gli alcolici, questi sono generalmente di importazione e quindi molto cari.<\/p>\n<p>Enjoy your meal!<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kiribati (IPA [&#8216;kiribas]), ufficialmente Republic of Kiribati, \u00c3\u00a8 uno stato insulare dell&#8217;Oceania di circa 120000 abitanti.<\/p>\n","protected":false},"author":2,"featured_media":21252,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,237],"tags":[176,239],"class_list":["post-21217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","category-oceania","tag-176","tag-micronesia"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=21217"}],"version-history":[{"count":16,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21217\/revisions"}],"predecessor-version":[{"id":30400,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21217\/revisions\/30400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/21252"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=21217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=21217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=21217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}