{"id":21135,"date":"2020-03-08T17:45:03","date_gmt":"2020-03-08T16:45:03","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=21135"},"modified":"2023-03-26T14:50:12","modified_gmt":"2023-03-26T12:50:12","slug":"sudafrica_kapmalaien-boeber","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/03\/08\/sudafrica_kapmalaien-boeber\/","title":{"rendered":"# 39 &#8211; SudAfrica\/Kapmalaien. Boeber (dessert)"},"content":{"rendered":"<p style=\"text-align: justify;\">Ed anche per il <strong>SudAfrica<\/strong> ho trovato un veloce, si fa per dire, dessert.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Viste le origini del SudAfrica, e della sua influenza asiatica, ritroviamo ancora una volta quanto avevamo gia&#8217; assaporato per l&#8217;India, il <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/02\/09\/india_seviyan\/\">Vermicelli Kheer<\/a><\/strong><\/em>.<\/p>\n<p style=\"text-align: justify;\">In questo caso si chiama &#8220;<strong>boeber<\/strong>&#8221; e, fatte pochissime eccezioni nella preparazione, direi che il risultato e&#8217; veramente simile.<\/p>\n<p><strong>Ingredienti<\/strong> per 4 persone di <strong>Boeber<\/strong>.<\/p>\n<pre>3 cucchiai di sago\r\n125ml di acqua\r\n50gr di burro\r\n150gr di spaghettini, spezzati\r\n8-10 capsule di cardamomo\r\n3 stanghe di cannella\r\n200gr di uvetta\r\n2 litri di latte\r\n400gr di zuccheri\r\nqualche goccia di acqua di rose (a piacere)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Mettete il sago in acqua per 30 minuti.<br \/>\nIn una pentola inserite il burro, poi fate abbrustolire leggermente la pasta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21163\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_135228-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_135228-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_135228-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_135228-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_135228-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Aggiungete tutti gli altri ingredienti, ad esclusione dell&#8217;acqua di rose.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21164\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_135533-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_135533-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_135533-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_135533-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_135533-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21165\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_135750-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_135750-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_135750-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_135750-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_135750-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Mescolate ogni tanto, fino a che il budino non risulti cremoso e spesso.<br \/>\nA questo punto aggiungete l&#8217;acqua di rose, secondo il gusto personale.<\/p>\n<figure id=\"attachment_21184\" aria-describedby=\"caption-attachment-21184\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21184 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_162136-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_162136-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_162136-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_162136-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/03\/IMG_20200308_162136-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-21184\" class=\"wp-caption-text\">SudAfrica\/Kapmalaien. Boeber<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Non volendo acquistare il sago solo per pochi grammi, l&#8217;ho sostituito con della farina di semi di carrube.<\/li>\n<li style=\"text-align: justify;\">Fatto un mix tra uvetta e albicocche secche<\/li>\n<\/ul>\n<p>geniet u maaltyd<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ed anche per il SudAfrica ho trovato un veloce, si fa per dire, dessert.<\/p>\n","protected":false},"author":2,"featured_media":21131,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173,82,69,22],"tags":[176,223,54,88],"class_list":["post-21135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa","category-al_cucchiaio","category-dessert","category-food","tag-176","tag-africa_del_sud","tag-cereali","tag-frutta_secca"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=21135"}],"version-history":[{"count":13,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21135\/revisions"}],"predecessor-version":[{"id":41387,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21135\/revisions\/41387"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/21131"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=21135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=21135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=21135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}