{"id":2086,"date":"2009-09-08T18:40:19","date_gmt":"2009-09-08T17:40:19","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/il-mare\/"},"modified":"2018-03-01T11:36:00","modified_gmt":"2018-03-01T10:36:00","slug":"il-mare","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2009\/09\/08\/il-mare\/","title":{"rendered":"Toscana:  mare"},"content":{"rendered":"<p style=\"text-align: justify;\">Qualche di foto della Toscana (San Vincenzo) giusto per ricordami che sono andata anche io in vacanza con Tobias..<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Per Tobias e&#8217; stata la prima volta che ha visto il mare e non he ha avuto assolutamente paura.<br \/>\nPer me e&#8217; stata una piacevole vacanza di 4 settimane, in una localita&#8217; nella quale avevo speso anni di vacanza, facendo volotariato.<\/p>\n<p style=\"text-align: justify;\">Peccato che sia gia&#8217; passato tanto tempo e che non me ne ricordi quasi piu&#8217;..!<\/p>\n<figure id=\"attachment_3379\" aria-describedby=\"caption-attachment-3379\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3379 size-medium\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7048-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7048-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7048.jpg 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-3379\" class=\"wp-caption-text\">Con il camion in spiaggia.<\/figcaption><\/figure>\n<figure id=\"attachment_3380\" aria-describedby=\"caption-attachment-3380\" style=\"width: 225px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3380 size-medium\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7403-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7403-225x300.jpg 225w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7403.jpg 240w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><figcaption id=\"caption-attachment-3380\" class=\"wp-caption-text\">Tobias con il beniamino della spiaggia: Marea!<\/figcaption><\/figure>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3377 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6904.jpg\" alt=\"\" width=\"200\" height=\"150\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3378 size-medium\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6897-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6897-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_6897.jpg 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: justify;\">Per il piccolo\u00c2\u00a0 siamo partiti con fattore di protezione della pelle di 50+ per calare al nulla&#8230;<\/p>\n<p style=\"text-align: justify;\">Ma non e&#8217; servito a molto&#8230; nonostante il biancore della pelle ed i capelli biondi, fortunatamente NON si e&#8217; scottato (ma non ha preso neppure un poco di abbronzatura)<\/p>\n<p style=\"text-align: justify;\">&#8230; PER FORTUNA!!<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qualche di foto della Toscana (San Vincenzo) giusto per ricordami che sono andata anche io in vacanza con Tobias..<\/p>\n","protected":false},"author":2,"featured_media":3380,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[40],"class_list":["post-2086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life","tag-toscana"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2086"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2086\/revisions"}],"predecessor-version":[{"id":3376,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2086\/revisions\/3376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/3380"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}