{"id":2075,"date":"2009-09-21T18:40:19","date_gmt":"2009-09-21T17:40:19","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/i-molinetti-prima-versione\/"},"modified":"2021-03-02T18:01:39","modified_gmt":"2021-03-02T17:01:39","slug":"i-molinetti-prima-versione","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2009\/09\/21\/i-molinetti-prima-versione\/","title":{"rendered":"I Molinetti &#8211; prima versione"},"content":{"rendered":"<p style=\"text-align: justify;\">Ebbene si, anche io ci ho tentato di copiare i biscotti &#8220;Molinetti&#8221; ed il mio risultato non e&#8217; stato soddisfacente come l&#8217;originale.<!--more--><\/p>\n<p style=\"text-align: justify;\">Ho provato ha copiare e riprodurre la ricetta della confezione dei Molinetti, ed il mio risultato non e&#8217; stato altro che delle piccole pallette pressate, abbastanza dure (ma facili da intingersi nella colazione mattutina).<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7714\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7888.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7888.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7888-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7888-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p style=\"text-align: justify;\">Ho seguito piu&#8217; o meno la ricetta, evitando di mettere lo zucchero finale (prima di infornare il tutto) ed i fiocchi d&#8217;avena sono rimasti nel mixer \ud83d\ude41<\/p>\n<p style=\"text-align: justify;\">La farina di grano saraceno e&#8217; stata sostituita dal farro e parte del burro da yoghurt.<\/p>\n<p style=\"text-align: justify;\">Forse sara&#8217; per questo.<br \/>\nChissa&#8217;&#8230;<\/p>\n<p style=\"text-align: justify;\">Ma non demordo, prima o poi (appena avro&#8217; un attimo di tempo) ci ritentero&#8217;.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort&lt;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ebbene si, anche io ci ho tentato di copiare i biscotti &#8220;Molinetti&#8221; ed il mio risultato non e&#8217; stato soddisfacente come l&#8217;originale.<\/p>\n","protected":false},"author":2,"featured_media":7714,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78,69,22],"tags":[54],"class_list":["post-2075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biscotti","category-dessert","category-food","tag-cereali"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2075"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2075\/revisions"}],"predecessor-version":[{"id":29142,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2075\/revisions\/29142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/7714"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}