{"id":2074,"date":"2009-09-22T18:40:19","date_gmt":"2009-09-22T17:40:19","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/torta-con-le-prugne\/"},"modified":"2020-09-09T12:06:45","modified_gmt":"2020-09-09T11:06:45","slug":"torta-con-le-prugne","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2009\/09\/22\/torta-con-le-prugne\/","title":{"rendered":"Torta con le prugne"},"content":{"rendered":"<p style=\"text-align: justify;\">Sembra che non possa fare a meno di questa frutta.. le prugne!<!--more--><\/p>\n<p style=\"text-align: justify;\">Ed ecco l&#8217;ennesima &#8220;<strong>torta con le prugne<\/strong>&#8221; .<\/p>\n<p style=\"text-align: justify;\">Dalla foto un po&#8217; scarna non potrete avere una grossa idea del risultato, ma questo e&#8217; quanto avanzato.. giusto il tempo per scattare!<\/p>\n<p style=\"text-align: justify;\">(Sempre da CucinareBene oramai decimato e senza molte pagine&#8230;)<\/p>\n<figure id=\"attachment_10755\" aria-describedby=\"caption-attachment-10755\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10755\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7925.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7925.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7925-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_7925-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><figcaption id=\"caption-attachment-10755\" class=\"wp-caption-text\">Torta con le prugne<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong><\/p>\n<pre>360gr di farina 00\r\n230gr zucchero\r\n135gr burro\r\n3 uova\r\n1\/2 bicchiere di latte\r\n600gr di prugne nere\r\n1 bustina di lievito\r\n1 pizzico di sale\r\nzucchero a velo (omesso)<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Ungete ed infarinate una tortiera (meglio se a cerniera&#8230;).<\/p>\n<p style=\"text-align: justify;\">Scaldate il forno a 200gradi.<\/p>\n<p style=\"text-align: justify;\">Mettete il resto del burro a pezzetti in una ciotola, aggiungetevi lo zucchero e lavoratelo bene, sino a che e&#8217; ridotto ad una crema.<br \/>\nUnite i tuorli, uno alla volta, continuando a lavorare (gli albumi &#8211; ai quali viene aggiunto il pizzico di sale &#8211; fino a quando saranno montati a neve ben ferma, per aggiungerli alla fine).<\/p>\n<p style=\"text-align: justify;\">Incorporate la farina setacciata con il lievito, poca per volta, alternandola al latte e continuate a mescolare con un cucchiaio di legno.<br \/>\nUnite all&#8217;impasto della torta 2 cucchiaiate di albumi montati a neve precedentemente, incorporandoli bene.<\/p>\n<p style=\"text-align: justify;\">Nel frattempo avrete lavato, asciugato e denocciolato le prugne.<br \/>\nTagliate la polpa di 1\/3 dei frutti a dadini di 1 cm.<br \/>\nRiducete quella delle prugne rimanenti a spicchi<br \/>\n[ Consiglio per la prossima volta: meglio invertire le quantita&#8217;]<\/p>\n<p style=\"text-align: justify;\">Incorporate tutti i dadini di prugne nell&#8217;impasto.<br \/>\nAggiungete gli albumi rimasti con una forchetta, eseguendo dei movimenti verticali per non smontarli.<br \/>\nVersate l&#8217;impasto nella teglia, livellando la superficie.<\/p>\n<p style=\"text-align: justify;\">Infornate per 40 minuti ponendo la teglia nella parte centrale.<br \/>\nTogliete la teglia dal forno e sistemate gli spicchi di frutta sulla superficie cercando diottenere un motivo decorativo.<\/p>\n<p style=\"text-align: justify;\">Mettete ancora in forno e cuocete altri 10 minuti.<br \/>\n(Se la torta si scurisse in superficie, copritela con dell&#8217;alu).<\/p>\n<p style=\"text-align: justify;\">Provate la cottura con uno stecchino, che deve uscire perfettamente asciutto<br \/>\n(Altrimenti abbassata a 190gradi e cuocete per altri 10 minuti).<\/p>\n<p style=\"text-align: justify;\">Spegnete il forno, aprite leggermente lo sportello e lasciate raffreddare.<\/p>\n<p style=\"text-align: justify;\">Sformatela su un piatto e spolverizzatela con zucchero a velo<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sembra che non possa fare a meno di questa frutta.. le prugne!<\/p>\n","protected":false},"author":2,"featured_media":10755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,22,79],"tags":[107],"class_list":["post-2074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-food","category-torte","tag-frutta"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2074"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2074\/revisions"}],"predecessor-version":[{"id":25306,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2074\/revisions\/25306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/10755"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}