{"id":2065,"date":"2009-10-08T18:40:18","date_gmt":"2009-10-08T17:40:18","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/carote-viola\/"},"modified":"2018-04-03T19:47:37","modified_gmt":"2018-04-03T18:47:37","slug":"carote-viola","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2009\/10\/08\/carote-viola\/","title":{"rendered":"Carote&#8230; viola!"},"content":{"rendered":"<p style=\"text-align: justify;\">Lo so.. lo so&#8230;<\/p>\n<p style=\"text-align: justify;\">dovrei andare a fare la spesa con il paraocchi o preparare una lista e mandare Stephan.<!--more--><br \/>\nProprio non so resistere alle tentazioni di acquistare prodotti particolari.<\/p>\n<p style=\"text-align: justify;\">Questa volta mi sono limitata alle <a href=\"http:\/\/it.answers.yahoo.com\/question\/index?qid=20060921092740AA1MVkh\">carote viola<\/a> olandesi, anche se quelle gialle mi strizzavano l&#8217;occhietto.<\/p>\n<figure id=\"attachment_10674\" aria-describedby=\"caption-attachment-10674\" style=\"width: 200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10674\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_8021.jpg\" alt=\"\" width=\"200\" height=\"150\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_8021.jpg 200w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_8021-150x113.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><figcaption id=\"caption-attachment-10674\" class=\"wp-caption-text\">Carote viola<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ed ancora una volta mi sono lasciata trascinare senza pensare a come prepararle.<\/p>\n<p style=\"text-align: justify;\">Beh, ad essere sincera ho preso anche un&#8217;altra verdura, simile ad una grossa rapa che non ricordo neppure come si chiama.<br \/>\nFigurarsi se riusciro&#8217; anche a prepararla in maniera mangiabile.<\/p>\n<p style=\"text-align: justify;\">Staremo a vedere!<\/p>\n<p style=\"text-align: justify;\">Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo so.. lo so&#8230; dovrei andare a fare la spesa con il paraocchi o preparare una lista e mandare Stephan.<\/p>\n","protected":false},"author":2,"featured_media":10674,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,22],"tags":[],"class_list":["post-2065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contorni","category-food"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2065"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2065\/revisions"}],"predecessor-version":[{"id":10675,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2065\/revisions\/10675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/10674"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}