{"id":2063,"date":"2009-10-09T18:40:18","date_gmt":"2009-10-09T17:40:18","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/crema-di-pastinaca\/"},"modified":"2026-02-08T10:46:28","modified_gmt":"2026-02-08T09:46:28","slug":"crema-di-pastinaca","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2009\/10\/09\/crema-di-pastinaca\/","title":{"rendered":"Crema di pastinaca"},"content":{"rendered":"<p style=\"text-align: justify;\">Nel mese invernale le verdure disponibili scarseggiano.<br \/>\nCosi&#8217; ho preso delle pastinache.<br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\">Solitamente le pastinache vengono proposte ai bambini per il loro sapore dolciastro, un misto tra carota, finocchio, sedano.<\/p>\n<p>Questa volta sono finite nel mio carrello.<\/p>\n<p style=\"text-align: justify;\">Ho trovato su un vecchio numero della rivista &#8220;CucinareBene&#8221; questa ricettina, non troppo per bimbi<\/p>\n<p><strong>Ingredienti &#8211; Crema di pastinaca &#8211; per 4<\/strong><\/p>\n<pre>3 pastinache\r\n3 cipolle grandi (<em>sostituite con scalogno<\/em>)\r\n30gr di burro\r\n250ml di vino bianco secco\r\n1 litro di brodo vegetale\r\n60ml di panna liquida (<em>sostituita con besciamella avanzata<\/em> )\r\n20gr zucchero di canna\r\n4 rametti di timo\r\nsale, pepe<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Sbucciate le pastinache, tagliatele a pezzetti.<br \/>\nSpellate le cipolle e tagliatele in fettine sottili.<\/p>\n<p style=\"text-align: justify;\">Scaldate il brodo in un pentolino, tenendolo al caldo.<br \/>\nPulite il timo con carta da cucina inumidita.<\/p>\n<p style=\"text-align: justify;\">Mettete il burro in una casseruola, fatevi rosolare le cipolle 5 minuti, spolverizzate con lo zucchero.<br \/>\nFate caramellare 10 minuti a fuoco dolce.<\/p>\n<p style=\"text-align: justify;\">Scolate 1\/3 di cipolle e tenetele da parte per decorazione.<\/p>\n<p style=\"text-align: justify;\">Unite il vino e le pastinache e lasciate cuocere 20 minuti coperto.<br \/>\nAggiungete il brodo caldo, portate a bollore, abbassate il fuoco e lasciate cuocere per altri 10 minuti.<\/p>\n<p style=\"text-align: justify;\">Frullate il composto, sino ad ottenere una crema liscia e corposa.<\/p>\n<p style=\"text-align: justify;\">Aggiungete la panna, mescolate 1 minuto a fuoco basso.<br \/>\nInsaporite con sale e pepe.<\/p>\n<p style=\"text-align: justify;\">Dividete la crema, spolverizzate di timo e decorate con le cipolle caramellate.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel mese invernale le verdure disponibili scarseggiano. Cosi&#8217; ho preso delle pastinache.<\/p>\n","protected":false},"author":2,"featured_media":3638,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,51,57],"tags":[],"class_list":["post-2063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-primi_piatti","category-zuppa"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2063"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2063\/revisions"}],"predecessor-version":[{"id":51047,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2063\/revisions\/51047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/3638"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}