{"id":2058,"date":"2009-10-20T18:40:18","date_gmt":"2009-10-20T17:40:18","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/budino-di-mele-e-pane\/"},"modified":"2021-03-02T18:35:12","modified_gmt":"2021-03-02T17:35:12","slug":"budino-di-mele-e-pane","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2009\/10\/20\/budino-di-mele-e-pane\/","title":{"rendered":"Budino di mele e pane"},"content":{"rendered":"<p style=\"text-align: justify;\">Andiamo subito al sodo con questa ricetta di &#8220;<strong>BUDINO DI MELE E PANE<\/strong>&#8220;&#8230;<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Budino di mele e pane<br \/>\n<\/strong><\/p>\n<pre>4 mele\r\n180gr di pane raffermo di segale e integrale {ho usato quello di noci}\r\n150gr di burro {o meno!}\r\n2 uova\r\n50gr di mandorle spellate e tritate {avevo delle nocciole, cosi' le ho sostituite..}\r\n50gr di uvetta ammollata e strizzata\r\n100gr di zucchero {o meno!}\r\n1 cucchiaino di cannella<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Riducete il pane in piccole pezzi.<br \/>\nTritateli finemente per 2 minuti nel mixer<\/p>\n<p style=\"text-align: justify;\">Sciogliete 130 gr di burro in un pentolino\u00c2\u00a0 a fuoco dolcissimo senza farlo colorire.<\/p>\n<p style=\"text-align: justify;\">Lavate le mele, asciugatele, sbucciatele e tagliatele a spicchi, eliminando il torsolo, in fettine di 2-3mm di spessore.<\/p>\n<p style=\"text-align: justify;\">Mettete i tuorli in una terrina con lo zucchero e montateli.<br \/>\nAggiungete il pane tritato, le mandorle e la cannella.<\/p>\n<p style=\"text-align: justify;\">Mescolate bene con un cucchiaio di legno per amalgamare il tutto.<\/p>\n<p style=\"text-align: justify;\">Unite l&#8217;uvetta al composto, versate il burro fuso poco alla volta, mescolando.<br \/>\nMontate a neve ferma gli albumi ed incorporateli lentamente alla preparazione con movimenti verticali per non smontarli.<\/p>\n<p style=\"text-align: justify;\">Scaldate il forno a 180gradi.<\/p>\n<p style=\"text-align: justify;\">Imburrate uno stampo di 22cm di diametro e versate 1\/3 del composto.<\/p>\n<p style=\"text-align: justify;\">Coprite con uno strato di mele a spicchi.<br \/>\nProseguite con altri strati di impasto e di spicchi di mele fino ad esaurire gli ingredienti.<\/p>\n<p style=\"text-align: justify;\">Livellate la superficie con il dorso del cucchiaio e terminate con uno strato di mele.<\/p>\n<p style=\"text-align: justify;\">Portate a bollore 2 litri di acqua, versateli in un recipiente che vada in forno e che contenga comodamente lo stampo.<\/p>\n<p>Appoggiate il recipiente ed infornate per 45 minuti.<\/p>\n<p>Sfornate il budino caldo e servitelo nel recipiente di cottura.<\/p>\n<p style=\"text-align: justify;\">E&#8217; possibile cuocerlo anche nel forno a microonde (io ho fatto cosi&#8217;) per 20 minuti alla massima potenza, con piatto rotante.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andiamo subito al sodo con questa ricetta di &#8220;BUDINO DI MELE E PANE&#8220;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82,69,22],"tags":[107,88],"class_list":["post-2058","post","type-post","status-publish","format-standard","hentry","category-al_cucchiaio","category-dessert","category-food","tag-frutta","tag-frutta_secca"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2058"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2058\/revisions"}],"predecessor-version":[{"id":29185,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2058\/revisions\/29185"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}