{"id":20340,"date":"2020-02-10T09:53:07","date_gmt":"2020-02-10T08:53:07","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=20340"},"modified":"2020-02-02T20:55:14","modified_gmt":"2020-02-02T19:55:14","slug":"krapfen-maestro-antonio-chiera","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/02\/10\/krapfen-maestro-antonio-chiera\/","title":{"rendered":"Krapfen del maestro Antonio Chiera"},"content":{"rendered":"<p style=\"text-align: justify;\">Siamo quasi a Carnevale e quest&#8217;anno, anche se ne avrei molta voglia, ho deciso di passare il giro &#8220;chiacchere&#8221; a data da destinarsi ma di tentare nella preparazione dei bomboloni (o krapfen).<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Ho visto il risultato decisamente accattivante proposto dalla mia amica Eva che, instancabile, mi dimostra sempre di piu&#8217; la sua abilita&#8217; nella preparazione di dolci golosi e di lievitati mozzafiato&#8230; ma come fa!!!!???<\/p>\n<p style=\"text-align: justify;\">Cosi&#8217; ho provato a chiederle la ricetta utilizzata e mi ha spedito questa immagine dei Krapfen del maestro Antonio Chiera.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-20341\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/eva_Krapfen-e1580479085660.jpg\" alt=\"\" width=\"960\" height=\"496\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/eva_Krapfen-e1580479085660.jpg 960w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/eva_Krapfen-e1580479085660-150x78.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/eva_Krapfen-e1580479085660-300x155.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/eva_Krapfen-e1580479085660-768x397.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p style=\"text-align: justify;\">Visto che si tratta del primo tentativo, ho deciso di &#8220;cambiare&#8221; la ricetta, diminuendo le quantita&#8217; e ricalcolando tutto in base alla quantita&#8217; di uova.<\/p>\n<p style=\"text-align: justify;\">In breve, ecco gli <strong>ingredienti<\/strong> ricalcolati e da me usati:<\/p>\n<pre>730gr di farina 00 con 12,8% di proteine (Edeka)\r\n110gr di zucchero\r\n110gr di uova (2 uova)\r\n110gr di burro (temperatura ambiente)\r\n330gr di latte\r\n16gr di sale\r\n7 gr malto\r\n30gr di lievito di birra\r\n3gr lievito per dolci\r\naromi (di arancia)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Inserite nella ciotola della planetaria tutti gli ingredienti ad eccezione del burro.<br \/>\nImpastate tutto con la spirale ad una velocit\u00c3\u00a0 sostenuta, quando l&#8217;impasto si mostra incordato ed abbastanza compatto e levigato aggiungete a pezzetti il burro fino ad assorbimento.<\/p>\n<p style=\"text-align: justify;\">Appoggiate l&#8217;impasto scoperto su spianatoia ed attendete per venti minuti circa.<br \/>\nArrotondate e mettete in ciotola a lievitare. L&#8217;ideale sarebbe un contenitore rettangolare in modo da segnare il livello e poter con sicurezza controllare il raddoppio l&#8217;impasto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20363\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200131_142224-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200131_142224-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200131_142224-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200131_142224-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200131_142224-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20364\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200131_144543-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200131_144543-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200131_144543-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200131_144543-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200131_144543-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Coprite e lasciate in frigo dalle 12 alle 16 ore a 4\u00c2\u00b0. Trascorso il tempo, rimuovete il contenitore dal frigorifero e lasciate l&#8217;impasto acclimatare e lievitare.<\/p>\n<p style=\"text-align: justify;\">Formate i krapfen sezionando l&#8217;impasto a 80 g , pirlate leggermente e metteteli a lievitare ancora su una teglia, coperta fa carta forno.<\/p>\n<figure id=\"attachment_20394\" aria-describedby=\"caption-attachment-20394\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20394 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_141740-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_141740-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_141740-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_141740-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_141740-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20394\" class=\"wp-caption-text\">Krapfen del maestro Antonio Chiera<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ricordatevi di coprire il tutto con una pellicola.<\/p>\n<p style=\"text-align: justify;\">Al raddoppio procedete alla cottura.<\/p>\n<figure id=\"attachment_20396\" aria-describedby=\"caption-attachment-20396\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20396 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_155627-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_155627-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_155627-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_155627-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_155627-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20396\" class=\"wp-caption-text\">Krapfen del maestro Antonio Chiera<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Per cottura al forno (da me utilizzata).<\/strong><br \/>\nPreriscaldate il forno a 180\u00c2\u00b0 ed infornate per 18 minuti circa, se avete una pezzatura da 70 gr<\/p>\n<figure id=\"attachment_20397\" aria-describedby=\"caption-attachment-20397\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20397 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_161139-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_161139-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_161139-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_161139-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_161139-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20397\" class=\"wp-caption-text\">Krapfen del maestro Antonio Chiera<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Per frittura.<\/strong><br \/>\nScaldate l&#8217;olio di semi in un pentolino, a 170gradi, ed inserite i krapfen pochi alla volta facendo in modo che siano immersi nell&#8217;olio.<\/p>\n<div id=\"titlediv\"><\/div>\n<div>\n<figure id=\"attachment_20393\" aria-describedby=\"caption-attachment-20393\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20393 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_162213-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_162213-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_162213-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_162213-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_162213-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20393\" class=\"wp-caption-text\">Krapfen del maestro Antonio Chiera<\/figcaption><\/figure>\n<\/div>\n<div>\n<figure id=\"attachment_20392\" aria-describedby=\"caption-attachment-20392\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20392 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_191412-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_191412-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_191412-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_191412-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200201_191412-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20392\" class=\"wp-caption-text\">Krapfen del maestro Antonio Chiera<\/figcaption><\/figure>\n<\/div>\n<div>Sicuramente da rifare!<br \/>\nDecisamente ottime&#8230;!<\/div>\n<div><\/div>\n<div>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bischen dort<\/div>\n<div id=\"postdivrich\" class=\"postarea wp-editor-expand\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Siamo quasi a Carnevale e quest&#8217;anno, anche se ne avrei molta voglia, ho deciso di passare il giro &#8220;chiacchere&#8221; a data da destinarsi ma di tentare nella preparazione dei bomboloni (o krapfen).<\/p>\n","protected":false},"author":2,"featured_media":20393,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,145,22,90],"tags":[116],"class_list":["post-20340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-dolci","category-food","category-lievitati","tag-ldb"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/20340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=20340"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/20340\/revisions"}],"predecessor-version":[{"id":20399,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/20340\/revisions\/20399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/20393"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=20340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=20340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=20340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}