{"id":20267,"date":"2020-01-26T15:30:17","date_gmt":"2020-01-26T14:30:17","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=20267"},"modified":"2022-01-24T16:15:35","modified_gmt":"2022-01-24T15:15:35","slug":"azerbaigian_parcha-dosheme-plov","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/01\/26\/azerbaigian_parcha-dosheme-plov\/","title":{"rendered":"# 28 &#8211; Repubblica dell\u00e2\u20ac\u2122Azerbaigian. &#8220;Parcha-dosheme plov&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\">L&#8217;<strong>Azerbaigian<\/strong> (\/a\u00ca\u00a3\u00ca\u00a3erbai\u00cb\u02c6\u00ca\u00a4an\/; in azero Az\u00c9\u2122rbaycan), ufficialmente <strong>Repubblica dell&#8217;Azerbaigian<\/strong> (in azero: Az\u00c9\u2122rbaycan Respublikas\u00c4\u00b1), \u00c3\u00a8 uno Stato della regione transcaucasica, tra l&#8217;Asia occidentale e l&#8217;Europa orientale.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Confina con il Mar Caspio a est, con la Russia a nord, la Georgia e l&#8217;Armenia a ovest e l&#8217;Iran a sud.<br \/>\nCapitale <em>Baku<\/em>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30807\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/06\/asia_occidentale-1024x881.jpg\" alt=\"\" width=\"525\" height=\"452\" \/><\/p>\n<p style=\"text-align: justify;\">La lingua ufficiale \u00c3\u00a8 l&#8217;azero appartenente alla famiglia delle lingue turche; dal punto di vista etno-geografico quindi l&#8217;Azerbaigian rappresenta l&#8217;anello di congiunzione tra l&#8217;odierna Turchia, nell&#8217;Asia occidentale, e i paesi del Turkestan, nell&#8217;Asia Centrale.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong> x 6 persone per il <strong>Parcha-dosheme plov<\/strong><\/p>\n<pre>580 g di riso Basmati a grani lunghi\r\n60 g di burro fuso\r\n150 g di castagne, pelate\r\n130 g di albicocche secche\r\n150 g di prugne acide\r\n80 g di datteri snocciolati\r\n75 g di uvetta\r\n700 g di pollo senza pelle disossato (*)\r\n1 cipolla\r\n\u00e2\u2026\u201c cucchiaino di filamenti di zafferano\r\nsale\r\nPepe nero\r\n\r\nLavash (o una piadina)<\/pre>\n<p style=\"text-align: justify;\">(*) Ho visto e letto diverse ricette a tal proposito.<br \/>\nIn alcune si suggerisce, come in questa, di tagliare la carne a bocconcini.<br \/>\nIn altre, invece, la carne viene lasciata a &#8220;grossi bottoni&#8221; (o porzioni) ed intera, con ossa e pelle.<br \/>\nVedete voi come vi e&#8217; piu&#8217; comodo<\/p>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>Iniziate con la preparazione del riso.<\/em><br \/>\nMettete il \u00e2\u20ac\u2039\u00e2\u20ac\u2039riso in uno scolapasta e lavatelo accuratamente con acqua tiepida fino a quando l&#8217;acqua non sara&#8217; limpida.<\/p>\n<figure id=\"attachment_20285\" aria-describedby=\"caption-attachment-20285\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20285 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_104059-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_104059-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_104059-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_104059-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_104059-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20285\" class=\"wp-caption-text\">Riso basmati prima del lavaggio<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Il processo di risciacquo consente di eliminare l&#8217;amido in modo tale che i chicchi di riso rimangano ben separati dopo la cottura.<\/p>\n<figure id=\"attachment_20286\" aria-describedby=\"caption-attachment-20286\" style=\"width: 525px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20286 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_104210-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_104210-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_104210-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_104210-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_104210-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20286\" class=\"wp-caption-text\">Riso Basmati in ammollo, acqua da cambiare<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Immergete il riso in un grande contenitore riempito con acqua tiepida ed 1 cucchiaio di sale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20287\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_105620-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_105620-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_105620-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_105620-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_105620-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">In una padella media, scaldate 30 g di burro a fuoco medio.<br \/>\nAggiungete le castagne sbucciate e soffriggetele per circa 3 minuti.<br \/>\nAggiungete le albicocche secche, le prugne secche e i datteri e rosolate il tutto per circa 3 minuti. Aggiungete a questo punto l&#8217;uvetta e cuocete per 1 minuto.<br \/>\nRimuovete la frutta dal fuoco.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20288\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_105843-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_105843-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_105843-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_105843-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_105843-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">In una grande casseruola antiaderente, unite 2,5 litri di acqua e 2 cucchiai di sale.<br \/>\nPortate ad ebollizione.<br \/>\nScolate il riso (lasciandolo comunque un po&#8217; bagnato) e aggiungetelo gradualmente nella pentola.<br \/>\nFate bollire per circa 7-10 minuti, mescolando di tanto in tanto con un cucchiaio di legno, per evitare che i chicchi di riso aderiscano al fondo.<br \/>\nFate attenzione a non cuocere troppo il riso: non dovrebbe essere completamente cotto e non troppo tenero, dovrebbe essere ancora croccate.<br \/>\nScolate il riso in un grande scolapasta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20291\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_112055-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_112055-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_112055-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_112055-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_112055-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Mettetelo in una grossa ciotola ed unitevi la frutta secca-cotta, con del burro fuso, mescolando lentamente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20292\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_112214-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_112214-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_112214-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_112214-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_112214-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20293\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_112500-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_112500-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_112500-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_112500-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_112500-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Mettete in infusione lo zafferano in una piccola tazza con 3 cucchiai di acqua calda<\/p>\n<p><em>Per la carne:<\/em><br \/>\nPreparate la carne con sale e pepe, da entrambi i lati.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20294\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_113521-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_113521-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_113521-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_113521-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_113521-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Sciogliete 15 g di burro a fuoco medio in una padella.<br \/>\nMettete la carne su uno strato nel fondo della padella.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20295\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_113926-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_113926-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_113926-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_113926-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_113926-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Coprite la carne con lo strato di cipolle affettate non troppo fini e lasciate cuocere a fuoco medio, scoperto, per circa 3 minuti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20299\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114515-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114515-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114515-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114515-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114515-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><em>Assemblate i componenti<\/em><\/p>\n<p style=\"text-align: justify;\">Opzionale:<br \/>\nRimuovete la carne dalla padella ed inserite, sul fondo di una pentola alta, una tortilla.<br \/>\nAggiungete sulla tortilla un leggero strato di solo riso (senza la frutta secca!) e ridisponete la carne sopra, in un unico strato.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20297\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114030-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114030-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114030-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114030-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114030-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20298\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114218-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114218-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114218-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114218-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114218-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20300\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114519-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114519-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114519-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114519-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114519-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Aggiungete il restante riso e coprite il tutto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20301\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114659-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114659-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114659-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114659-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_114659-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20302\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_115056-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_115056-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_115056-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_115056-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_115056-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Con il manico del cucchiaio di legno fate dei fori, cosi&#8217; che il vapore possa uscire.<br \/>\nVersate 15 g di burro fuso sul riso.<\/p>\n<p style=\"text-align: justify;\">Mettete un panno pulito o 2 strati di tovagliolo di carta sulla padella e coprite bene per assorbire il vapore, appoggiate gli angoli dell&#8217;asciugamano sul coperchio (fate attenzione se non avete un fornello ad induzione, ma a gas, in quanto puo&#8217; bruciare!).<\/p>\n<figure id=\"attachment_20303\" aria-describedby=\"caption-attachment-20303\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20303 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125428-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125428-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125428-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125428-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125428-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20303\" class=\"wp-caption-text\">Azerbaigian. &#8220;Parcha-dosheme plov&#8221;<\/figcaption><\/figure>\n<figure id=\"attachment_20304\" aria-describedby=\"caption-attachment-20304\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20304 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125558-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125558-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125558-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125558-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125558-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20304\" class=\"wp-caption-text\">Azerbaigian. &#8220;Parcha-dosheme plov&#8221;<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Riducete il fuoco e cuocete per 30 minuti circa, senza mescolare.<br \/>\nQuindi rimuovete il coperchio e cospargete il riso utilizzando l&#8217;acqua con lo zafferano.<br \/>\nCoprire di nuovo e cuocere a fuoco lento per ulteriori 30 minuti.<\/p>\n<figure id=\"attachment_20306\" aria-describedby=\"caption-attachment-20306\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20306 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125957-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125957-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125957-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125957-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125957-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20306\" class=\"wp-caption-text\">Azerbaigian. &#8220;Parcha-dosheme plov&#8221;<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Quando il riso \u00c3\u00a8 pronto, dovrebbe apparire cos\u00c3\u00ac:<\/p>\n<p style=\"text-align: justify;\">1. Riso soffice con chicchi separati.<br \/>\n2. La carne dovrebbe avere una crosta dorata sul fondo e cotta (se non si utilizza la fase &#8220;opzionale&#8221;).<br \/>\n3. La cipolla dovrebbe essere traslucida (quasi invisibile).<br \/>\nRaccogliete il tutto e disponetelo su un grande piatto da portata.<br \/>\n\u00c3\u02c6 pronto per servire.<\/p>\n<figure id=\"attachment_20307\" aria-describedby=\"caption-attachment-20307\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20307 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_130421-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_130421-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_130421-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_130421-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_130421-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20307\" class=\"wp-caption-text\">Azerbaigian. &#8220;Parcha-dosheme plov&#8221;<\/figcaption><\/figure>\n<p><strong>NOTE Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Ho utilizzato il Riso Basmati che potete vedere nella foto sottostante.<\/li>\n<li style=\"text-align: justify;\">Il tempo di cottura, in questo caso, e&#8217; di 10 minuti.<\/li>\n<li style=\"text-align: justify;\">Dovendo cuocere per piu&#8217; di un&#8217;ora, ho deciso di cuocere il riso in acqua bollente salata per solo 1-2 minuti.<br \/>\nLasciando cosi&#8217; il chicco ancora &#8220;sodo&#8221; internamente<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20289\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_110000-e1580047291957-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_110000-e1580047291957-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_110000-e1580047291957-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_110000-e1580047291957-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_110000-e1580047291957-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Dopo mezz&#8217;ora di cottura del &#8220;Parcha-dosheme plov&#8221;,\u00c2\u00a0 quando ho scoperchiato per inserire lo zafferano ho assaggiato ancora il riso, trovandolo ancora crudo.<br \/>\nHo poi ricoperto e lasciato per altri 20minuti in cottura: risultato perfetto.<\/p>\n<p style=\"text-align: justify;\">Il riso non e&#8217; assolutamente speziato, se non si conta l&#8217;aggiunta di zafferano, e la frutta secca lo rende dolciastro ma non terribile.<\/p>\n<p style=\"text-align: justify;\">Sicuramente con tutto il burro richiesto, direi che non e&#8217; un cibo particolarmente adatto per chi e&#8217; a dieta&#8230; magari si potrebbe stare un po&#8217; piu&#8217; ristretti (come del resto ho fatto io) ed evitare alcune porzioni di burro (come quello utilizzato per pre-cuocere il pollo).<\/p>\n<figure id=\"attachment_20305\" aria-describedby=\"caption-attachment-20305\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20305 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125954-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125954-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125954-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125954-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200126_125954-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20305\" class=\"wp-caption-text\">Azerbaigian. &#8220;Parcha-dosheme plov&#8221;<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Personalmente ho bevuto, come accompagnamento al piatto, dell&#8217;<a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/08\/28\/turchia_ayran\/\"><em><strong>Ayran<\/strong><\/em><\/a> (reperibile al supermercato, reparto latte fresco).<br \/>\nVista la velocita&#8217; nella preparazione di questa bevanda e&#8217; possibile farla anche a casa, velocemente.\u00c2\u00a0 Prossimamente la ricetta!<\/p>\n<p style=\"text-align: justify;\">Ho ancora alcuni dubbi sulla cottura del riso: prima in acqua e sale, poi in acqua bollente. Magari serve solo per accorciare i tempi di cottura dello stesso, ma mi devo ancora documentare a tal proposito.<br \/>\nVoi ne sapete qualche cosa?<\/p>\n<hr \/>\n<p style=\"text-align: justify;\">La <b>cucina azera<\/b> (Az\u00c9\u2122rbaycan m\u00c9\u2122tb\u00c9\u2122xi) \u00c3\u00a8 la cucina tradizionale dell&#8217;<strong>Azerbaigian<\/strong> e dei paesi membri della diaspora azera.<\/p>\n<p style=\"text-align: justify;\">La cucina nazionale dell&#8217;Azerbaigian ha diverse variet\u00c3\u00a0, con decine di piatti unici come: latticini, di carne, di farina, verdure, ecc.<br \/>\nI metodi di cottura e del consumo di alimenti sono diversi e molteplici.<\/p>\n<p style=\"text-align: justify;\">Fra i piatti tipici si ricordano dolma, pilaf, lavash, kebab, kishk e b\u00c3\u00b6rek, tra le bevande t\u00c3\u00a8 nero, sharbat e ayran.<\/p>\n<p style=\"text-align: justify;\">Su 11 zone climatiche conosciute nel mondo, il clima azerbaigiano ne ha otto.<br \/>\nQuesto contribuisce alla fertilit\u00c3\u00a0 della terra, che a sua volta produce la ricchezza della cucina. I componenti principali della cucina sono determinati dalle condizioni naturali del paese: il clima montuoso e subtropicale hanno causato un&#8217;ampia diffusione della carne di montone, pollame, di pesci d&#8217;acqua dolce e mare nella cucina azera.<\/p>\n<p style=\"text-align: justify;\">Vari tipi di kebab e piatti in tandoor sono ampiamente diffusi nella cucina azerbaigiana.<br \/>\nCi sono una variet\u00c3\u00a0 di bevande e dolci. Una caratteristica distintiva della cucina azera \u00c3\u00a8 diffusione dell&#8217;uso di agnello per preparare vari piatti<\/p>\n<p style=\"text-align: justify;\">La formazione della cucina azerbaigiana \u00c3\u00a8 stata influenzata dalle richieste dell&#8217;Islam.<\/p>\n<p style=\"text-align: justify;\">Un&#8217;altra specialit\u00c3\u00a0 della cucina azera \u00c3\u00a8 la diffusione di spezie e condimenti tipo: cannella, chiodi di garofano, prezzemolo, crescione inglese, basilico verde e rosso, aneto, peperoncino, pimento, cumino, coriandolo, menta, zafferano (\u00c3\u00a8 una componente indispensabile per la preparazione di numerosi pilaf &#8211; riso &#8211; e dolci), sommacco ecc.<\/p>\n<p style=\"text-align: justify;\">La cucina azerbaigiane usa ampiamente verdure come pomodori, cetrioli, melanzane e altri), frutti ( mele, pere, mele cotogne, arance, limoni), frutti drupacee (prugne, amoli, albicocche, pesche)<\/p>\n<p style=\"text-align: justify;\">Uno dei piatti pi\u00c3\u00b9 famosi e caratteristici della cucina azera \u00c3\u00a8 il dolma.<\/p>\n<p style=\"text-align: justify;\">Il piatto pi\u00c3\u00b9 comune &#8211; <strong>plov<\/strong> (nel paese ci sono pi\u00c3\u00b9 di 40 ricette per la sua preparazione): ad esempio, ci sono &#8220;nardancha pilaf&#8221; preparati (preparati con pollo, riso, albicocche secche, semi di melograno, uva passa) o &#8220;Shah pilaf (per la sua preparazione con riso, zafferano, prugna, agnello, castagne, uvetta).<br \/>\nNon meno comuni nella cucina locale hanno piatti come patate o spiedini di melanzane, peperoni marinati e ripieni e pomodori.<\/p>\n<p style=\"text-align: justify;\">Anche utilizzando semplici ingredienti come riso, carne o olio, il riso Pilaf dell&#8217;Azerbaijian sono pieni di sapore ed esistono diverse variazioni.<br \/>\nNelle diverse regioni l&#8217;aggiunta di ingredienti diversi, o la diversa tecnica per la cottura, ne crea diversissime versioni:<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>Shah plov<\/strong> &#8211; e&#8217; dichiarato il &#8220;re del riso&#8221;, si distingue per la sua crosta croccante, creata durante la cottura.<\/li>\n<li style=\"text-align: justify;\"><strong>Shirin plov<\/strong> &#8211; riso dolce e pieno di frutta secca, servito senza carne. Meglio se servito tiepido.<\/li>\n<li style=\"text-align: justify;\"><strong>Toyuq plov<\/strong> &#8211; questo riso e&#8217; cotto con carne di pollo, nonostante questo resta soffice, e dolce.<\/li>\n<li><strong>Fisinjan plov<\/strong> &#8211; combinato con carne a lunga cottura e melograno.<\/li>\n<li style=\"text-align: justify;\"><strong>Parcha-dosheme plov<\/strong> &#8211; si tratta probabilmente del piu; comune metodo di cottura nelle cucine dell&#8217;Ovest. Con questo sistema di cottura, il riso viene bollito in acqua fino a che essa non viene assorbita. Poi il riso viene cotto con tutti gli ingredienti in una sola pentola, a livelli: carne, cipolla e riso. Viene poi inserita la frutta secca.<\/li>\n<\/ul>\n<p>yem\u00c9\u2122kd\u00c9\u2122n z\u00c3\u00b6vq al\u00c4\u00b1n<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Azerbaigian (\/a\u00ca\u00a3\u00ca\u00a3erbai\u00cb\u02c6\u00ca\u00a4an\/; in azero Az\u00c9\u2122rbaycan), ufficialmente Repubblica dell&#8217;Azerbaigian (in azero: Az\u00c9\u2122rbaycan Respublikas\u00c4\u00b1), \u00c3\u00a8 uno Stato della regione transcaucasica, tra l&#8217;Asia occidentale e l&#8217;Europa orientale.<\/p>\n","protected":false},"author":2,"featured_media":20268,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[230,64,22,138,51,67],"tags":[176,234,107,88],"class_list":["post-20267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asia","category-carne","category-food","category-piatti_unici","category-primi_piatti","category-riso_risotti","tag-176","tag-asia_occidentale","tag-frutta","tag-frutta_secca"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/20267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=20267"}],"version-history":[{"count":20,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/20267\/revisions"}],"predecessor-version":[{"id":35477,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/20267\/revisions\/35477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/20268"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=20267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=20267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=20267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}