{"id":20178,"date":"2020-02-03T14:28:33","date_gmt":"2020-02-03T13:28:33","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=20178"},"modified":"2025-06-01T20:17:24","modified_gmt":"2025-06-01T18:17:24","slug":"miglio-info-e-proprieta","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/02\/03\/miglio-info-e-proprieta\/","title":{"rendered":"Miglio &#8230; info e proprieta&#8217;"},"content":{"rendered":"<p style=\"text-align: justify;\">Il &#8220;padre&#8221; miglio e&#8217; il precursore di tutti i cerali.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Esso ha nutrito l&#8217;umanita&#8217; prima della scoperta dell&#8217;aratro, poiche&#8217; veniva raccolto allo stato selvatico. Trascorsero migliaia di anni prima che fosse messo a coltura.<br \/>\nVari sono i tipi di miglio che crescono spontaneamente in Cina, in Africa, in India e nei Balcani.<br \/>\nNei luoghi dove il miglio cresceva liberamente, le condizioni climatiche consentivano anche la crescita del riso. Gradatamente quest&#8217;ultimo fini&#8217; per sostituirsi al miglio.<\/p>\n<p style=\"text-align: justify;\">Il miglio \u00c3\u00a8 dunque un cereale antico appartenente alla famiglia delle Graminacee, il cui nome botanico \u00c3\u00a8 Panicum miliaceum.<br \/>\nLa pianta del miglio pu\u00c3\u00b2 arrivare fino ad un metro e mezzo di altezza e produce piccoli semini lisci, che costituiscono appunto la parte edibile.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20165\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200112_095548-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200112_095548-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200112_095548-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200112_095548-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200112_095548-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Il miglio \u00c3\u00a8 un cereale privo di glutine con interessanti propriet\u00c3\u00a0 terapeutiche, gli studi dimostrano che il suo consumo favorisce il controllo della glicemia ed apporta altri benefici alla salute:<\/p>\n<ul style=\"text-align: justify;\">\n<li>propriet\u00c3\u00a0 antistress, abbondante presenza di vitamine del gruppo B, fosforo e alla ricchezza di minerali<\/li>\n<li>benefici per la salute cardiovascolare<\/li>\n<li>bellezza di pelle e capelli, l\u00e2\u20ac\u2122acido silicico contenuto \u00c3\u00a8 in grado di rinforzare le unghie e i capelli in quanto ne irrobustisce la struttura<\/li>\n<li>non contiene glutine, quindi ottimo per i celiaci o intolleranti<\/li>\n<li>apparato gastrointestinale, indicato per tutte quelle categorie di persone che hanno bisogno di alimenti facilmente digeribili<\/li>\n<li>riduce il colesterolo, la fibra presente nel miglio, insieme alla presenza di niacina, \u00c3\u00a8 in grado di contribuire alla riduzione dei livelli di colesterolo cattivo nel sangue aumentando di conseguenza quelli di colesterolo buono<br \/>\npreviene i calcoli biliari, grazie alla presenza di fibre insolubili, il consumo regolare di miglio sarebbe in grado di prevenire la formazione di calcoli biliari<\/li>\n<li>favorisce il buonumore, con il suo amminoacido essenziale indispensabile per la produzione di serotonina, l\u00e2\u20ac\u2122ormone che promuove il buonumore.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Il<strong> miglio<\/strong> \u00c3\u00a8 stato riscoperto negli ultimi tempi grazie alle sue <strong>propriet\u00c3\u00a0<\/strong>, al suo gusto delicato ed all\u00e2\u20ac\u2122assenza di glutine.<br \/>\nPurtroppo il suo utilizzo principale in Europa resta per\u00c3\u00b2 quello destinato al mangime per gli uccelli e per il pollame.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20169\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200112_120910-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200112_120910-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200112_120910-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200112_120910-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200112_120910-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><em><strong>Il miglio in cucina<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Il miglio pu\u00c3\u00b2 essere utilizzato come qualunque altro cereale grezzo.<br \/>\nSe fatto bollire, si presta moltissimo alla formulazione di una &#8220;polenta grossolana&#8221; (progenitrice della polenta di mais).<br \/>\nE&#8217; spesso presente nelle zuppe miste di cereali o cereali e legumi.<\/p>\n<p style=\"text-align: justify;\">Per la preparazione non \u00c3\u00a8 necessario l\u00e2\u20ac\u2122ammollo, ma \u00c3\u00a8 opportuno lavarlo accuratamente sotto acqua corrente, in modo da eliminare le impurit\u00c3\u00a0, usando un colino a maglie fini, lasciandolo scolare per un po\u00e2\u20ac\u2122. Poi tostiamolo per qualche minuto in una padella larga con un po\u00e2\u20ac\u2122 di olio di oliva.<\/p>\n<p style=\"text-align: justify;\">Successivamente possiamo procedere con la cottura:<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\">in pentola<\/span><br \/>\nmettiamo l\u00e2\u20ac\u2122acqua, che dovr\u00c3\u00a0 essere 2 volte e mezzo il volume del miglio. Quando comincia a bollire, versiamola nella padella con il <strong>miglio tostato<\/strong> e riportiamo a bollore a fiamma alta. Abbassiamo la fiamma e lasciamo cuocere con un coperchio per 20 minuti controllando che, durante la fase di <strong>cottura del miglio<\/strong>, l\u00e2\u20ac\u2122acqua non evapori del tutto. Solo dopo una ventina di minuti possiamo togliere il coperchio e far evaporare l\u00e2\u20ac\u2122acqua in eccesso.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\">in pentola a pressione<\/span><br \/>\ntostiamo leggermente il miglio ed aggiungiamo poi l\u00e2\u20ac\u2122acqua, che dovr\u00c3\u00a0 essere 1 volta e mezzo il volume del miglio. Chiudiamo con il coperchio e portiamo a pressione, quando incomincia a fischiare, abbassiamo la fiamma e calcoliamo 10 minuti.<br \/>\nFacciamo poi sfiatare in modo naturale (altri 10 minuti circa).<\/p>\n<p style=\"text-align: justify;\">A questo punto non ci resta che utilizzarlo!<\/p>\n<p style=\"text-align: justify;\">Ecco alcune ricette che avevo preparato anni fa&#8230;<\/p>\n<p><em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2010\/09\/21\/sformato-di-miglio\/\">Sformato di miglio<\/a><\/strong><\/em> &#8211;<br \/>\n<em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2009\/11\/18\/minestra-di-miglio-e-finocchio\/\">Minestra di miglio e finocchio<\/a><\/strong><\/em> &#8211; light<br \/>\n<em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2009\/08\/30\/sformato-di-miglio-con-ricotta-e-rucola\/\">Sformato di miglio con ricotta e rucola<\/a><\/strong><\/em> &#8211;<br \/>\n<em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2009\/03\/28\/budino-di-miglio\/\">Budino di miglio<\/a><\/strong><\/em> &#8211;<br \/>\n<a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2009\/02\/07\/risotto-di-miglio-alle-erbe-fini\/\"><em><strong>Risotto di miglio alle erbe fini<\/strong><\/em><\/a> &#8211;<br \/>\n<em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/01\/12\/burkina-faso-poulet-gingembre\/\">Cottura semplice<\/a><\/strong><\/em> &#8211; in pentola a pressione<\/p>\n<p>Alla prossima!<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il &#8220;padre&#8221; miglio e&#8217; il precursore di tutti i cerali.<\/p>\n","protected":false},"author":2,"featured_media":20173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[54,53],"class_list":["post-20178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosita","tag-cereali","tag-pentola_a_pressione"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/20178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=20178"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/20178\/revisions"}],"predecessor-version":[{"id":48283,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/20178\/revisions\/48283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/20173"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=20178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=20178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=20178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}