{"id":2016,"date":"2010-02-05T18:40:17","date_gmt":"2010-02-05T17:40:17","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/chiacchere-anno-2ndo\/"},"modified":"2018-03-31T17:29:31","modified_gmt":"2018-03-31T16:29:31","slug":"chiacchere-anno-2ndo","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2010\/02\/05\/chiacchere-anno-2ndo\/","title":{"rendered":"Chiacchere.. anno 2ndo"},"content":{"rendered":"<p style=\"text-align: justify;\">Ed eccomi ancora qui, durante il periodo di Carnevale a pensare di voler cucinare le chiacchere.<!--more--><\/p>\n<p style=\"text-align: justify;\">Ho preso la ricetta utilizzata l&#8217;<a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2009\/02\/chiacchere-al-forno\/\">anno scorso<\/a> ed ho utilizzato la macchina della pasta, anziche&#8217; il mattarello.<\/p>\n<p style=\"text-align: justify;\">C&#8217;e&#8217; da dire che non l&#8217;avevo mai utilizzata ma e&#8217; nella mia &#8220;dotazione&#8221; come eredita&#8217; da parte di mia nonna.<\/p>\n<p style=\"text-align: justify;\">Non posso dire che il risultato sia stato migliore o peggiore&#8230;<br \/>\npurtroppo sono sempre stoppose e non friabili, non hanno lievitato neppure di un poco!<br \/>\nInoltre la ricetta e&#8217; per 6 persone, e le chiacchere prodotte sono un po&#8217; pochine.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7035\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_8383.jpg\" alt=\"\" width=\"200\" height=\"150\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_8383.jpg 200w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_8383-150x113.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/p>\n<p style=\"text-align: justify;\">Vabbe&#8217;, magari cerco qualche altra ricetta in rete o qualche accorgimento particolare che mi e&#8217; sfuggito.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ed eccomi ancora qui, durante il periodo di Carnevale a pensare di voler cucinare le chiacchere.<\/p>\n","protected":false},"author":2,"featured_media":7035,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,22],"tags":[122],"class_list":["post-2016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-food","tag-carnevale"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2016"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2016\/revisions"}],"predecessor-version":[{"id":9729,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2016\/revisions\/9729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/7035"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}