{"id":20100,"date":"2020-01-10T20:02:35","date_gmt":"2020-01-10T19:02:35","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=20100"},"modified":"2022-01-23T14:54:45","modified_gmt":"2022-01-23T13:54:45","slug":"peru_lomo-saltado","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/01\/10\/peru_lomo-saltado\/","title":{"rendered":"# 24 &#8211; Repubblica del Per\u00c3\u00b9. Lomo saltado."},"content":{"rendered":"<p style=\"text-align: justify;\">Il <strong>Per\u00c3\u00b9<\/strong>, ufficialmente <strong>Repubblica del Per\u00c3\u00b9<\/strong> (in spagnolo: Rep\u00c3\u00bablica del Per\u00c3\u00ba, in quechua: Piruw Ripuwlika, in aymara: Piruw Suyu), \u00c3\u00a8 uno Stato dell&#8217;America meridionale.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">La capitale e&#8217; <em>Lima<\/em>.<\/p>\n<p style=\"text-align: justify;\">Confina a nord con l&#8217;Ecuador, a nord-est con la Colombia, a est con il Brasile, a sud-est con la Bolivia, a sud con il Cile, e a ovest con l&#8217;oceano Pacifico.<br \/>\nIl Per\u00c3\u00b9 \u00c3\u00a8 un paese megadiverso con habitat che variano dalle pianure aride della costa del Pacifico, alle vette delle Ande che si estendono da nord a sud-est e alle foreste tropicali del bacino amazzonico a est con il Rio delle Amazzoni.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-30334\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/sud_america.png\" alt=\"\" width=\"420\" height=\"581\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/sud_america.png 531w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/sud_america-108x150.png 108w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/sud_america-217x300.png 217w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><\/p>\n<p style=\"text-align: justify;\">Il territorio peruviano \u00c3\u00a8 stata sede di diverse antiche culture, che vanno dalla civilt\u00c3\u00a0 Caral, la civilt\u00c3\u00a0 pi\u00c3\u00b9 antica di America e una delle cinque culle della civilt\u00c3\u00a0, all&#8217;Impero Inca, lo Stato pi\u00c3\u00b9 grande dell&#8217;America precolombiana. Il territorio che ora include il Per\u00c3\u00b9 ha una delle pi\u00c3\u00b9 lunghe storie di civilt\u00c3\u00a0 di qualsiasi paese, che fa risalire la sua eredit\u00c3\u00a0 al 4 \u00c2\u00b0 millennio aC.<\/p>\n<p style=\"text-align: justify;\">La lingua spagnola \u00c3\u00a8 parlata dall&#8217;84,1% della popolazione. Le altre due lingue ufficiali sono il quechua, parlato dal 13,7% della popolazione, e l&#8217;aymara, parlato dall&#8217;1,7%. Nel paese si parlano anche altre lingue native americane, ma i locutori complessivamente rappresentano l&#8217;1,2% della popolazione.<\/p>\n<p style=\"text-align: justify;\">Il Per\u00c3\u00b9 \u00c3\u00a8 un paese con molti habitat naturali diversi: si passa infatti dalla foresta amazzonica fino al paesaggio delle Ande; per questo motivo, anche le specie animali e vegetali presenti sul territorio sono molto varie. Nella foresta amazzonica si possono trovare piante tropicali (tra cui diverse specie di orchidee). Tipici del deserto sono i cactus e altre piante grasse.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">La ricetta di oggi, di origine peruviana, mi e&#8217; stata suggerita da Carmen.<\/p>\n<p style=\"text-align: justify;\">Il piatto che ho preparato questa sera e&#8217;\u00c2\u00a0un piatto popolare e tradizionale della cucina del Peru&#8217;, denominato <b>Lomo saltado<\/b>.<br \/>\nEsso e&#8217; nato come parte della tradizione chifa, la cucina cinese del Per\u00c3\u00b9, e data la sua popolarit\u00c3\u00a0 lo ha reso parte della cultura tradizionale.<\/p>\n<p style=\"text-align: justify;\">Data la sua non particolare difficolta&#8217;, ho pensato di prepararlo di sera.<br \/>\nSi tratta di preparare un soffritto che in genere combina strisce marinate di controfiletto (o altra bistecca di manzo) con cipolle, pomodori, patate fritte e altri ingredienti; tipicamente servito con riso.<\/p>\n<p style=\"text-align: justify;\">Alcune persone servono il riso e le patatine fritte separatamente, ma in realt\u00c3\u00a0 le patatine fritte ed il lomo saltado vengono serviti contemporaneamente nello stesso piatto.<\/p>\n<p><strong>Ingredienti &#8211; <em><a href=\"http:\/\/perudelights.com\/lomo-saltado-chinese-inspired-feast-for-the-senses\/\">Lomo saltado<\/a><\/em> &#8211;<br \/>\n<\/strong><\/p>\n<pre>Bistecca di lombata tagliata a fette sottili\r\nSale e pepe\r\n3 cucchiai di olio vegetale\r\n2 spicchi d'aglio tagliati a dadini\r\n1 cipolla rossa tagliata a fette spesse\r\n2 pomodori tagliati a fette spesse\r\n1 peperoncino aji amarillo e tagliato a fettine sottili (*)\r\n3 cucchiai di salsa di soia\r\n3 cucchiai di aceto di vino rosso\r\n\u00c2\u00bd tazza di coriandolo fresco, tritato\r\n2 tazze di patatine fritte\r\nRiso bianco come contorno<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Condite la bistecca di manzo con sale e pepe.<br \/>\nMettete un wok o una padella a fuoco molto alto. Aggiungete l&#8217;olio e rosolate la carne, alcune fette alla volta in modo che non cuociano al vapore ma rimangono dorate (circa 10 minuti, a seconda della potenza della fiamma).<\/p>\n<figure id=\"attachment_20112\" aria-describedby=\"caption-attachment-20112\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20112 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_185340-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_185340-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_185340-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_185340-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_185340-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20112\" class=\"wp-caption-text\">Peru&#8217;. Lomo saltado.<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Aggiungete aglio, cipolla, pomodoro, peperoncino e mescolate per un paio di minuti.<\/p>\n<figure id=\"attachment_20111\" aria-describedby=\"caption-attachment-20111\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20111 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_185335-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_185335-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_185335-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_185335-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_185335-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20111\" class=\"wp-caption-text\">Peru&#8217;. Lomo saltado.<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Inserite la salsa di soia e l&#8217;aceto ai lati della padella e mescolate tutto.<br \/>\nCondite con pi\u00c3\u00b9 sale e pepe.<\/p>\n<figure id=\"attachment_20113\" aria-describedby=\"caption-attachment-20113\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20113 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_190034-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_190034-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_190034-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_190034-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_190034-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20113\" class=\"wp-caption-text\">Peru&#8217;. Lomo saltado.<\/figcaption><\/figure>\n<figure id=\"attachment_20114\" aria-describedby=\"caption-attachment-20114\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20114 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_190623-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_190623-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_190623-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_190623-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_190623-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20114\" class=\"wp-caption-text\">Peru&#8217;. Lomo saltado.<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Togliete dal fuoco, cospargete con coriandolo tritato e servite subito con patatine fritte e riso bianco.<\/p>\n<figure id=\"attachment_20115\" aria-describedby=\"caption-attachment-20115\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20115 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_191344-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_191344-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_191344-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_191344-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200110_191344-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20115\" class=\"wp-caption-text\">Peru&#8217;. Lomo saltado.<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>NOTE Personali e Varie.<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">(*) sostituibile con 1 cucchiaio di pasta di aji amarillo, o con qualsiasi peperoncino a disposizione.<br \/>\nNon amando il peperoncino, l&#8217;ho sostituito con della Ajvar che avevo acquistato precedentemente, per il menu&#8217; bosniaco.<\/li>\n<li style=\"text-align: justify;\">Per la cottura ho usato il wok e, onestamente, non ho misurato tutto, andando a buonsenso.<\/li>\n<li style=\"text-align: justify;\">In effetti non ho fritto le patatine, che dovrebbero cuocere prima della carne, utilizando lo stesso olio, ma ho usato la mia friggitrice ad aria.<\/li>\n<li style=\"text-align: justify;\">Quando viene aggiunta la salsa di soia e poi l&#8217;aceto, il sapore rimane forte ed accentuato. Ho preferito lasciare cuocere ancora, in modo da far evaporare meglio il liquido (aceto) e concentrare un pochino anche la salsa.<\/li>\n<\/ul>\n<hr \/>\n<p style=\"text-align: justify;\">La <b>cucina peruviana<\/b> \u00c3\u00a8 una delle pi\u00c3\u00b9 variegate del mondo ed il Per\u00c3\u00b9 \u00c3\u00a8 il paese con il maggior numero di piatti tipici: 491 con piatti di livello equivalente a quello delle gastronomie francese, italiana, cinese e indiana.<\/p>\n<p style=\"text-align: justify;\">Le arti culinarie peruviane sono in costante evoluzione e questo, sommato alla variet\u00c3\u00a0 dei piatti tradizionali, rende impossibile stabilire una lista completa dei suoi piatti rappresentativi: solo lungo la costa peruviana esistono pi\u00c3\u00b9 di 2500 differenti tipi di zuppe e 250 dolci tradizionali.<\/p>\n<p style=\"text-align: justify;\">La grande variet\u00c3\u00a0 della gastronomia peruviana \u00c3\u00a8 basata su tre fonti:<\/p>\n<ul style=\"text-align: justify;\">\n<li>la particolarit\u00c3\u00a0 della geografia peruviana;<\/li>\n<li>la somma di gruppi etnografici e culture che hanno formato il paese;<\/li>\n<li>l&#8217;adattamento delle culture autoctone millenarie alla cucina moderna.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Al giorno d&#8217;oggi, il ceviche, il pollo a la brasa e i piatti di chif costituiscono i rappresentanti pi\u00c3\u00b9 popolari della cucina peruviana, essendo consumati massivamente in tutto il territorio peruviano ed esistendo versioni per tutte le classi sociali: da preparati molto economici, da consumarsi &#8220;al momento&#8221;, a piatti <i>gourmet<\/i> molto esclusivi.<\/p>\n<p style=\"text-align: justify;\">Il <strong>chaufa<\/strong> \u00c3\u00a8 un termine utilizzato in Per\u00c3\u00b9 per riferirsi alla cucina che sorse dalla fusione tra la cucina peruviana e quella degli immigrati cinesi, principalmente cantonesi, che giunsero in Per\u00c3\u00b9 a met\u00c3\u00a0 del XIX secolo e agli inizi del XX secolo; si usa lo stesso termine per denominare i ristoranti che servono questo tipo di piatti.<\/p>\n<p style=\"text-align: justify;\">Al giorno d&#8217;oggi i ristoranti di cucina cinese, con forti influenze di cucina criolla, sono molto comuni a Lima e in molte altre citt\u00c3\u00a0 del Per\u00c3\u00b9.<br \/>\nI principali piatti sono <i><strong>arroz chaufa<\/strong><\/i>, <strong><i>pollo TiPaKay<\/i><\/strong>, <strong><i>sopa want\u00c3\u00a1n<\/i><\/strong> (zuppa <i>wantan<\/i>) e il cosiddetto &#8220;<strong>aeropuerto<\/strong>&#8221; (aeroporto) che \u00c3\u00a8 una combinazione di cucina <i>chaufa<\/i> con tagliolini saltati, serviti in un piatto grande.<\/p>\n<p style=\"text-align: justify;\">Data la vastita&#8217; del territorio, possiamo trovare la cucina della costa (mare), la cucina andina, la criolla e della selva<\/p>\n<p>&nbsp;<\/p>\n<p>Disfruta tu comida<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Per\u00c3\u00b9, ufficialmente Repubblica del Per\u00c3\u00b9 (in spagnolo: Rep\u00c3\u00bablica del Per\u00c3\u00ba, in quechua: Piruw Ripuwlika, in aymara: Piruw Suyu), \u00c3\u00a8 uno Stato dell&#8217;America meridionale.<\/p>\n","protected":false},"author":2,"featured_media":20102,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,138,60,226],"tags":[176,86,160],"class_list":["post-20100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","category-piatti_unici","category-secondi_piatti","category-stati-americhe","tag-176","tag-friggitrice","tag-sud_america"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/20100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=20100"}],"version-history":[{"count":15,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/20100\/revisions"}],"predecessor-version":[{"id":31563,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/20100\/revisions\/31563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/20102"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=20100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=20100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=20100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}