{"id":19962,"date":"2020-01-06T14:27:34","date_gmt":"2020-01-06T13:27:34","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=19962"},"modified":"2023-12-30T13:55:09","modified_gmt":"2023-12-30T12:55:09","slug":"italia_ossobuco","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/01\/06\/italia_ossobuco\/","title":{"rendered":"# 22 &#8211; Repubblica Italiana. Ossobuco con polenta &#8211; in PaP"},"content":{"rendered":"<p style=\"text-align: justify;\">La <b>cucina italiana<\/b> si \u00c3\u00a8 sviluppata attraverso secoli di cambiamenti politici e sociali, con radici che risalgono al IV secolo a.C.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">La <strong>cucina italiana<\/strong> stessa \u00c3\u00a8 stata influenzata dalla cucina dell&#8217;antica Grecia, dell&#8217;antica Roma, bizantina, ebraica e arab.<\/p>\n<p style=\"text-align: justify;\">Importanti mutamenti si ebbero con la scoperta del Nuovo Mondo e l&#8217;introduzione di nuovi ingredienti come patate, pomodori, peperoni e il mais, ora fondamentali nella cucina ma introdotti in grandi quantit\u00c3\u00a0 solo nel XVIII secolo.<br \/>\nLa cucina italiana \u00c3\u00a8 conosciuta soprattutto per la propria vasta diversit\u00c3\u00a0 a livello regionale, la sua abbondanza nel gusto e nei condimenti e come classico esempio di dieta mediterranea, riconosciuta come patrimonio immateriale dell&#8217;umanit\u00c3\u00a0 dall&#8217;UNESCO nel 2010, ed \u00c3\u00a8 ritenuta la pi\u00c3\u00b9 famosa gastronomia al mondo, con grande influenza a livello internazionale.<br \/>\nL&#8217;emittente televisiva statunitense CNN la colloca al primo posto tra le cucine pi\u00c3\u00b9 apprezzate a livello globale.<\/p>\n<p style=\"text-align: justify;\">La caratteristica principale della cucina italiana \u00c3\u00a8 la sua semplicit\u00c3\u00a0, con molti piatti composti da 4 fino a 8 ingredienti.<br \/>\nI cuochi Italiani fanno affidamento sulla qualit\u00c3\u00a0 degli ingredienti piuttosto che sulla complessit\u00c3\u00a0 di preparazione. I piatti e le ricette tradizionali, nel corso dei secoli, sono stati spesso creati dalle nonne pi\u00c3\u00b9 che dagli chef, ed \u00c3\u00a8 per questo che molte ricette italiane sono adatte alla cucina casalinga e quotidiana.<br \/>\nMolti piatti italiani che una volta erano conosciuti solo nelle regioni di provenienza col tempo si sono diffusi in tutto il paese.<\/p>\n<p style=\"text-align: justify;\">Il formaggio (alimento di cui l&#8217;Italia pu\u00c3\u00b2 vantare la pi\u00c3\u00b9 grande diversit\u00c3\u00a0 di tipologie esistenti) e il vino (del quale l&#8217;Italia \u00c3\u00a8 il maggior produttore mondiale) costituiscono una parte importante della cucina italiana, con molte variet\u00c3\u00a0 autoctone e una tutela legale specifica.<br \/>\nAnche il caff\u00c3\u00a8, specialmente l&#8217;<strong> <a>espresso<\/a><\/strong> e quello napoletano, \u00c3\u00a8 una bevanda importante e tipica della cucina italiana.<\/p>\n<p style=\"text-align: justify;\">Nato in Italia e di grande importanza internazionale \u00c3\u00a8 anche il movimento culturale e gastronomico<strong> Slow Food,<\/strong> convertitosi in ente atto alla tutela delle specificit\u00c3\u00a0 culinarie, il quale salvaguarda svariati prodotti regionali della cucina italiana, sotto il sello dei Presidi Slow Food.<\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Con queste premesse, devo ammettere che il mio compito e&#8217; veramente arduo.<\/p>\n<p style=\"text-align: justify;\">A casa abbiamo pensato molto a quale cibo avrebbe potuto meglio identificare questa nazione e, devo ammetterlo, non e&#8217; stato assolutamente facile.<\/p>\n<p style=\"text-align: justify;\">Data la giornata di &#8220;Befana&#8221;, tipica festivita&#8217; nazionale, abbiamo &#8220;celebrato oggi con un ossobuco e polenta.<br \/>\nIn effetti il clima caldo non e&#8217; molto indicato, ma pazienza.<\/p>\n<p style=\"text-align: justify;\">Negli anni passati ho seguito diversi procedimenti per la preparazione dell&#8217;ossobuco (vedi <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2010\/10\/17\/ossobuco-cucinarebene_pap\/\">qua<\/a><\/strong><\/em> e <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2008\/05\/08\/ossobuco-in-gremolata\/\">qua<\/a><\/strong><\/em>), oggi mi sono basata sul libro &#8220;<em>La cucina della pentola a pressione<\/em>&#8221; di <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/09\/18\/lisa-biondi\/\">Lisa Biondi<\/a><\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Purtroppo &#8211; per me &#8211; ho ecceduto con la quantita&#8217; della carne, quindi ho quasi raddoppiato le dosi degli ingredienti.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong> x 4 persone &#8211; <strong>Ossobuco<\/strong><\/p>\n<pre>4 ossibuchi (circa 600-700gr)\r\n80gr di burro o margarina\r\n1\/2 bicchiere di vino bianco secco\r\nsedano, carota, cipolla tritati\r\n250gr di pomodori pelati\r\n1\/2 bicchiere di brodo o dado\r\nsale e pepe\r\nfarina\r\nscorza di limone \r\nprezzemolo tritati<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Per prima cosa tagliuzzate leggermente il bordo della carne, cosi&#8217; che durante la cottura non si arricci.<\/p>\n<p style=\"text-align: justify;\">Nella pentola scoperta fate dorare gli ossibuchi leggermente infarinati nel burro imbiondito, spruzzateli con il vino bianco che lascerete evaporare, salate, pepate ed unite il trito di sedano, carota e cipolla.<\/p>\n<figure id=\"attachment_20078\" aria-describedby=\"caption-attachment-20078\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20078 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200105_151133-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200105_151133-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200105_151133-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200105_151133-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200105_151133-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20078\" class=\"wp-caption-text\">Italia. Ossobuco con polenta<\/figcaption><\/figure>\n<figure id=\"attachment_20079\" aria-describedby=\"caption-attachment-20079\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20079 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200105_152028-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200105_152028-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200105_152028-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200105_152028-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200105_152028-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20079\" class=\"wp-caption-text\">Italia. Ossobuco con polenta<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Lasciate insaporire poi aggiungete i pomodori pelati ed il brodo.<\/p>\n<figure id=\"attachment_20080\" aria-describedby=\"caption-attachment-20080\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20080 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200105_152354-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200105_152354-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200105_152354-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200105_152354-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200105_152354-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20080\" class=\"wp-caption-text\">Italia. Ossobuco con polenta<\/figcaption><\/figure>\n<figure id=\"attachment_20093\" aria-describedby=\"caption-attachment-20093\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20093 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_124613-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_124613-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_124613-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_124613-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_124613-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20093\" class=\"wp-caption-text\">Italia. Ossobuco con polenta<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Chiudete la pentola, all&#8217;inizio del sibilo abbassate la fiamma e calcolate 45 minuti di cottura.<\/p>\n<p style=\"text-align: justify;\">Cospargete gli ossibuchi con il trito di scorza di limone e di prezzemolo e serviteli (meglio con un risotto alla milanese o del pure&#8217;, ma anche un&#8217;ottima polenta, sempre in pentola a pressione, come ho fatto io).<\/p>\n<figure id=\"attachment_20094\" aria-describedby=\"caption-attachment-20094\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20094 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_125134-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_125134-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_125134-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_125134-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_125134-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20094\" class=\"wp-caption-text\">Italia. Ossobuco con polenta<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Per la cottura della polenta FIORETTO in pentola a pressione, ho seguito il mio procedimento &#8211; che troverete <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/11\/21\/polenta-in-pap\/\">qua<\/a><\/strong><\/em> &#8211; usando la proporzione di 1:3,5<\/p>\n<figure id=\"attachment_20092\" aria-describedby=\"caption-attachment-20092\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20092 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_124609-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_124609-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_124609-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_124609-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_124609-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20092\" class=\"wp-caption-text\">Italia. Polenta in pentola a pressione<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Volevamo farci mancare forse un ultimo dolcino?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20091\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_133340-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_133340-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_133340-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_133340-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200106_133340-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Buon appetito<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cucina italiana si \u00c3\u00a8 sviluppata attraverso secoli di cambiamenti politici e sociali, con radici che risalgono al IV secolo a.C.<\/p>\n","protected":false},"author":2,"featured_media":19968,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,168,22,60],"tags":[176,54,243,53],"class_list":["post-19962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-europa","category-food","category-secondi_piatti","tag-176","tag-cereali","tag-europa_sud","tag-pentola_a_pressione"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/19962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=19962"}],"version-history":[{"count":13,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/19962\/revisions"}],"predecessor-version":[{"id":43907,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/19962\/revisions\/43907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/19968"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=19962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=19962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=19962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}