{"id":19958,"date":"2020-01-08T14:39:33","date_gmt":"2020-01-08T13:39:33","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=19958"},"modified":"2023-01-22T13:31:17","modified_gmt":"2023-01-22T12:31:17","slug":"liechtenstein_kasknopfle","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/01\/08\/liechtenstein_kasknopfle\/","title":{"rendered":"# 23 &#8211; Principato del Liechtenstein. K\u00c3\u00a4skn\u00c3\u00b6pfle e strudel"},"content":{"rendered":"<p style=\"text-align: justify;\">Dopo diversi giri, siamo approdati in uno tra i piu&#8217; piccoli stati: il<strong> Principato del Liechtenstein<\/strong>, che misura all\u00e2\u20ac\u2122incirca 160 km\u00c2\u00b2 ed \u00c3\u00a8 popolato da 37.800 abitanti.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Il Liechtenstein e&#8217; immerso nel cuore dell&#8217;Europa, tra la Svizzera e l&#8217;Austria, e dista solo mezz&#8217;ora d\u00e2\u20ac\u2122auto dal Lago di Costanza.<br \/>\nNon ha alcun sbocco sul mare ed \u00c3\u00a8 percorso da fiume Reno, la cui navigazione internazionale gli ha sempre permesso di mantenere un \u00e2\u20ac\u02dcfilo diretto\u00e2\u20ac\u2122 con la Germania.<\/p>\n<figure id=\"attachment_31058\" aria-describedby=\"caption-attachment-31058\" style=\"width: 470px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31058\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/mappa-europa-capitali-e1619257906254.jpg\" alt=\"\" width=\"470\" height=\"410\" \/><figcaption id=\"caption-attachment-31058\" class=\"wp-caption-text\">Da Internet: Mappa dell&#8217;Europa con le capitali<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Cosa degustare in Liechtenstein, dunque?<br \/>\nSi possono assaporare anche gli eccellenti vini, tra i quali il Vaduzer, un ottimo vino rosso molto apprezzato da abitanti e visitatori.<\/p>\n<p style=\"text-align: justify;\">Il Principato\u00c2\u00a0\u00c3\u00a8 caratterizzato da piatti che risentono delle influenze dei paesi limitrofi, in particolar modo di Austria e Svizzera.<br \/>\nEcco dunque una variegata offerta di formaggi e relative pietanze, come ad esempio le succose polpettine K\u00c3\u00a4skn\u00c3\u00b6pfle, specialit\u00c3\u00a0 del paese.<\/p>\n<p style=\"text-align: justify;\">E <strong>K\u00c3\u00a4skn\u00c3\u00b6pfle<\/strong> sia!<\/p>\n<p style=\"text-align: justify;\">La ricetta e&#8217; stata presa direttamente dal sito istituzionale e la potete trovare <em><strong>qui <\/strong><\/em>( era https:\/\/tourismus.li\/en\/activities\/art-culture\/gastronomy-wine\/delights-from-liechtenstein\/kaesknoepfle\/ ).<br \/>\nPer ragioni &#8220;numeriche&#8221;, l&#8217;ho dimezzata.<\/p>\n<p><strong>Ingredienti\u00c2\u00a0 &#8211; K\u00c3\u00a4skn\u00c3\u00b6pfle -\u00c2\u00a0 4 persone<br \/>\n<\/strong><\/p>\n<pre>300 g di farina\r\n4 uova\r\n500 ml di acqua\r\nun pizzico di pepe\r\nun pizzico di noce moscata\r\nun pizzico di sale<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Mettete gli ingredienti in una ciotola e mescolateli creando un impasto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-19980\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_175400-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_175400-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_175400-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_175400-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_175400-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Lasciate riposare l&#8217;impasto per 10-20 minuti.<\/p>\n<p style=\"text-align: justify;\">A questo punto passate l&#8217;impasto attraverso la grattugia speciale (&#8220;Kn\u00c3\u00b6pflehobel&#8221;) direttamente in acqua bollente e salata (2 cucchiai colmi di sale).<\/p>\n<figure id=\"attachment_19981\" aria-describedby=\"caption-attachment-19981\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19981 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_182258-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_182258-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_182258-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_182258-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_182258-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-19981\" class=\"wp-caption-text\">grattugia speciale (&#8220;Kn\u00c3\u00b6pflehobel&#8221;)<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Lasciate i pezzetti di pasta nell&#8217;acqua bollente per un paio di minuti, facendoli cosi&#8217; cuocere, quindi metteteli in una ciotola.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-19983\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_184059-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_184059-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_184059-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_184059-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_184059-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-19984\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_184216-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_184216-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_184216-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_184216-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_184216-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nAggiungete il formaggio grattugiato di Appenzeller e il formaggio acido grattugiato e mescolare insieme (noi ci siamo accontentati di normale Ementhaler).<\/p>\n<figure id=\"attachment_19985\" aria-describedby=\"caption-attachment-19985\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19985 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_184905-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_184905-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_184905-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_184905-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_184905-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-19985\" class=\"wp-caption-text\">Liechtenstein. K\u00c3\u00a4skn\u00c3\u00b6pfle<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Friggete gli anelli di cipolla nel burro fino a quando non sono dorati, quindi metteteli sopra il piatto di portata e servite ben caldo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-19982\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_182637-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_182637-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_182637-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_182637-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_182637-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">I contorni tradizionali sono insalata verde, insalata di patate e salsa di mele (che, pur avendola a casa, non sapevo bene come usarla e dove metterla).<\/p>\n<figure id=\"attachment_19986\" aria-describedby=\"caption-attachment-19986\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19986 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_185357-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_185357-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_185357-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_185357-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200103_185357-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-19986\" class=\"wp-caption-text\">Liechtenstein. K\u00c3\u00a4skn\u00c3\u00b6pfle<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Se i K\u00c3\u00a4skn\u00c3\u00b6pfle dovessero risultare troppo asciutti, aggiungete un goccio di acqua calda prima di mescolarli al formaggio.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Sicuramente molti di voi conosceranno questa preparazione con un nome diverso, a seconda della posizione &#8220;geografica&#8221; in cui si trova: K\u00c3\u00a4sesp\u00c3\u00a4tzle, noto anche a livello regionale come Ch\u00c3\u00a4schn\u00c3\u00b6pfli (Svizzera), K\u00c3\u00a4skn\u00c3\u00b6pfle (Vorarlberg), Kasspatzln (Tirolo) o K\u00c3\u00a4ssp\u00c3\u00a4tzle \/ K\u00c3\u00a4sspatz\u00c3\u00a2 \/ K\u00c3\u00a4sspatzn (Swabia), Svizzera, Tirolo, Svizzera, Liechtenstein, Svizzera,<\/p>\n<p style=\"text-align: justify;\">E per dolcino?<br \/>\nUn piccolo Apfelstrudel, come richiesto anche dalla Nazione in oggetto, chiaramente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-19987\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200101_142558-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200101_142558-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200101_142558-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200101_142558-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/01\/IMG_20200101_142558-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Guten Appetit.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo diversi giri, siamo approdati in uno tra i piu&#8217; piccoli stati: il Principato del Liechtenstein, che misura all\u00e2\u20ac\u2122incirca 160 km\u00c2\u00b2 ed \u00c3\u00a8 popolato da 37.800 abitanti.<\/p>\n","protected":false},"author":2,"featured_media":19969,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,22,76,51],"tags":[176,236],"class_list":["post-19958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-food","category-pasta","category-primi_piatti","tag-176","tag-europa_centrale"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/19958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=19958"}],"version-history":[{"count":12,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/19958\/revisions"}],"predecessor-version":[{"id":40489,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/19958\/revisions\/40489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/19969"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=19958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=19958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=19958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}