{"id":1990,"date":"2010-03-31T18:40:15","date_gmt":"2010-03-31T17:40:15","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/cioccolata-calda\/"},"modified":"2018-11-10T17:35:38","modified_gmt":"2018-11-10T16:35:38","slug":"cioccolata-calda","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2010\/03\/31\/cioccolata-calda\/","title":{"rendered":"Cioccolata calda&#8230;"},"content":{"rendered":"<p style=\"text-align: justify;\">.. fuori dall&#8217;Italia.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Per me e&#8217; decisamente un bel dramma.<br \/>\nIn Italia, se vuoi una bella (e buona) cioccolata calda, te ne vai in un bar e te la ordini, con o senza panna, a discrezione della quantita&#8217; di sovrappeso personale.<\/p>\n<p style=\"text-align: justify;\">Ma se si esce di un pochino&#8230; ecco il dramma.<br \/>\nGia&#8217; in Svizzera ed in Austria la situazione non cambia, figurarsi qui a Patatolandia!<\/p>\n<p style=\"text-align: justify;\">Uno entra in un bar, definiamolo cosi&#8217;, oppure in un negozio che vende cioccolato\/praline, si prepara la bocca per una buona cioccolata densa, scura, che quasi il cucchiaino resta in piedi nella tazza e.. ecco che arriva&#8230; brodaglia.<\/p>\n<p style=\"text-align: justify;\">Ebbene si, bisogna ammetterlo, quello che si aspetta non e&#8217; minimamente simile a quello che si pregusta: latte e cioccolato.<\/p>\n<p style=\"text-align: justify;\">Poi dipende da dove vai e trovi cioccolato e cioccolato, ma la sostanza non cambia.<\/p>\n<p>Che tristezza \ud83d\ude41<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>.. fuori dall&#8217;Italia.<\/p>\n","protected":false},"author":2,"featured_media":13763,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[149,110],"tags":[],"class_list":["post-1990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bevande","category-monaco"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1990"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1990\/revisions"}],"predecessor-version":[{"id":13764,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1990\/revisions\/13764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/13763"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}