{"id":1975,"date":"2010-05-21T18:40:15","date_gmt":"2010-05-21T17:40:15","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/panini-dolci-con-gocce-di-cioccolato\/"},"modified":"2022-07-05T11:43:25","modified_gmt":"2022-07-05T09:43:25","slug":"panini-con-gocce-di-cioccolato","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2010\/05\/21\/panini-con-gocce-di-cioccolato\/","title":{"rendered":"Panini dolci con gocce di cioccolato"},"content":{"rendered":"<p style=\"text-align: justify;\">Ok.<!--more--><br \/>\nOra che vedo che l&#8217;impasto lievita, mi sto cimentando con la panificazione e la lievitazione (iniziando con il lievito di birra).<\/p>\n<p style=\"text-align: justify;\">In questo caso ho preparato i <strong>panini dolci con gocce di cioccolato<\/strong> (di <strong>Anna Moroni<\/strong>), trovati nel forum di GialloZafferano, dove era postata anche la seguente ricetta<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong><\/p>\n<pre style=\"text-align: justify;\">1\/2 Kg di farina\r\n250g di latte\r\n1 cubetto di lievito di birra,\r\n50g di zucchero\r\n25g di burro\r\n1 cucchiaino di sale\r\n1 uovo + 1 tuorlo\r\n100g di gocce di cioccolato\r\nfarina per il piano di lavoro<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Mettete la farina a fontana sul piano di lavoro.<br \/>\nAl centro mettete il latte, in cui avrete diluito il lievito e lo zucchero, il burro tagliato a pezzetti e il sale.<\/p>\n<p style=\"text-align: justify;\">Impastate leggermente e unite le uova, uno alla volta, incorporandole bene.<\/p>\n<p style=\"text-align: justify;\">Unite le gocce di cioccolato, precedentemente raffreddate in frigorifero per evitare che si sciolgano.<\/p>\n<p style=\"text-align: justify;\">Impastate bene e lasciate lievitare l&#8217;impasto.<\/p>\n<p style=\"text-align: justify;\">Copritelo con la pellicola trasparente per non farlo seccare.<br \/>\nCapovolgere l&#8217;impasto sul piano di lavoro infarinato e stendetelo con il matterello.<\/p>\n<p style=\"text-align: justify;\">Con il tagliapasta rotondo ritagliate un disco-porzione di 30g.<\/p>\n<p style=\"text-align: justify;\">Lavorate ogni disco avvolgendolo con le mani infarinate e formate una pagnottella; disponetele sopra la placca da forno , far lievitare 1 ora e cuocere in forno a 180\u00c2\u00b0per 30&#8242;<\/p>\n<figure id=\"attachment_9197\" aria-describedby=\"caption-attachment-9197\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-9197\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_9067-1024x768.jpg\" alt=\"\" width=\"525\" height=\"394\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_9067-1024x768.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_9067-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_9067-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_9067-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_9067.jpg 1600w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-9197\" class=\"wp-caption-text\">Panini dolci con gocce di cioccolato<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Devo dire che queste cose mi danno un&#8217;enorme soddisfazione.<br \/>\nIn questo caso ho fatto lievitare per piu&#8217; dei 45minuti suggeriti, erano quasi 2 ore.<br \/>\nMa non avevo niente da fare!<\/p>\n<p style=\"text-align: justify;\">Ne sono usciti circa una 30ina, di 37grammi (piu&#8217; o meno) cadauno.<\/p>\n<p>E&#8217; difficile da credersi, ma questo della foto era l&#8217;ultimo rimasto!<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ok.<\/p>\n","protected":false},"author":2,"featured_media":9197,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[145,22,90],"tags":[116],"class_list":["post-1975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dolci","category-food","category-lievitati","tag-ldb"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1975"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1975\/revisions"}],"predecessor-version":[{"id":37842,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1975\/revisions\/37842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/9197"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}