{"id":19472,"date":"2019-12-01T17:56:56","date_gmt":"2019-12-01T16:56:56","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=19472"},"modified":"2022-01-22T18:29:15","modified_gmt":"2022-01-22T17:29:15","slug":"norvegia_laksuppe","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/12\/01\/norvegia_laksuppe\/","title":{"rendered":"# 10 &#8211; Regno di Norvegia. Laksuppe &#8211; Zuppa di salmone"},"content":{"rendered":"<p style=\"text-align: justify;\">Ed eccoci ancora qua.<br \/>\nAbbiamo nuovamente sorvolato l&#8217;Europa approdando in<strong> Norvegia.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>Oggi e&#8217; la prima d&#8217;Avvento.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-19474\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_125909-e1575218661519-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_125909-e1575218661519-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_125909-e1575218661519-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_125909-e1575218661519-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_125909-e1575218661519-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Ma il nostro viaggio intorno al mondo non si ferma e prosegue.<\/p>\n<p style=\"text-align: justify;\">Nel libro &#8220;<strong>Norwegisch Kochen<\/strong>&#8221; ( Alexander Poeche e Susanne Schoeer) ho cercato qualche piatto semplice e leggero per la giornata di oggi: Tobias sarebbe uscito poco dopo l&#8217;ora di pranzo per andare ad un compleanno, mentre io non ho troppo tempo da &#8220;perdere&#8221; dato che dovrei iniziare con la preparazione dei biscotti dell&#8217;Avvento.<\/p>\n<figure id=\"attachment_19479\" aria-describedby=\"caption-attachment-19479\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19479 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_173141-e1575218669515-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_173141-e1575218669515-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_173141-e1575218669515-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_173141-e1575218669515-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_173141-e1575218669515-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-19479\" class=\"wp-caption-text\">&#8220;Norwegisch Kochen&#8221; ( Alexander P\u00c3\u00b6che e Susanne Sch\u00c3\u00b6er)<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ho cosi&#8217; optato per questa &#8220;<strong>Lakssuppe<\/strong>&#8220;, ossia una zuppa di salmone.<\/p>\n<p><strong>Ingredienti &#8211; Laksuppe &#8211; Zuppa di salmone<br \/>\n<\/strong><\/p>\n<pre>3 patate\r\n1 piccolo pezzetto di sedano\r\n1 cipolla\r\nprezzemolo o erba cipollina\r\nolio\r\n1 lattina di pomodori (400gr)\r\n250gr di salmone\r\nsale, pepe\r\npanna acida (sostituibile con yoghurt)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Gli ingredienti sopra descritti sono quelle elencati nel libro.<br \/>\nHo aggiunto un cucchiaio di concentrato di pomodoro ed ho sostituito la panna acida con un normale yoghurt naturale.<\/p>\n<p style=\"text-align: justify;\">Pelate le patate e riducetele a pezzetti, affettate il sedano e la cipolla, sempre in piccoli pezzettini.<br \/>\nSminuzzate il prezzemolo (o erba cipollina).<\/p>\n<figure id=\"attachment_19478\" aria-describedby=\"caption-attachment-19478\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19478 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_120655-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_120655-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_120655-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_120655-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_120655-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-19478\" class=\"wp-caption-text\">Laksuppe &#8211; Zuppa di salmone &#8211; preparazione<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">In una pentola versate dell&#8217;olio e fatelo scaldare, poi unite la zipolla, le patate ed il sedano facendoli cuocere.<br \/>\nAggiungete 1 litro di acqua (calda) e continuate la cottura. Unite la lattina di pomodori ed il prezzemolo.<br \/>\nHo usato la pentola a pressione, facendo cuocere per 4 minuti e facendo sfiatare leggermente.<\/p>\n<figure id=\"attachment_19477\" aria-describedby=\"caption-attachment-19477\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19477 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_123925-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_123925-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_123925-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_123925-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_123925-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-19477\" class=\"wp-caption-text\">Laksuppe &#8211; Zuppa di salmone &#8211; preparazione<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Quando la verdura sara&#8217; cotta, inserite il salmone tagliato a piccole e sottili fettine.<\/p>\n<figure id=\"attachment_19475\" aria-describedby=\"caption-attachment-19475\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19475 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_125249-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_125249-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_125249-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_125249-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_125249-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-19475\" class=\"wp-caption-text\">Laksuppe &#8211; Zuppa di salmone &#8211; preparazione<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La zuppa e&#8217; pronta quando anche il salmone e&#8217; cotto: ci vorranno pochi minuti, essendo tagliato finemente.<\/p>\n<p style=\"text-align: justify;\">Salate e pepate a gusto.<\/p>\n<p style=\"text-align: justify;\">Servite nel piatto, aggiungendo la panna acida.<\/p>\n<figure id=\"attachment_19476\" aria-describedby=\"caption-attachment-19476\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19476 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_125848-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_125848-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_125848-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_125848-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_125848-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-19476\" class=\"wp-caption-text\">Laksuppe &#8211; Zuppa di salmone<\/figcaption><\/figure>\n<figure id=\"attachment_19480\" aria-describedby=\"caption-attachment-19480\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-19480\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_130219-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_130219-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_130219-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_130219-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191201_130219-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-19480\" class=\"wp-caption-text\">Laksuppe &#8211; Zuppa di salmone<\/figcaption><\/figure>\n<p>Kos deg med m\u00c3\u00a5ltidet<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ed eccoci ancora qua. Abbiamo nuovamente sorvolato l&#8217;Europa approdando in Norvegia.<\/p>\n","protected":false},"author":2,"featured_media":19483,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,77,51,57],"tags":[176,242,53,183],"class_list":["post-19472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pesce","category-primi_piatti","category-zuppa","tag-176","tag-europa_nord","tag-pentola_a_pressione","tag-yoghurt"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/19472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=19472"}],"version-history":[{"count":13,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/19472\/revisions"}],"predecessor-version":[{"id":31111,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/19472\/revisions\/31111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/19483"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=19472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=19472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=19472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}