{"id":1923,"date":"2010-09-09T18:40:14","date_gmt":"2010-09-09T17:40:14","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/pasta-con-carne-macinata\/"},"modified":"2025-11-23T16:56:27","modified_gmt":"2025-11-23T15:56:27","slug":"pasta-con-carne-macinata","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2010\/09\/09\/pasta-con-carne-macinata\/","title":{"rendered":"Pasta con carne macinata"},"content":{"rendered":"<p style=\"text-align: justify;\">Non hai tutto il tempo per aspettare che il ragu&#8217; cuocia?<!--more--><br \/>\nHai della carne macinata e non sai come utilizzarla?<br \/>\nEcco questa ricettina, tratta da CucinadiStagione (Agosto 2010) potrebbe essere adatta a te:<\/p>\n<p style=\"text-align: center;\"><strong>PASTA CON CARNE MACINATA<\/strong><\/p>\n<figure id=\"attachment_8262\" aria-describedby=\"caption-attachment-8262\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-8262\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_9723-1024x768.jpg\" alt=\"\" width=\"525\" height=\"394\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_9723-1024x768.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_9723-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_9723-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_9723-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_9723.jpg 1600w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-8262\" class=\"wp-caption-text\">Pasta con carne macinata<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Pasta con carne macinata &#8211; 4 persone<br \/>\n<\/strong><\/p>\n<pre>1 cipolla\r\n2 cucchiai d'olio di arachini\r\n600gr di macinato magro di manzo\r\n1 spicchio d'aglio\r\n1\/2 cucchiaio di concentrato di pomodoro\r\n1 foglia di alloro\r\n1 chiodo di garofano\r\n1 dl di salsa per arrosto legata o brodo\r\n0,4dl di vino rosso\r\nsale, pepe bianco\r\n300gr di pasta (sono indicati i cornetti, ma ho usato i maccheroncini)\r\n2 cucchiai di burro\r\n160gr di formaggio grattugiato (ad es: emmentaler)<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Tritate la cipolla.<br \/>\nScaldate l&#8217;olio in una pentola e rosolatevi la carne macinata mescolando continuamente.<br \/>\nAggiungete la cipolla.<br \/>\nUnite l&#8217;aglio schiacciato, il concentrato di pomodoro, la foglia di alloro ed il chiodo di garofano.<\/p>\n<p>Quindi aggiungete la salsa per l&#8217;arrosto e fate sobbollire per circa 10 minuti. Unite il vino rosso e condite con sale e pepe.<\/p>\n<p>Nel frattempo lessate la pasta.<br \/>\nScolatela, passatela sotto l&#8217;acqua e fatela sgocciolare bene.<br \/>\nCondite con sale e pepe.<\/p>\n<p>Incorporate il burro a pezzetti e mescolate.<\/p>\n<p>Servite la pasta nei piatti.<\/p>\n<p>Spolverizzate di formaggio grattugiato e condite con la carne.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non hai tutto il tempo per aspettare che il ragu&#8217; cuocia?<\/p>\n","protected":false},"author":2,"featured_media":8262,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,76,51],"tags":[],"class_list":["post-1923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pasta","category-primi_piatti"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1923"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1923\/revisions"}],"predecessor-version":[{"id":49817,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1923\/revisions\/49817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/8262"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}