{"id":1911,"date":"2010-10-03T18:40:13","date_gmt":"2010-10-03T17:40:13","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/settimana-degli-italiani\/"},"modified":"2018-11-10T17:24:08","modified_gmt":"2018-11-10T16:24:08","slug":"settimana-degli-italiani","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2010\/10\/03\/settimana-degli-italiani\/","title":{"rendered":"Settimana degli italiani"},"content":{"rendered":"<p style=\"text-align: justify;\">Ed eccoci, oramai, alla conclusione dell&#8217;Oktoberfest.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Anche per quest&#8217;anno i turisti stranieri ritorneranno in patria pensando alle grandi bevute di birra, alle canzoni, alle bionde ed a tutto il resto.<\/p>\n<p style=\"text-align: justify;\">La seconda settimana dell&#8217;Oktoberfest viene definita &#8220;settimana degli italiani&#8221; ed e&#8217; vero!<br \/>\nUn grande assemblamento di italiani arrivano, organizzati con pullman e quant&#8217;altro per passare qualche ora.<\/p>\n<p style=\"text-align: justify;\">Va bene.<\/p>\n<p style=\"text-align: justify;\">Noi non ci siamo neppure avvicinati alla parata e neppure alle giostre.<\/p>\n<p style=\"text-align: justify;\">Tobias e&#8217; ancora piccolo (a mio avviso) per tutta questa baraonda&#8230;<\/p>\n<p style=\"text-align: justify;\">Chissa&#8217;, magari l&#8217;anno prossimo faremo un giro.<\/p>\n<p style=\"text-align: justify;\">Per il momento accontentiamoci di questa foto\u00c2\u00a0 \ud83d\ude42<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-13749\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_9602.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_9602.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_9602-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_9602-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ed eccoci, oramai, alla conclusione dell&#8217;Oktoberfest.<\/p>\n","protected":false},"author":2,"featured_media":13749,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-1911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1911"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1911\/revisions"}],"predecessor-version":[{"id":13751,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1911\/revisions\/13751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/13749"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}