{"id":19097,"date":"2019-12-10T20:10:05","date_gmt":"2019-12-10T19:10:05","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=19097"},"modified":"2022-01-24T16:09:24","modified_gmt":"2022-01-24T15:09:24","slug":"grecia_midia_pilafi","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/12\/10\/grecia_midia_pilafi\/","title":{"rendered":"# 13 &#8211; Grecia. Midia pilafi &#8211; Pilaf di cozze"},"content":{"rendered":"<p style=\"text-align: justify;\">Solitamente affrontiamo il pranzo &#8220;nazionale&#8221; del nostro giro intorno al Mondo durante il weekend.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Come mi e&#8217; gia&#8217; capitato precedentemente per il <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/12\/05\/nepal_dal-bhat\/\">Nepal<\/a><\/strong><\/em>, alcune volte e&#8217; possibile prepararlo anche in settimana.<br \/>\nPer la velocita&#8217; di esecuzione .. o per il tempo a disposizione della sottoscritta.<\/p>\n<p style=\"text-align: justify;\">Siamo cosi&#8217; ritornati nel Mediterraneo, precisamente in <strong>Grecia<\/strong>.<\/p>\n<figure id=\"attachment_31058\" aria-describedby=\"caption-attachment-31058\" style=\"width: 470px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31058\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/mappa-europa-capitali-e1619257906254.jpg\" alt=\"\" width=\"470\" height=\"410\" \/><figcaption id=\"caption-attachment-31058\" class=\"wp-caption-text\">Da Internet: Mappa dell&#8217;Europa con le capitali<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Cosa cucinare?<br \/>\nIl &#8220;Gyros&#8221; e&#8217; un secondo abbastanza comune a casa nostra, mentre la Moussak\u00c3\u00a0 e&#8217; forse un po&#8217; troppa piena di verdure per i rappresentanti maschi della famiglia.<br \/>\nCosi&#8217; ho preso in prestito dalla biblioteca locale un altro libto intitolato &#8220;Traditionelle griechische Rezept&#8221; &#8211; di Eleni Patera &#8211; dove ho trovato questo risottino con cozze, denominato appunto &#8220;<strong>Midia pilafi<\/strong> &#8220;<\/p>\n<figure id=\"attachment_19622\" aria-describedby=\"caption-attachment-19622\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19622 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_182232-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_182232-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_182232-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_182232-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_182232-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-19622\" class=\"wp-caption-text\">Grecia: Midia pilafi &#8211; Pilaf di cozze<\/figcaption><\/figure>\n<p><strong>Ingredienti &#8211; Midia pilafi &#8211; Pilaf di cozze<br \/>\n<\/strong><\/p>\n<pre><strong>Pilaf<\/strong>\r\n2 cucchiai di burro\r\n1 tazza di riso (per Pilaf)\r\n4 tazze di brodo vegetale\r\n\r\n1kg di cozze\r\n1\/4 di tazza di olio di oliva\r\n1 medio-grossa cipolla affettata\r\n1 spicchio d'aglio tagliato finemente\r\n1 tazza di succo di pomodoro (passata per me)\r\n1 cucchiaio di concentrato di pomodoro\r\nprezzemolo tritato fine\r\npepe nero macinato fresco \r\nsale<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Ho iniziato con la preparazione del condimento-cozze, dato che per la cottura del riso pilaf, con la pentola a pressione, impiego veramente poco.<\/p>\n<p style=\"text-align: justify;\">In una padella inserite l&#8217;olio e fate imbiondire la cipolla e l&#8217;aglio (precedentemente affettati in modo sottile).<br \/>\nInserite i restanti ingredienti, ad eccezione delle cozze, e cuocete la salsa una decina di minuti, fino a che non si restringe.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-19621\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_182222-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_182222-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_182222-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_182222-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_182222-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Aggiungete le cozze e fate cuocere per altri 5 minuti circa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-19619\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_183803-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_183803-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_183803-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_183803-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_183803-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Per la<strong> preparazione del riso pilaf<\/strong>, ho seguito la mia solita ricetta e tempistica cuocendo il riso in pentola a pressione (6.30 minuti, lasciando poi sfiatare lentemente).<\/p>\n<pre style=\"text-align: justify;\">burro\r\n250gr di riso\r\n375ml di liquido (brodo vegetale).<\/pre>\n<p>In questo caso non ho inserito la cipolla, ma ho usato del brodo di verdure come liquido.<br \/>\nUna volta sfiatato, ho aperto la pentola e sgranato il riso contenuto.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-19620\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_183807-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_183807-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_183807-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_183807-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_183807-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>A questo punto ho preparato il piatto: riso pilaf e cozze.<\/p>\n<figure id=\"attachment_19618\" aria-describedby=\"caption-attachment-19618\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19618 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_184313-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_184313-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_184313-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_184313-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_184313-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-19618\" class=\"wp-caption-text\">Grecia: Midia pilafi &#8211; Pilaf di cozze<\/figcaption><\/figure>\n<figure id=\"attachment_19617\" aria-describedby=\"caption-attachment-19617\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19617 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_184125-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_184125-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_184125-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_184125-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/IMG_20191210_184125-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-19617\" class=\"wp-caption-text\">Grecia: Midia pilafi &#8211; Pilaf di cozze<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ed anche questa volta Tobias ha gradito.<br \/>\nLe cozze erano decisamente giganti, ma non abbiamo rinunciato nel mangiarle!!<\/p>\n<p>\u00ce\u2018\u00cf\u20ac\u00ce\u00bf\u00ce\u00bb\u00ce\u00b1\u00cf\u008d\u00cf\u0192\u00cf\u201e\u00ce\u00b5 \u00cf\u201e\u00ce\u00bf \u00ce\u00b3\u00ce\u00b5\u00cf\u008d\u00ce\u00bc\u00ce\u00b1 \u00cf\u0192\u00ce\u00b1\u00cf\u201a<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Solitamente affrontiamo il pranzo &#8220;nazionale&#8221; del nostro giro intorno al Mondo durante il weekend.<\/p>\n","protected":false},"author":2,"featured_media":19098,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,22,77,51,67],"tags":[176,243,53],"class_list":["post-19097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-food","category-pesce","category-primi_piatti","category-riso_risotti","tag-176","tag-europa_sud","tag-pentola_a_pressione"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/19097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=19097"}],"version-history":[{"count":12,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/19097\/revisions"}],"predecessor-version":[{"id":35470,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/19097\/revisions\/35470"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/19098"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=19097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=19097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=19097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}