{"id":19088,"date":"2019-12-05T09:34:28","date_gmt":"2019-12-05T08:34:28","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=19088"},"modified":"2022-01-22T18:23:45","modified_gmt":"2022-01-22T17:23:45","slug":"nepal_dal-bhat","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/12\/05\/nepal_dal-bhat\/","title":{"rendered":"# 11 &#8211; Repubblica Federale Democratica del Nepal. Dal Bhat"},"content":{"rendered":"<p lang=\"it-IT\" style=\"text-align: justify;\">Visto il clima invernale una zuppa calda di sera ci sta piu&#8217; che bene.<\/p>\n<p lang=\"it-IT\" style=\"text-align: justify;\"><!--more--><\/p>\n<p lang=\"it-IT\" style=\"text-align: justify;\">In effetti quanto proposto oggi non e&#8217; altro che\u00c2\u00a0 il piatto nazionale del <strong>Nepal.<\/strong><\/p>\n<p lang=\"it-IT\" style=\"text-align: justify;\">Non che qui a Patatolandia al momento faccia cosi&#8217; freddo&#8230; ma il calore di una zuppa confortante rincuora gli animi piu&#8217; freddi e riscalda il corpo, rigenerandolo.<\/p>\n<p lang=\"it-IT\" style=\"text-align: justify;\">Le informazioni generali sul Nepal\u00c2\u00a0 che seguono, sono tratte da <em><strong><a href=\"https:\/\/www.turismo.it\/oltreconfine\/articolo\/art\/dal-bhat-le-lenticchie-profumano-di-aromi-in-nepal-id-17046\/\">qui <\/a><\/strong><\/em><\/p>\n<p lang=\"it-IT\" style=\"text-align: justify;\">&#8230; Incastonato tra il Tibet e l\u00e2\u20ac\u2122India, il Nepal rappresenta l\u00e2\u20ac\u2122incontro di due fedi e culture, hindu e buddista. Dalla capitale Kathmandu fino ai villaggi sherpa, tradizioni e riti religiosi rimangono intatti. Anche nella cucina \u00c3\u00a8 naturalmente presente l\u00e2\u20ac\u2122incontro tra India e Tibet .<\/p>\n<p style=\"text-align: justify;\">Il piatto nazionale \u00c3\u00a8 il <strong>Dal Bhat<\/strong>, composto da riso (bhat), una zuppa di lenticchie (dal), spezie e verdure (tarkari).<br \/>\nIl pane viene preparato come chapati (simile alla nostra piadina) e mangiato insieme a curry e al dahl.<\/p>\n<p style=\"text-align: justify;\">Il \u00e2\u20ac\u0153dahl\u00e2\u20ac\u009d o \u00e2\u20ac\u0153dal\u00e2\u20ac\u009d \u00c3\u00a8 preparato in diversi modi; basti solo pensare che in India vengono coltivate pi\u00c3\u00b9 di 50 tipologie di lenticchie.<\/p>\n<figure id=\"attachment_19539\" aria-describedby=\"caption-attachment-19539\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19539 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_190443-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_190443-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_190443-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_190443-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_190443-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-19539\" class=\"wp-caption-text\">Nepal: Dal Bhat<\/figcaption><\/figure>\n<p lang=\"it-IT\" style=\"text-align: justify;\">Il dal bhat viene consumato due volte al giorno nella maggior parte delle famiglie. Gli ingredienti, separati nel piatto, sono assemblati da ciascun commensale usando solamente la mano destra, per non rendere impuro il cibo. Solitamente \u00c3\u00a8 vegetariano, ma non mancano le varianti con aggiunta di carne. La bevanda che accompagna il piatto \u00c3\u00a8 il t\u00c3\u00a8 (chiya), nella sua versione pi\u00c3\u00b9 classica e popolare con latte, acqua, te nero e spezie (masala).<\/p>\n<p lang=\"it-IT\" style=\"text-align: justify;\">Per quanto riguarda la <strong>ricetta<\/strong> che ho seguito, questa e&#8217; presa da <em><strong><a href=\"http:\/\/indiaedintorni.wordpress.com\">Indiaedintorni <\/a><\/strong><\/em><\/p>\n<p lang=\"it-IT\" style=\"text-align: justify;\">La preparazione richiede una particolare tecnica chiamata \u00e2\u20ac\u0153<strong>tarka<\/strong>\u00e2\u20ac\u009d: si scalda una piccola quantit\u00c3\u00a0 di olio o di ghee (burro chiarificato) in cui poi verranno cotte le spezie fresche per pochi secondi. Un accorgimento utilizzato nella fase finale di cottura di piatti a base di verdura, legumi, pesce e carne.<br \/>\nUn \u00e2\u20ac\u0153soffritto\u00e2\u20ac\u009d rapido che permette agli aromi di non perdere le caratteristiche organolettiche, utile nelle cotture lente e prolungate per far s\u00c3\u00ac che non diminuisca l\u00e2\u20ac\u2122intensit\u00c3\u00a0 del sapore. Il tarka pu\u00c3\u00b2 anche essere aggiunto nella fase finale della ricetta e sempre allo scopo di donare profumo al piatto esaltando il gusto degli ingredienti.<br \/>\nIn Nepal, come in India, viene utilizzata una pentola di piccole dimensioni e dai bordi alti, in ferro pesante in grado di mantenere il calore durante la cottura.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Dal Bhat\u00c2\u00a0 ( riso e lenticchie )<br \/>\n<\/strong><\/p>\n<pre><strong>Per il riso (Bhat)<\/strong>\r\n2 tazze di riso (basmati)\r\n4 tazze (1 lt) di acqua\r\n1 cucchiaino di burro (opzionale)\r\n\r\n<strong>Per le lenticchie (Dal)<\/strong>\r\n1 \u00c2\u00bd tazze di lenticchie (qualsiasi tipo)\r\n4-5 tazze di acqua (dipende della consistenza di liquido)\r\n\u00c2\u00bd cucchiaino di curcuma\r\n1 cucchiaino di aglio tritato\r\n6 cucchiai di burro chiarificato (ghee)\r\n3\/4 di tazza di cipolle affettate\r\n2 peperoncini ( meglio peperoncini rossi secchi)\r\nSale qb\r\nun pizzico di assafetida (A)\r\nun pizzico di jimbu (B)\r\n1 cucchiaio di pasta di zenzero fresco<\/pre>\n<p><strong>Procedimento.. originale<br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\">Sciacquate il riso Basmati pi\u00c3\u00b9 volte svuotando continuamente l\u00e2\u20ac\u2122acqua, finch\u00c3\u00a9 questa non risulti limpida, poi copritelo con acqua fredda e far riposare in frigo per 5 minuti.<\/p>\n<p style=\"text-align: justify;\">Scolate e ripetete l\u00e2\u20ac\u2122operazione precedente quindi copritelo con acqua fredda e far riposare in frigo per altri 5 minuti. Scolate e fate bollire il riso nel litro d\u00e2\u20ac\u2122acqua a fuoco medio per circa 10 -15 minuti. A questo punto l\u00e2\u20ac\u2122acqua si dovrebbe essere completamente assorbita, aggiungete il burro. Mettete al minimo il fuoco e fate cuocere, coperto, per altri 5 minuti fino a cottura ultimata.<\/p>\n<figure id=\"attachment_19538\" aria-describedby=\"caption-attachment-19538\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19538 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_185910-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_185910-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_185910-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_185910-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_185910-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-19538\" class=\"wp-caption-text\">Nepal: Dal Bhat &#8211; riso Pilaf<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Lavate le lenticchie e lasciatele in ammollo per 10 minuti. Rimuovete tutto ci\u00c3\u00b2 che galleggia sulla superficie, risciacquate. Mettete le lenticchie sgocciolate in acqua dolce e portate a bollore, quindi aggiungere tutte le spezie. Riducete il fuoco e cuocete, coperto, per 20 o 30 minuti fino a quando le lenticchie sono morbide e la consistenza \u00c3\u00a8 cremosa.<br \/>\n{ in pentola a pressione 15 minuti sono risultati troppi.. le lenticchie sono risultate un po&#8217; sfaldate }<\/p>\n<p style=\"text-align: justify;\">In una piccola padella mettete a soffriggere la cipolla nel restante burro, assieme ai peperoncini ed all\u00e2\u20ac\u2122aglio. Aggiungete al soffritto le lenticchie e lasciate cuocere ancora qualche minuto. Servite nello stesso piatto il riso ed a fianco le lenticchie. Il riso nepalese non \u00c3\u00a8 troppo umido e appiccicoso.<br \/>\nI chicchi di riso sono soffici, i grani separati gli uni dagli altri e morbidi.<\/p>\n<figure id=\"attachment_19537\" aria-describedby=\"caption-attachment-19537\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19537 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_185433-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_185433-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_185433-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_185433-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_185433-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-19537\" class=\"wp-caption-text\">Nepal: Dal Bhat<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_19540\" aria-describedby=\"caption-attachment-19540\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19540 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_190504-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_190504-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_190504-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_190504-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_190504-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-19540\" class=\"wp-caption-text\">Nepal: Dal Bhat<\/figcaption><\/figure>\n<p><strong>Note Personali e Varie<br \/>\n<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Per il riso Pilaf ho seguito la ricetta per la pentola a pressione.<br \/>\nNon avevo l&#8217;arborio, ma un normale riso..<\/li>\n<li style=\"text-align: justify;\">(A) assafetida &#8211; l&#8217;ho omessa, aggiungendo del pepe nero<\/li>\n<li style=\"text-align: justify;\">(B) Jumbo &#8211; qui su <em><strong><a href=\"https:\/\/en.wikipedia.org\/wiki\/Jimbu\">Wikipedia<\/a> <\/strong><\/em>&#8211; totalmente omessa<\/li>\n<\/ul>\n<p><strong>Ingredienti &#8211; Riso Pilaf con Pentola a Pressione<\/strong> &#8211; (x 4 persone)<strong><br \/>\n<\/strong><\/p>\n<pre>250gr di riso arborio\r\n50gr di burro\r\n50gr di cipolla tritata\r\n375 gr di brodo o acqua<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Fate rosolare lentamente la cipolla con il burro, senza lasciarla imbiondire, unite il riso e mescolatelo finche&#8217; avra&#8217; assorbito parte del condimento.<br \/>\nVersate il brodo bollente, sale, pepe e rimestate.<br \/>\nChiudete la pentola, all&#8217;inizio del sibilo abbassate la fiamma e calcolate 7-8 minuti di cottura.<br \/>\nTrascorso questo tempo, aprite la pentola come di regola, mescolate il riso e servitelo subito ben caldo come contorno<\/p>\n<figure id=\"attachment_19539\" aria-describedby=\"caption-attachment-19539\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19539 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_190443-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_190443-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_190443-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_190443-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/12\/IMG_20191204_190443-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-19539\" class=\"wp-caption-text\">Nepal: Dal Bhat<\/figcaption><\/figure>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li>Il liquido deve essere sempre una volta e mezza il volume del riso.<\/li>\n<\/ul>\n<p>\u00e0\u00a4\u00a4\u00e0\u00a4\u00aa\u00e0\u00a4\u00be\u00e0\u00a4\u02c6\u00e0\u00a4\u201a\u00e0\u00a4\u2022\u00e0\u00a5\u2039 \u00e0\u00a4\u2013\u00e0\u00a4\u00be\u00e0\u00a4\u00a8\u00e0\u00a4\u00be\u00e0\u00a4\u2022\u00e0\u00a5\u2039 \u00e0\u00a4\u00ae\u00e0\u00a4\u0153\u00e0\u00a4\u00be \u00e0\u00a4\u00b2\u00e0\u00a4\u00bf\u00e0\u00a4\u00a8\u00e0\u00a5\u0081\u00e0\u00a4\u00b9\u00e0\u00a5\u2039\u00e0\u00a4\u00b8\u00e0\u00a5\u008d<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visto il clima invernale una zuppa calda di sera ci sta piu&#8217; che bene.<\/p>\n","protected":false},"author":2,"featured_media":19089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,57],"tags":[176,55,53],"class_list":["post-19088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-zuppa","tag-176","tag-legumi","tag-pentola_a_pressione"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/19088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=19088"}],"version-history":[{"count":19,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/19088\/revisions"}],"predecessor-version":[{"id":34268,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/19088\/revisions\/34268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/19089"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=19088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=19088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=19088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}