{"id":1900,"date":"2010-10-25T18:40:13","date_gmt":"2010-10-25T17:40:13","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/spirali-bicolore\/"},"modified":"2019-11-25T17:25:11","modified_gmt":"2019-11-25T16:25:11","slug":"spirali-bicolore","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2010\/10\/25\/spirali-bicolore\/","title":{"rendered":"Spirali bicolore"},"content":{"rendered":"<p style=\"text-align: justify;\">OK.<!--more--><br \/>\nNon hanno niente delle spirali bicolore viste sulla rivista.<br \/>\nAlcune parti sono anche &#8220;marmorizzate&#8221;, ma il gusto non e&#8217; stato minimamente compromesso.<\/p>\n<figure id=\"attachment_7701\" aria-describedby=\"caption-attachment-7701\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7701\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0054.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0054.jpg 1600w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0054-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0054-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0054-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0054-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-7701\" class=\"wp-caption-text\">Spirali bicolore<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Solitamente uno non sa mai come usare i bianchi dell&#8217;uovo, questa volta avevo il problema inverso: Tobias voleva fare le lingue di gatto, cosi&#8217; mi avanzavano i rossi.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong><\/p>\n<pre>200gr di farina\r\n120gr di burro\r\n50gr di cacao in polvere\r\n80gr di zucchero\r\n3 tuorli\r\n1 cucchiaino di lievito\r\n1 pizzico di sale fino<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Setacciate la farina con il lievito ed il sale.<br \/>\nTenete da parte 2 cucchiai di farina per il piano di lavoro<br \/>\nMettete nel mix lo zucchero ed il burro freddo di frigo.<br \/>\nAzionate l&#8217;apparecchio per 3 minuti alla minima velocita&#8217;, fino ad ottenere una crema.<br \/>\nUnite i tuorli, uno alla volta, tenendo il robot in funzione per incorporarli.<br \/>\nAggiungete la farina, continuando a mixare.<br \/>\nTogliete dal mixer un po&#8217; piu&#8217; della meta&#8217; del composto, aggiungete il cacao nel recipiente e lavoratelo ancora 1 minuto.<\/p>\n<p style=\"text-align: justify;\">Scaldate il forno a 180gradi.<br \/>\nLavorate 5 minuti con le mani i 2 impasti, sul piano infarinato.<br \/>\nTirate con il mattarello la pasta gialla in una sfoglia alta 1\/2 cm.<br \/>\nStendete nello stesso modo anche la pasta al cacao.<br \/>\nAppoggiate le 2 paste una sull&#8217;altra, pressatele con il mattarello ed arrotolatele.<\/p>\n<p style=\"text-align: justify;\">Tagliate il rotolo a fette spesse 1 cm.<br \/>\nAdagiate le spirali su una placca rivestita con carta.<br \/>\nInfornate e cuocete 15 minuti.<\/p>\n<p style=\"text-align: justify;\">Staccate i biscotti dalla carta e lasciateli raffreddare.<\/p>\n<p style=\"text-align: justify;\">Metteteli su un piatto prima di servirli.<br \/>\nCopriteli di zucchero a velo nel caso in cui dovessero risultare come i miei<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OK.<\/p>\n","protected":false},"author":2,"featured_media":7701,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78,69,22],"tags":[],"class_list":["post-1900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biscotti","category-dessert","category-food"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1900"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1900\/revisions"}],"predecessor-version":[{"id":19134,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1900\/revisions\/19134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/7701"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}