{"id":1896,"date":"2010-11-30T18:40:13","date_gmt":"2010-11-30T17:40:13","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/harec\/"},"modified":"2020-07-19T13:58:41","modified_gmt":"2020-07-19T12:58:41","slug":"harec","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2010\/11\/30\/harec\/","title":{"rendered":"HAREC"},"content":{"rendered":"<p style=\"text-align: justify;\">Anni fa, quando abitavo ancora in Italia, avevo deciso di fare qualche cosa di cui non ero assolutamente capace e di cui non avevo assoluta conoscenza in materia: diventare <strong>Radioamatrice<\/strong>.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Questo significava passare un esame e conoscere il magnetismo, regole e regolamenti, ampere e quant&#8217;altro ancora in questo campo.<\/p>\n<p style=\"text-align: justify;\">Insomma, tutto cio&#8217; che non avevo mai capito a scuola e, alla fine, ecco che ho passato l&#8217;esame!<br \/>\nMa non chiedetemi piu&#8217; questi argomenti: si sono nascosti da qualche parte nel mio cervello, in un angolino cosi&#8217; celato che neppure io stessa riesco a trovarli.<\/p>\n<p style=\"text-align: justify;\">Perche&#8217; lasciare &#8220;scadere&#8221; il mio nominativo ( <em>callsign<\/em> )\u00c2\u00a0 italiano e non chiederne uno nuovo, qui a Patatolandia?<br \/>\nOttenendone uno, comunque, senza dover superare nuovamente l&#8217;esame teorico e pratico, praticamente un sogno!<\/p>\n<p style=\"text-align: justify;\">Ad una delle tante feste del paese, mi sono avvicinata al banchetto del gruppo dei radioamatori del mio paese per chiedere lumi.<br \/>\nGentilmente mi hanno fornito il nominativo dell&#8217;Ente preposto a tutto l&#8217;iter che avrei dovuto seguire per ricevere un nuovo &#8220;callsign&#8221; tedesco.<\/p>\n<p style=\"text-align: justify;\">Ecco la procedura da seguire qui in Germania\/Patatolandia.<br \/>\nLa scrivo perche&#8217; ho provato a cercarla ovunque e ci sono tantissime fonti diverse e contradditorie.<\/p>\n<p>Questo, comunque, e&#8217; quanto ha funzionato nel mio caso:<\/p>\n<p style=\"text-align: justify;\">1.- Inviare una mail ( mstr01.postfach@bnetza.de ) chiedendo un nuovo Callsign.<br \/>\nL&#8217;ufficio preposto ( Stefanie.Nieder@BNetzA.de, nel mio caso) mi ha risposto inviando un allegato da compilare, e la richiesta di inviare il certificato Harec in originale (si tratta di un documento scritto in 3 lingue che attesta il superamento dell&#8217;esame).<br \/>\nProbabilmente l&#8217;allegato e&#8217; disponibile anche sul loro sito, ma non ho verificato..<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">2.- Inviare la richiesta di ricevere il certificato HAREC presso l&#8217;ufficio competente (?) del &#8220;Ministero dello Sviluppo Economico Dipartimento per le Comunicazioni&#8221; &#8211; Sotto Articolazione II \u00e2\u20ac\u201c Autorizzazioni, verifiche e controlli nel mio caso si tratta della Regione Lombardia , allegando i seguenti documenti (scannerizzati):<\/p>\n<p style=\"text-align: justify;\">a. Licenza di Radioamatore italiana<br \/>\nb. Certificato di Residenza in Germania<br \/>\nc. Fotocopia di un documento di identita&#8217;<\/p>\n<p style=\"text-align: justify;\">Scrivendo chiaramente l&#8217;indirizzo di dove tale certificato <strong>deve essere inviato<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Ho scritto una semplice mail, senza tante formalita&#8217;, dicendo che ne avevo bisogno in quanto vivo all&#8217;estero.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">3.- Quando vi arriva il certificato originale dall&#8217;Italia (HAREC), mandatelo per normale posta qui<\/p>\n<p style=\"text-align: justify;\">Bundesnetzagentur<br \/>\nDienstleistungszentrum 2<br \/>\nHansaring 66<br \/>\n48155 M\u00c3\u00bcnster<\/p>\n<p style=\"text-align: justify;\">Tel:\u00c2\u00a0\u00c2\u00a0\u00c2\u00a0 0251 60 81-2 80<br \/>\nFax:\u00c2\u00a0\u00c2\u00a0\u00c2\u00a0 0251 60 81-1 81<\/p>\n<p style=\"text-align: justify;\">Allegando:<br \/>\na. Aufenthaltsbescheinigug\u00c2\u00a0 (ossia il documento che dichiara dove abitate)<br \/>\nb. Documento di identita&#8217; (passaporto o carta d&#8217;identita&#8217;)<br \/>\nc. Copia della Licenza italiana (Ordinaria, per me)<br \/>\nd. &#8220;Bescheinigung gem\u00c3\u00a4\u00c3\u0178 \u00c2\u00a7 5 Freiz\u00c3\u00bcgG\/EU (rilasciato dal comune tedesco di residenza)<\/p>\n<p style=\"text-align: justify;\">4.- L&#8217;ufficio tedesco competente ve lo rimandera&#8217; poi indietro, dicendo che la pratica e&#8217; stata inoltrata (a Monaco, nel mio specifico caso).<\/p>\n<p style=\"text-align: justify;\">5.- A seconda del tipo di licenza, verrete contattati o meno dal personale tedesco.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Qualche giorno dopo una simpatica signora, che parla anche inglese (! altrimenti era veramente tragica per me&#8230;), vi telefonera&#8217; chiedendo quale nominativo (callsign) volete adottare.<\/p>\n<p style=\"text-align: justify;\">La disponibilita&#8217; o meno della vostra scelta verra&#8217; verificata direttamente online.<\/p>\n<p style=\"text-align: justify;\">6.- Qualche giorno dopo dovreste essere presenti anche nel Callbook.\u00c2\u00a0 Personalmente mi cerco.. ma non mi sono trovata!<\/p>\n<p style=\"text-align: justify;\">A questo punto vorrei ringraziare tutti coloro che mi hanno aiutato nell&#8217;intricata ricerca della persona italiana preposta alla spedizione del certificato Harec:\u00c2\u00a0 grazie sezione ARI di Cinisello!<\/p>\n<p style=\"text-align: justify;\">73,<\/p>\n<p style=\"text-align: justify;\">ik2rxw \/ db2rxw<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anni fa, quando abitavo ancora in Italia, avevo deciso di fare qualche cosa di cui non ero assolutamente capace e di cui non avevo assoluta conoscenza in materia: diventare Radioamatrice.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101],"tags":[141,102],"class_list":["post-1896","post","type-post","status-publish","format-standard","hentry","category-passatempo","tag-darc","tag-hobby"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1896"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1896\/revisions"}],"predecessor-version":[{"id":24462,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1896\/revisions\/24462"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}