{"id":1877,"date":"2011-01-14T18:40:13","date_gmt":"2011-01-14T17:40:13","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/confettura-extra-di-zucca\/"},"modified":"2024-09-21T17:35:45","modified_gmt":"2024-09-21T15:35:45","slug":"confettura-extra-di-zucca","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2011\/01\/14\/confettura-extra-di-zucca\/","title":{"rendered":"Confettura extra di zucca"},"content":{"rendered":"<p style=\"text-align: justify;\">Avendo finito la marmellata di mirtilli, sono andata in dispensa a vedere che altro gusto era disponibile, giusto per spalmarlo sul pane a colazione.<!--more--><\/p>\n<p style=\"text-align: justify;\">Ho ritrovato un vasetto, che era stato acquistato tempo fa, durante le vacanze estive in Italia dell&#8217; &#8220;<strong>Officina della Natura<\/strong>&#8220;<\/p>\n<p style=\"text-align: justify;\">Avevo sempre tenuto con cura e tanto amore questo vasetto di &#8220;<strong>Confettura extra di zucca<\/strong>&#8220;, non sapendo bene come usarla&#8230; con del formaggio, accompagnando chissa&#8217; che cosa.<br \/>\nPensando, quindi, di sprecarlo e non farne buon uso.<\/p>\n<p style=\"text-align: justify;\">Alla fine ho deciso di aprirla per spalmarla sul pane (con semi di sesamo..).<\/p>\n<p style=\"text-align: center;\"><strong>Meraviglia<\/strong>!<\/p>\n<p style=\"text-align: justify;\">Davvero buonissima, il suo sapore e&#8217; molto intenso (nonostante non ci siano i &#8220;pezzi&#8221;), pastoso, con un tocco di limone per conservare il composto e con un pizzico di cannella per aromatizzarlo.<\/p>\n<p style=\"text-align: justify;\">Veramente adorabile!<\/p>\n<p style=\"text-align: justify;\">Avrei potuto aprirla prima, cosi&#8217; da prenderne una vagonata..<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avendo finito la marmellata di mirtilli, sono andata in dispensa a vedere che altro gusto era disponibile, giusto per spalmarlo sul pane a colazione.<\/p>\n","protected":false},"author":2,"featured_media":11192,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[152,22],"tags":[],"class_list":["post-1877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-confetture","category-food"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1877"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1877\/revisions"}],"predecessor-version":[{"id":46244,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1877\/revisions\/46244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/11192"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}