{"id":1856,"date":"2011-02-25T18:40:12","date_gmt":"2011-02-25T17:40:12","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/chiacchere\/"},"modified":"2018-02-23T15:47:44","modified_gmt":"2018-02-23T14:47:44","slug":"chiacchere","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2011\/02\/25\/chiacchere\/","title":{"rendered":"&#8230; chiacchere"},"content":{"rendered":"<p style=\"text-align: justify;\">Le chiacchere perche&#8217; vengono fatte solamente nel periodo di Carnevale?<!--more--><br \/>\nE se un ragazzino vuole usare la macchinetta della pasta (e voi non avete la piu&#8217; pallida idea di come fare la pasta in casa), cosa gli rispondete?<\/p>\n<p style=\"text-align: center;\">\n<strong>CHIACCHERE<\/strong>!!<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">In effetti, in questo modo, ci stiamo preparando per trovare la giusta combinazione per Carnevale.<br \/>\nLa giusta cottura, il giusto dosaggio degli ingredienti anche perche&#8217;, negli ultimi 2 anni appena passati, tutti i miei tentativi sono miseramente falliti.<\/p>\n<p style=\"text-align: justify;\">Questa volta, ancora la Nonna Papera ci ha aiutato.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong><\/p>\n<pre>350gr di farina\r\n 3 uova\r\n 3 cucchiai di zucchero\r\n 3 cucchiai di vino bianco secco\r\n un pizzico di sale\r\n zucchero a velo<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">In una zuppiera disponete la farina a fontana.<br \/>\nNel centro ponete le uova intere, lo zucchero ed il sale.<\/p>\n<p>Mescolate ed impastate bene gli ingredienti aggiungendo poco alla volta il vino, lavorando prima con un cucchiaio di legno poi con le mani fino ad ottenere una palla di pasta omogenea.<\/p>\n<p>Sistematela sul piano del lavoro e stendetela con un mattarello, fino a ridurre la palla in uno strato sottile.<\/p>\n<p>Tagliatelo a strisce irregolari, larche 3-4 cm e lunghe 7-8.<\/p>\n<p>Preparate un tegame, meglio se dotato con manico lungo, dell&#8217;olio che farete scaldare a fuoco vivo.<br \/>\nQuando l&#8217;olio sara&#8217; bollente versate tante strisce di pasta quante ne puo&#8217; contenere la padella e toglietele quando le vedrete ben dorate.<\/p>\n<p>Appoggiatele man mano su un piatto ricoperto di carta assorbente in modo da perdere l&#8217;unto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7028\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0041.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0041.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0041-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0041-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p style=\"text-align: justify;\">Non ce l&#8217;ho fatta, ed anche questa volta le ho cotte al forno.<br \/>\nMagari la prossima finiranno in padella&#8230; chissa&#8217;..<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le chiacchere perche&#8217; vengono fatte solamente nel periodo di Carnevale?<\/p>\n","protected":false},"author":2,"featured_media":7028,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69],"tags":[122],"class_list":["post-1856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","tag-carnevale"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1856"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1856\/revisions"}],"predecessor-version":[{"id":10558,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1856\/revisions\/10558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/7028"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}