{"id":18555,"date":"2019-10-23T14:16:19","date_gmt":"2019-10-23T12:16:19","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=18555"},"modified":"2022-07-13T16:42:59","modified_gmt":"2022-07-13T14:42:59","slug":"porridge-alla-mela_airfryer","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/10\/23\/porridge-alla-mela_airfryer\/","title":{"rendered":"Porridge alla mela &#8211; in friggitrice ad aria"},"content":{"rendered":"<p style=\"text-align: justify;\">Per evitare di diventare monotematica parlando sempre delle virtu&#8217; della mia pentola a pressione, sono ritornata a preparare qualche cosuccia anche con la friggitrice ad aria.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Complice il libro preso in <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/10\/12\/barbara\/\">biblioteca<\/a><\/strong><\/em>, e poi regolarmente acquistata una copia, ci siamo cimentati nel cucinare qualche colazione particolare, gustosa e decisamente salutare: <strong>Porridge alla mela<\/strong> (anche se la ricetta originale prevedeve l&#8217;inserimento della zucca).<\/p>\n<figure id=\"attachment_18566\" aria-describedby=\"caption-attachment-18566\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-18566\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191014_071833-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191014_071833-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191014_071833-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191014_071833-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191014_071833-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18566\" class=\"wp-caption-text\">Porridge alla mela &#8211; in friggitrice ad aria<\/figcaption><\/figure>\n<p>Il libro si intitola &#8220;Das gesunde Airfryer-Kochbuch: 100 kreative Rezepte f\u00c3\u00bcr die Hei\u00c3\u0178luftfritteuse&#8221; di\u00c2\u00a0White, Dana Angelo<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Porridge alla mela <\/strong>&#8211; in friggitrice ad aria &#8211; 2 porzioni abbondanti<\/p>\n<pre>75gr di fiocchi di avena\r\n2 cucchiai di uvetta\r\n1 punta di cannella\r\n1 presa di sale\r\n110 gr di pure' di zucca (sostituito da mousse di mela)\r\n2 cucchiai di sciroppo d'acero\r\n230ml di latte<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Preriscaldate la friggitrice ad aria a 150gradi<\/p>\n<p style=\"text-align: justify;\">Unite i fiocchi d&#8217;avena, l&#8217;uvetta, la cannella ed il sale in una ciotola e mischiate.<br \/>\nAggiungete poi il pure (zucca, mela o quello che volete), lo sciroppo d&#8217;acero ed il latte, mischiando bene.<\/p>\n<p style=\"text-align: justify;\">Ungete leggermente il contenitore alto della friggitrice, inseriteci l&#8217;impasto e fate cuocere per 10 minuti.<\/p>\n<figure id=\"attachment_18567\" aria-describedby=\"caption-attachment-18567\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-18567\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191014_071031-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191014_071031-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191014_071031-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191014_071031-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191014_071031-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18567\" class=\"wp-caption-text\">Porridge alla mela &#8211; in friggitrice ad aria &#8211; cotto<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Al termine, aspettate 5 minuti prima di servire\/mangiare.<\/p>\n<figure id=\"attachment_18565\" aria-describedby=\"caption-attachment-18565\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-18565\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191014_071449-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191014_071449-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191014_071449-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191014_071449-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191014_071449-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18565\" class=\"wp-caption-text\">Porridge alla mela &#8211; in friggitrice ad aria<\/figcaption><\/figure>\n<p><span style=\"color: #ff0000;\">Un po\u00e2\u20ac\u2122 di calcoli ProPoints (del vecchio sistema WeightWatchers), con la ricetta originale<\/span><\/p>\n<p>7,5pp &#8211; 75gr di fiocchi di avena<br \/>\n2pp &#8211; 2 cucchiai di uvetta<br \/>\n0pp &#8211; 1 punta di cannella<br \/>\n0pp &#8211; 1 presa di sale<br \/>\n0pp &#8211; 110 gr di pure&#8217; di zucca<br \/>\n2pp &#8211; 2 cucchiai di sciroppo d&#8217;acero<br \/>\n1pp &#8211; 230ml di latte<\/p>\n<p><span style=\"color: #ff0000;\">12,6PP in totale, per 6,2 PP a persona (se si sceglie la porzione abbondante)<br \/>\n<\/span><\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per evitare di diventare monotematica parlando sempre delle virtu&#8217; della mia pentola a pressione, sono ritornata a preparare qualche cosuccia anche con la friggitrice ad aria.<\/p>\n","protected":false},"author":2,"featured_media":18565,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,22],"tags":[86,54,88,106,49],"class_list":["post-18555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-food","tag-friggitrice","tag-cereali","tag-frutta_secca","tag-ricetta_perfetta","tag-ww"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/18555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=18555"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/18555\/revisions"}],"predecessor-version":[{"id":30434,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/18555\/revisions\/30434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/18565"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=18555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=18555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=18555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}