{"id":18391,"date":"2019-10-04T12:37:44","date_gmt":"2019-10-04T10:37:44","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=18391"},"modified":"2022-01-23T17:20:00","modified_gmt":"2022-01-23T16:20:00","slug":"germania_schweinshaxe","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/10\/04\/germania_schweinshaxe\/","title":{"rendered":"# 1 &#8211; Repubblica Federale di Germania. Schweinshaxe &#8211; Stinco di maiale al forno"},"content":{"rendered":"<p style=\"text-align: justify;\">Ieri <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/10\/03\/3-10-wiedervereinigung\/\">3 ottobre<\/a><\/strong><\/em> era la giornata di riunificazione tedesca.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Stephan non ama andare all&#8217;Oktoberfest, Tobias non ci e&#8217; mai andato ed io\u00c2\u00a0 avevo pensato di festeggiare in qualche modo, magari con cibo tipico tedesco.<\/p>\n<figure id=\"attachment_31058\" aria-describedby=\"caption-attachment-31058\" style=\"width: 470px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31058\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/mappa-europa-capitali-e1619257906254.jpg\" alt=\"\" width=\"470\" height=\"410\" \/><figcaption id=\"caption-attachment-31058\" class=\"wp-caption-text\">Da Internet: Mappa dell&#8217;Europa con le capitali<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La scelta e&#8217; caduta sul famoso\/fatidico <strong>Schweinshaxe<\/strong> o &#8220;Stinco di maiale al forno&#8221;, ben conosciuto con questo nome in Italia.<\/p>\n<figure id=\"attachment_18399\" aria-describedby=\"caption-attachment-18399\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18399 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132751-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132751-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132751-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132751-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132751-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18399\" class=\"wp-caption-text\">Schweinshaxe &#8211; Stinco di maiale<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Se si cerca in Internet si possono trovare innumerevoli ricette, che spaziano dalla pentola a pressione alla griglia, dalla pre-cottura ad completa immersione in acqua bollente alla pre-cottura con solo un goccio di acqua, e chi piu&#8217; ne ha piu&#8217; ne metta.<\/p>\n<p style=\"text-align: justify;\">Come fare allora per non disperdersi in tutto questo mare di ricette??<br \/>\nCome fare a trovare quella veramente &#8220;originale&#8221; o che ci si avvina di piu&#8217;?<\/p>\n<p style=\"text-align: justify;\">Ho cosi&#8217; deciso di provarne solo una, affidandomi ad un libro imprestatomi da Barbara (in seguito vi diro&#8217; chi e&#8217;).. che si intitola, sorpresa sorpresa\u00c2\u00a0 &#8220;<strong>Bayerisches Kochbuch<\/strong>&#8221; e di cui vi scrivero&#8217; in seguito.<\/p>\n<p style=\"text-align: justify;\">La ricetta non e&#8217; molto complicata, ma abbastanza lunga per i tempi di cottura.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Schweinshaxe &#8211; Stinco di maiale al forno<\/strong><\/p>\n<pre>1,5kg stinco di maiale\r\nsale\r\npepe\r\npaprica\r\n250ml di acqua\r\n1 chiodo di garofano\r\n2 cipolle\r\n4 carote\r\nfoglie di salvia\r\nfoglie di alloro\r\nbirra<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Lavate ed asciugate bene lo stinco di maiale.<br \/>\nMassaggiate lo stinco con un mix di sale, pepe e paprica (facoltativa).<\/p>\n<figure id=\"attachment_18401\" aria-describedby=\"caption-attachment-18401\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18401 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_101435-1024x1024.jpg\" alt=\"\" width=\"525\" height=\"525\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_101435-1024x1024.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_101435-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_101435-300x300.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_101435-768x768.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_101435-100x100.jpg 100w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18401\" class=\"wp-caption-text\">Schweinshaxe &#8211; Stinco di maiale &#8211; mix per il massaggio<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Mettete a scaldare 250ml di acqua in un contenitore dove lo stinco possa starci comodamente, e con il suo relativo coperchio.<br \/>\nAl bollore, inserite lo stinco nella pentola\/padella e chiudete il coperchio, lasciando proseguire la carne nella cottura in acqua.<\/p>\n<figure id=\"attachment_18403\" aria-describedby=\"caption-attachment-18403\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18403 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_105054-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_105054-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_105054-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_105054-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_105054-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18403\" class=\"wp-caption-text\">Schweinshaxe &#8211; Stinco di maiale &#8211; Precottura in pentola<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Dopo circa 20minuti, la cotenna si sara&#8217; ammorbidita e potrete tagliarla a scacchi: in questo modo il grasso riuscira&#8217; ad uscire correttamente e la carne a cuocere bene ed insaporirsi.<br \/>\nL&#8217;operazione di &#8220;taglio&#8221; potrebbe essere fatta fare anticipatamente dal macellaio, come nel mio caso.<\/p>\n<figure id=\"attachment_18402\" aria-describedby=\"caption-attachment-18402\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18402 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_101452-e1570112981499-1024x1024.jpg\" alt=\"\" width=\"525\" height=\"525\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_101452-e1570112981499-1024x1024.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_101452-e1570112981499-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_101452-e1570112981499-300x300.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_101452-e1570112981499-768x768.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_101452-e1570112981499-100x100.jpg 100w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18402\" class=\"wp-caption-text\">Schweinshaxe &#8211; Stinco di maiale &#8211; tagli della carne<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">In caso di necessita&#8217;, aggiungete acqua calda, ma non sopra la carne.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-18397\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132325-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132325-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132325-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132325-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132325-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Accendete il forno a 200-220 gradi, statico.<\/p>\n<p style=\"text-align: justify;\">Dopo circa 25 minuti spegnete e passate la carne in forno.<\/p>\n<figure id=\"attachment_18405\" aria-describedby=\"caption-attachment-18405\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18405 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_105344-e1570112992920-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_105344-e1570112992920-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_105344-e1570112992920-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_105344-e1570112992920-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_105344-e1570112992920-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18405\" class=\"wp-caption-text\">Schweinshaxe &#8211; Stinco di maiale &#8211; in forno<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Io ho spostato la carne in un&#8217;altra pirofila (la mia cocotte) che avevo fatto precedentemente scaldare in forno.<br \/>\nUnite l&#8217;eventuale liquido della prima pentola (nel mio caso) e deglassate un poco.<br \/>\nAggiungete le carote, cipolle, chiodo di garofano, foglie di salvia ed alloro, aglio (facoltativo) ed altre erbe\/spezie a vostra scelta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-18404\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_104107-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_104107-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_104107-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_104107-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_104107-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<figure id=\"attachment_18396\" aria-describedby=\"caption-attachment-18396\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18396 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_131101-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_131101-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_131101-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_131101-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_131101-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18396\" class=\"wp-caption-text\">Schweinshaxe &#8211; Stinco di maiale &#8211; Spostamento in pentola per il forno<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Infornate il tutto e fate cuocere per almeno 1,5-2 ore.<\/p>\n<p style=\"text-align: justify;\">Nel frattempo bagnate la carne con il liquido che rilascia e, sempre all&#8217;occorrenza, aggiungete nuova acqua bollente.<\/p>\n<p style=\"text-align: justify;\">Circa 30minuti prima del termine della cottura, con un pennello pennellate la cotenna con la birra, cosi&#8217; da creare una crosta croccante.<\/p>\n<p style=\"text-align: justify;\">Sfornate, avvolgete la carne in alluminio e fatela rilassare qualche minuto, cosi&#8217; che i succhi si ridistribuiscano perfettamente.<\/p>\n<p style=\"text-align: justify;\">Nel frattempo dividete la verdura dal sugo.<br \/>\nFate addensare il sugo in un pentolino, io ho aggiunto della farina di carrube.<\/p>\n<p style=\"text-align: justify;\">Portate in tavola e servite.<\/p>\n<figure id=\"attachment_18398\" aria-describedby=\"caption-attachment-18398\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18398 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132800-e1570112965121-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132800-e1570112965121-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132800-e1570112965121-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132800-e1570112965121-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132800-e1570112965121-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18398\" class=\"wp-caption-text\">Schweinshaxe &#8211; Stinco di maiale<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Noi lo abbiamo accompagnato con del pure&#8217;, ma potreste affiancarlo con dei knodeln, semplici patate lessate, insalata mista, etc&#8230;<\/p>\n<figure id=\"attachment_18400\" aria-describedby=\"caption-attachment-18400\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18400 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132748-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132748-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132748-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132748-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/10\/IMG_20191003_132748-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18400\" class=\"wp-caption-text\">Schweinshaxe &#8211; Stinco di maiale<\/figcaption><\/figure>\n<p>Guten Appetit !<\/p>\n<p style=\"text-align: justify;\">PS: Lo so, se la tovaglia fosse stata a scacchi bianchi ed azzurri sarebbe stato meglio..<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ieri 3 ottobre era la giornata di riunificazione tedesca.<\/p>\n","protected":false},"author":2,"featured_media":19074,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,71,168,22,24,60],"tags":[176,236],"class_list":["post-18391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-contorni","category-europa","category-food","category-germania","category-secondi_piatti","tag-176","tag-europa_centrale"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/18391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=18391"}],"version-history":[{"count":14,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/18391\/revisions"}],"predecessor-version":[{"id":31068,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/18391\/revisions\/31068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/19074"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=18391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=18391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=18391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}