{"id":1839,"date":"2011-04-19T18:40:11","date_gmt":"2011-04-19T17:40:11","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/casa-aggiornamenti\/"},"modified":"2018-09-01T21:10:24","modified_gmt":"2018-09-01T20:10:24","slug":"casa-aggiornamenti","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2011\/04\/19\/casa-aggiornamenti\/","title":{"rendered":"Casa: aggiornamenti"},"content":{"rendered":"<p style=\"text-align: justify;\">Ora la nostra futura casa inizia ad avere un vero aspetto\u00c2\u00a0 &#8230;<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Non solo un semplice buco&#8230;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12475\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0663.jpg\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0663.jpg 400w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0663-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_0663-300x225.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p style=\"text-align: justify;\">Ma la strada per terminarla e&#8217; ancora lunga, chissa&#8217; se ce la faranno per questa estate?<\/p>\n<p style=\"text-align: justify;\">Io?<\/p>\n<p style=\"text-align: justify;\">Vorrei tanto iniziare ad impacchettare, almeno quanto non ci serve, ma non abbiamo piu&#8217; spazio in cantina, dato che e&#8217; ancora piena di scatole del trasporto precedente!<\/p>\n<p style=\"text-align: justify;\">Cosi&#8217; mi tocca aspettare&#8230; e non avro&#8217; tempo, gia&#8217; lo so&#8230;<\/p>\n<p style=\"text-align: justify;\">Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ora la nostra futura casa inizia ad avere un vero aspetto\u00c2\u00a0 &#8230;<\/p>\n","protected":false},"author":2,"featured_media":12475,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150],"tags":[156],"class_list":["post-1839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","tag-lavori"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1839"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1839\/revisions"}],"predecessor-version":[{"id":12476,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1839\/revisions\/12476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/12475"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}