{"id":18249,"date":"2019-09-22T10:08:21","date_gmt":"2019-09-22T09:08:21","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=18249"},"modified":"2025-02-22T12:47:06","modified_gmt":"2025-02-22T11:47:06","slug":"festa-tobias-2019","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/09\/22\/festa-tobias-2019\/","title":{"rendered":"Kristall Cake: Torta di Cristallo"},"content":{"rendered":"<p style=\"text-align: justify;\">Se vi ricordate, qualche giorno fa avevamo effettuato delle prove di cristallizzazione dello zucchero (leggi <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/09\/16\/prove-di-cristallizzazione\">qui<\/a><\/strong><\/em>)<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Diciamo che i risultati ottenuti non sono stati poi cosi&#8217; terribili, cosi&#8217; abbiamo deciso di continuare e creare i seguenti &#8220;cristalli colorati&#8221;, nella versione piu&#8217; semplice.<\/p>\n<figure id=\"attachment_18250\" aria-describedby=\"caption-attachment-18250\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18250 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_170948-e1568736222168-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_170948-e1568736222168-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_170948-e1568736222168-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_170948-e1568736222168-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_170948-e1568736222168-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18250\" class=\"wp-caption-text\">Cristalli di zucchero colorati &#8211; versione semplice<\/figcaption><\/figure>\n<p>I coloranti utilizzati sono questi, in polvere: non sono assolutamente difficili da miscelare ed il risultato e&#8217; soddisfacente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-18252\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_160801-e1568736210805-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_160801-e1568736210805-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_160801-e1568736210805-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_160801-e1568736210805-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_160801-e1568736210805-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Dopo tutte queste prove, e&#8217; stato il giorno del &#8220;dunque&#8221; e di iniziare a preparare per il compleanno di Tobias.<br \/>\nSi, sappiamo molto bene che e&#8217; nato ad agosto, ma festeggia con i suoi compagni (di classe e non) a settembre.<\/p>\n<p style=\"text-align: justify;\">Ho cosi&#8217; preparato 3 torte <strong>all&#8217;acqua gassata<\/strong>, prendendo la ricetta da <em><strong><a href=\"http:\/\/www.maicakes.it\/torta-con-lacqua-gassata\/\">Maicakes,<\/a><\/strong><\/em> per essere utilizzate come base e strati per la torta di compleanno.<\/p>\n<figure id=\"attachment_18251\" aria-describedby=\"caption-attachment-18251\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18251 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_170913-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_170913-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_170913-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_170913-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_170913-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18251\" class=\"wp-caption-text\">Torta all&#8217;acqua &#8211; raffreddamento<\/figcaption><\/figure>\n<p><strong>Ingredienti &#8211; Torta all&#8217;acqua gasata &#8211; 1 torta<br \/>\n<\/strong><\/p>\n<pre>3 uova\r\n200 g di zucchero\r\n230 g \u00c2\u00a0di farina\r\n100 g di olio di arachidi\r\n100 ml di acqua gassata\r\nvaniglia\r\n1 bustina di lievito per dolci<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Accendete il forno a 180 gradi.<br \/>\nMontate i tuorli con met\u00c3\u00a0 dose di zucchero e la vaniglia, a parte montate gli albumi con il restante zucchero.<br \/>\nAi tuorli montati unire l\u00e2\u20ac\u2122acqua gassata, unite la farina ed il lievito setacciati un po\u00e2\u20ac\u2122 alla volta cercando di non smontare il composto, unite l\u00e2\u20ac\u2122olio di semi ed in fine gli albumi montati.<br \/>\nInfornate per 30\/35 minuti.<\/p>\n<p style=\"text-align: justify;\">Con queste dosi usando una tortiera di diametro 22 cm potrete ottenere una torta alta 7\/8 cm.<\/p>\n<p style=\"text-align: justify;\"><strong>NOTA<\/strong>: La cottura e&#8217; durata un po&#8217; di piu&#8217;.<br \/>\nNon avevo mai preparato questa torta, e devo ammettere che cresce meravigliosamente!<\/p>\n<figure id=\"attachment_18254\" aria-describedby=\"caption-attachment-18254\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-18254\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_170857-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_170857-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_170857-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_170857-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190917_170857-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18254\" class=\"wp-caption-text\">Torta all&#8217;acqua gasata<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Dopo averle fatte raffreddare ben bene, sono state tagliate orizzontalmente. Logicamente questo lavoro di precisione NON lo ho fatto io, rifiutandomi, bensi&#8217; Stephan (il perfettino).<\/p>\n<p style=\"text-align: justify;\">Ho dovuto solamente assemblare il tutto, con creme diverse, per ottenere questo risultato&#8230; ma qui ci sono solamente 2 delle 3 torte&#8230;<br \/>\nGrazie al supporto di lunghi stuzzicadenti, mi sono aiutata a mantenere un minimo di equilibrio, sempre sperando nella stabilita&#8217; della costruzione.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-18286\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190918_153454-e1569080864433-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190918_153454-e1569080864433-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190918_153454-e1569080864433-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190918_153454-e1569080864433-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190918_153454-e1569080864433-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Dopo aver messo la &#8220;buttercreme&#8221; (crema al burro) che serve come &#8220;isolante&#8221; quanto ottenuto e&#8217; stato un mostruoso cilindro un po&#8217; storto\u00c2\u00a0 \ud83d\ude42<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-18285\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_135211-e1569080871954-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_135211-e1569080871954-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_135211-e1569080871954-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_135211-e1569080871954-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_135211-e1569080871954-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Ma la composizione non era ancora terminata!<\/p>\n<p style=\"text-align: justify;\">Abbiamo marmorizzato la Pasta di Zucchero, utilizzando il blu, bianco ed il nero.<br \/>\nSfortunatamente il nero era di una marca diversa e, anche se non esperta conoscitrice, non era decisamente il massimo della plasticita&#8217;. Tanto che, al termine, in molti punti &#8220;nero&#8221; la copertura si e&#8217; strappata.<\/p>\n<figure id=\"attachment_18275\" aria-describedby=\"caption-attachment-18275\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18275 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_161155-e1569080662744-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_161155-e1569080662744-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_161155-e1569080662744-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_161155-e1569080662744-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_161155-e1569080662744-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18275\" class=\"wp-caption-text\">Pasta di Zucchero &#8211; marmorizzazione<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Qui il ragazzo all&#8217;opera, cercando di rattoppare un buco.<br \/>\nEbbene si, anche se la torta era per lui, ho chiesto il suo supporto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-18276\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_172232-e1569080670406-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_172232-e1569080670406-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_172232-e1569080670406-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_172232-e1569080670406-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_172232-e1569080670406-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Ancora una volta Stephan ha dovuto &#8220;darci un taglio&#8221;&#8230;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-18277\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_193630-e1569080678685-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_193630-e1569080678685-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_193630-e1569080678685-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_193630-e1569080678685-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_193630-e1569080678685-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Beh, diciamo che non e&#8217; venuta cosi&#8217; male.<br \/>\nForse un po&#8217; troppo chiara, nonostante abbiamo cercato di colorare anche la crema al mascarpone fatta.<br \/>\nPer decisione del &#8220;festeggiato&#8221; non abbiamo usato cioccolato o altro, solamente cuna crema al limone ed una alla vaniglia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-18278\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_193949-e1569080687568-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_193949-e1569080687568-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_193949-e1569080687568-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_193949-e1569080687568-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_193949-e1569080687568-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">La prossima volta sara&#8217; meglio tentare di usare meno butter-creme e rendere la copertura ancora piu&#8217; sottile.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-18279\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_193955-e1569080694415-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_193955-e1569080694415-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_193955-e1569080694415-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_193955-e1569080694415-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_193955-e1569080694415-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Si e&#8217; poi passati alla fase finale, l&#8217;inserimento dei cristalli di zucchero.<br \/>\nAbbiamo disegnato un veloce schema, con il &#8220;cuore&#8221; piu&#8217; rosso, per poi progredire con un arancio, giallo e bianco.<\/p>\n<p style=\"text-align: justify;\">La fase per &#8220;attaccare&#8221; lo zucchero e&#8217; stata fatta con cautela ed attenzione, qualita&#8217; che mi mancano.<br \/>\nEcco perche&#8217; il ragazzo ha voluto &#8220;fare lui&#8221;&#8230;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-18280\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_201640-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_201640-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_201640-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_201640-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_201640-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Per poi ottenere una magnifica <strong>Torta Cristallo (KristallKuche)<\/strong>.<\/p>\n<figure id=\"attachment_18282\" aria-describedby=\"caption-attachment-18282\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18282 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_201703-e1569080703568-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_201703-e1569080703568-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_201703-e1569080703568-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_201703-e1569080703568-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/09\/IMG_20190920_201703-e1569080703568-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18282\" class=\"wp-caption-text\">Torta Cristallo &#8211; KristallKuche<\/figcaption><\/figure>\n<p>Grande soddisfazione per tutti.<\/p>\n<p>Qui potete trovare le altre ricette delle creme utilizzate:<\/p>\n<p><strong>Ingredienti &#8211; <a href=\"http:\/\/www.maicakes.it\/crema-al-burro\/\">Crema al burro<\/a><br \/>\n<\/strong><\/p>\n<pre>200 g di burro\r\n200 g di zucchero a velo\r\n3 cucchiai di latte<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Inserite in un recipiente capiente o meglio ancora in una planetaria lo zucchero a velo ed il burro a temperatura ambiente ed iniziate a montare prima a velocit\u00c3\u00a0 minima, inserite anche il latte e poi montate alla massima velocit\u00c3\u00a0 per almeno 5 minuti, il risultato deve essere una crema molto spumosa e bianchissima.<\/p>\n<p><em>Le piccole cose che fanno la differenza<\/em><\/p>\n<p style=\"text-align: justify;\">Il burro per montare bene e non formare grumi deve essere a temperatura ambiente, toglietelo dal frigorifero almeno 2 ore prima di fare la crema al burro, se vogliamo leggermente anticipare i tempi facciamolo a cubetti.<br \/>\nPer evitare grumi \u00c3\u00a8 sempre bene setacciare lo zucchero a velo.<\/p>\n<p style=\"text-align: justify;\">Indicativamente per una torta di diametro 22\/24 cm \u00c2\u00a0alta 8\/10 cm potremmo utilizzare circa 200\/250 g di crema al burro.<\/p>\n<p style=\"text-align: justify;\"><em><strong><a href=\"http:\/\/www.maicakes.it\/crema-mascarpone-per-farcitura\/\">Ingredienti &#8211; Crema al mascarpone per farcitura <\/a><\/strong><\/em><\/p>\n<pre>250 g di mascarpone\r\n 150 g di panna fresca da montare\r\n 100 g di zucchero a velo\r\n 1 bacca di vaniglia<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Unire tutti gli ingredienti in un recipiente capiente ed amalgamare bene con una forchetta o con una frusta poi montare con le fruste elettriche per circa 2minuti ed il gioco \u00c3\u00a8 fatto.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Ingredienti &#8211; Crema al limone ricetta facile <\/strong><\/em><\/p>\n<pre>buccia di 1 limone\r\nSucco di 1\/2 limone\r\n2 uova\r\n100 g di zucchero\r\n30 g di amido di mais\r\n1\/2 fialetta di aroma al limone<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Versate il latte in un pentolino, aggiungete la buccia di un limone e portate sul fuoco.<\/p>\n<p style=\"text-align: justify;\">A parte prendete un altro pentolino e rompete le uova, aggiungete lo zucchero e l&#8217;amido di mais. Iniziate a mescolare con una frusta amalgamando perfettamente tutti gli ingredienti.<br \/>\nQuando il latte \u00c3\u00a8 bollente eliminate la buccia del limone e lo versate a filo nel pentolino continuando a mescolare con la frusta.<br \/>\nPortate il pentolino sul fuoco e continuate a mescolare fino a quando la crema si addensa, ci vorranno 5 minuti circa.<br \/>\nSpegnete il fuoco.<br \/>\nSpremete il succo di mezzo limone e aggiungetelo alla crema.<\/p>\n<p>&#8230; e per quest&#8217;anno la torta e&#8217; stata fatta&#8230;<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se vi ricordate, qualche giorno fa avevamo effettuato delle prove di cristallizzazione dello zucchero (leggi qui)<\/p>\n","protected":false},"author":2,"featured_media":18276,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,22,79],"tags":[36,118],"class_list":["post-18249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-food","category-torte","tag-compleanno","tag-pdz"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/18249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=18249"}],"version-history":[{"count":10,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/18249\/revisions"}],"predecessor-version":[{"id":47471,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/18249\/revisions\/47471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/18276"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=18249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=18249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=18249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}