{"id":17938,"date":"2019-08-09T18:02:26","date_gmt":"2019-08-09T16:02:26","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=17938"},"modified":"2022-01-20T15:13:53","modified_gmt":"2022-01-20T14:13:53","slug":"francoforte-alcuni-spunti","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/08\/09\/francoforte-alcuni-spunti\/","title":{"rendered":"Francoforte: cosa vedere &#8211; alcuni spunti"},"content":{"rendered":"<p style=\"text-align: justify;\">Abbiamo deciso di prendere la metropolitana ed andare in centro a fare un giretto&#8230; e magari incontrare Francesca.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Anche se per poche stazioni, vale la pena acquistare il biglietto giornaliero che, comunque, permette di usufruire di tutti i mezzi di trasporto locale, senza limitazione.<\/p>\n<p>&nbsp;<\/p>\n<p>Abbiamo cosi&#8217; visto il Centro ( <em><strong>R\u00c3\u00b6merberg<\/strong><\/em> ), la piazza centrale e tradizionale di Francoforte, con i suoi edifici in stile germanico e poi ricostruiti dopo la seconda guerra mondiale.<br \/>\nGli edifici sono a traliccio e, nel centro della piazza, troviamo la fontana con la Dea della Giustizia.<\/p>\n<p>Veramente caratteristico e da visitare, magari perdendosi un pochino tra le viuzze.<\/p>\n<figure id=\"attachment_17945\" aria-describedby=\"caption-attachment-17945\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17945\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_101343-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_101343-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_101343-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_101343-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_101343-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17945\" class=\"wp-caption-text\">Francoforte &#8211; R\u00c3\u00b6merberg<\/figcaption><\/figure>\n<figure id=\"attachment_17949\" aria-describedby=\"caption-attachment-17949\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17949\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_101941-e1567085080183-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_101941-e1567085080183-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_101941-e1567085080183-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_101941-e1567085080183-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_101941-e1567085080183-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17949\" class=\"wp-caption-text\">Francoforte &#8211; Dea della Giustizia<\/figcaption><\/figure>\n<figure id=\"attachment_17953\" aria-describedby=\"caption-attachment-17953\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17953\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_102818-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_102818-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_102818-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_102818-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_102818-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17953\" class=\"wp-caption-text\">Francoforte &#8211; R\u00c3\u00b6merberg<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La vecchia chiesa medioevale di San Nicola ( <em><strong>Alte Nikolaikirche <\/strong><\/em>) dove alle 9, 12 e 17 si possono sentire suonare le 40 campane, si affaccia proprio sulla stessa piazza.<br \/>\nDecisamente e&#8217; d&#8217;obbligo fare un giro al suo interno&#8230; giusto per notare la semplicita&#8217; interna e le grandi vetrate colorate.<\/p>\n<figure id=\"attachment_17962\" aria-describedby=\"caption-attachment-17962\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17962\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_102145-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_102145-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_102145-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_102145-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_102145-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17962\" class=\"wp-caption-text\">Francoforte &#8211; Alte NikolaiKirche<\/figcaption><\/figure>\n<figure id=\"attachment_17963\" aria-describedby=\"caption-attachment-17963\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17963\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_102152-e1567086571669-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_102152-e1567086571669-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_102152-e1567086571669-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_102152-e1567086571669-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_102152-e1567086571669-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17963\" class=\"wp-caption-text\">Francoforte &#8211; Alte NikolaiKirche<\/figcaption><\/figure>\n<figure id=\"attachment_17964\" aria-describedby=\"caption-attachment-17964\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17964\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_103153-e1567086589871-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_103153-e1567086589871-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_103153-e1567086589871-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_103153-e1567086589871-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_103153-e1567086589871-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17964\" class=\"wp-caption-text\">Francoforte &#8211; Alte NikolaiKirche &#8211; Organo<\/figcaption><\/figure>\n<figure id=\"attachment_17965\" aria-describedby=\"caption-attachment-17965\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17965\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_103250-e1567086604894-1024x1024.jpg\" alt=\"\" width=\"525\" height=\"525\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_103250-e1567086604894-1024x1024.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_103250-e1567086604894-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_103250-e1567086604894-300x300.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_103250-e1567086604894-768x768.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_103250-e1567086604894-100x100.jpg 100w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17965\" class=\"wp-caption-text\">Francoforte &#8211; Alte NikolaiKirche &#8211; interno<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">E&#8217; sufficiente passeggiare vicino al centro cittadino, per assaporare altre immagini pittoresche&#8230; di vita e di arte.<br \/>\nSotto tutti i punti di vista.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17967\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_103933-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_103933-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_103933-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_103933-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_103933-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17968\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_104300-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_104300-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_104300-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_104300-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_104300-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17969\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_104415-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_104415-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_104415-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_104415-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_104415-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17970\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_105553-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_105553-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_105553-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_105553-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_105553-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<figure id=\"attachment_17972\" aria-describedby=\"caption-attachment-17972\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17972 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112218-e1567087422643-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112218-e1567087422643-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112218-e1567087422643-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112218-e1567087422643-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112218-e1567087422643-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17972\" class=\"wp-caption-text\">Francoforte &#8211; Fontana di Friedrich Stolze<\/figcaption><\/figure>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17973\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112439-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112439-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112439-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112439-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112439-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Non per ultimo visitiamo il Duomo ( <em><strong>Kaiserdom Sankt Bartholomaeus<\/strong><\/em> ), ossia la Cattedrale di questa citta&#8217;, con la sua torre campanaria e l&#8217;interno decorato.<\/p>\n<p style=\"text-align: justify;\">La chiesa \u00c3\u00a8 stata realizzata nel XIII secolo, ma nel tempo \u00c3\u00a8 stata pi\u00c3\u00b9 volta ricostruita a causa di incendi e dei bombardamenti della seconda guerra mondiale. E per questo l\u00e2\u20ac\u2122interno \u00c3\u00a8 piuttosto spoglio e anonimo.<br \/>\nNonostante il nome, non e&#8217; una cattedrale, ma al suo interno sono stati incoronati diversi imperatori.<\/p>\n<figure id=\"attachment_17975\" aria-describedby=\"caption-attachment-17975\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17975\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112707-e1567088135450-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112707-e1567088135450-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112707-e1567088135450-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112707-e1567088135450-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112707-e1567088135450-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17975\" class=\"wp-caption-text\">Francoforte &#8211; Dom St. Bartholom\u00c3\u00a4us<\/figcaption><\/figure>\n<figure id=\"attachment_17976\" aria-describedby=\"caption-attachment-17976\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17976\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112935-e1567088159885-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112935-e1567088159885-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112935-e1567088159885-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112935-e1567088159885-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_112935-e1567088159885-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17976\" class=\"wp-caption-text\">Francoforte &#8211; Dom St. Bartholom\u00c3\u00a4us<\/figcaption><\/figure>\n<figure id=\"attachment_17977\" aria-describedby=\"caption-attachment-17977\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17977\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_113112-e1567088176515-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_113112-e1567088176515-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_113112-e1567088176515-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_113112-e1567088176515-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_113112-e1567088176515-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17977\" class=\"wp-caption-text\">Francoforte &#8211; Dom St. Bartholom\u00c3\u00a4us<\/figcaption><\/figure>\n<figure id=\"attachment_17978\" aria-describedby=\"caption-attachment-17978\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17978\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_113311-e1567088189359-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_113311-e1567088189359-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_113311-e1567088189359-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_113311-e1567088189359-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_113311-e1567088189359-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17978\" class=\"wp-caption-text\">Francoforte &#8211; Dom St. Bartholom\u00c3\u00a4us<\/figcaption><\/figure>\n<figure id=\"attachment_17979\" aria-describedby=\"caption-attachment-17979\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17979\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_113853-e1567088203790-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_113853-e1567088203790-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_113853-e1567088203790-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_113853-e1567088203790-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_113853-e1567088203790-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17979\" class=\"wp-caption-text\">Francoforte &#8211; Dom St. Bartholom\u00c3\u00a4us<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">E&#8217; possibile anche salire sul campanile, logicamente a piedi, in quanto non esiste un ascensore: basta fare i 328 gradini per elevarsi di 66metri in altezza.<br \/>\nLa vista da lassu&#8217; e&#8217; ampia, nulla a confronto con la Main Tower sicuramente, ma pur sempre una grande veduta.<br \/>\nIl biglietto e&#8217; di 3euro per adulti, 1,5 per bambini.<\/p>\n<figure id=\"attachment_17985\" aria-describedby=\"caption-attachment-17985\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17985\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_111129-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_111129-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_111129-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_111129-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_111129-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17985\" class=\"wp-caption-text\">Francoforte &#8211; Dom St. Bartholom\u00c3\u00a4us &#8211; dalla Torre<\/figcaption><\/figure>\n<figure id=\"attachment_17986\" aria-describedby=\"caption-attachment-17986\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17986\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_111749-1024x1024.jpg\" alt=\"\" width=\"525\" height=\"525\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_111749-1024x1024.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_111749-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_111749-300x300.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_111749-768x768.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_111749-100x100.jpg 100w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17986\" class=\"wp-caption-text\">Francoforte &#8211; Dom St. Bartholom\u00c3\u00a4us &#8211; dalla Torre<\/figcaption><\/figure>\n<p>Sempre in centro, a pochi passi dal Roemerberg, troviamo un piccolo Museo gratuito, l&#8217; &#8220;<strong>Arch\u00c3\u00a4ologisches Museum Frankfurt<\/strong>&#8220;.<br \/>\nOnestamente non e&#8217; stato un gran che&#8230; ma essendo da quelle parti abbiamo comunque dato un&#8217;occhiata.<\/p>\n<figure id=\"attachment_17980\" aria-describedby=\"caption-attachment-17980\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17980 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_115908-e1567088806526-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_115908-e1567088806526-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_115908-e1567088806526-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_115908-e1567088806526-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_115908-e1567088806526-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17980\" class=\"wp-caption-text\">Francoforte: Arch\u00c3\u00a4ologisches Museum Frankfurt<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Poco distante troviamo la chiesa protestante di San Paolo ( <strong>PaulsKirche<\/strong> ) in mattoni rossi.<br \/>\nOramai e&#8217; sconsacrata, ma e&#8217; di grande importanza storica in quanto fu sede nel 1848 dell\u00e2\u20ac\u2122assemblea che cre\u00c3\u00b3 l\u00e2\u20ac\u2122odierna nazione.<br \/>\nE&#8217; di pianta circolare e prevalentemente bianca.<br \/>\nAl suo interno troviamo un grande archivio storico del periodo del dopoguerra.<br \/>\nInoltre c&#8217;e&#8217; anche una grossa sala, usata per conferenze.<\/p>\n<figure id=\"attachment_17955\" aria-describedby=\"caption-attachment-17955\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17955\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_120421_1-e1567085932456-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_120421_1-e1567085932456-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_120421_1-e1567085932456-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_120421_1-e1567085932456-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_120421_1-e1567085932456-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17955\" class=\"wp-caption-text\">Francoforte &#8211; PaulsKirche<\/figcaption><\/figure>\n<figure id=\"attachment_17956\" aria-describedby=\"caption-attachment-17956\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17956\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_120745-e1567085955306-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_120745-e1567085955306-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_120745-e1567085955306-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_120745-e1567085955306-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_120745-e1567085955306-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17956\" class=\"wp-caption-text\">Francoforte &#8211; PaulsKirche<\/figcaption><\/figure>\n<figure id=\"attachment_17957\" aria-describedby=\"caption-attachment-17957\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17957\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_121510-e1567085974383-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_121510-e1567085974383-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_121510-e1567085974383-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_121510-e1567085974383-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_121510-e1567085974383-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17957\" class=\"wp-caption-text\">Francoforte &#8211; PaulsKirche &#8211; Sala<\/figcaption><\/figure>\n<figure id=\"attachment_17958\" aria-describedby=\"caption-attachment-17958\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17958\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_121537-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_121537-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_121537-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_121537-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190809_121537-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17958\" class=\"wp-caption-text\">Francoforte &#8211; PaulsKirche &#8211; Sala<\/figcaption><\/figure>\n<p>.. e tanto altro ancora&#8230;.<\/p>\n<p>&nbsp;<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abbiamo deciso di prendere la metropolitana ed andare in centro a fare un giretto&#8230; e magari incontrare Francesca.<\/p>\n","protected":false},"author":2,"featured_media":17952,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,24,21],"tags":[26,255],"class_list":["post-17938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-germania","category-travel","tag-da_fare","tag-vacanze_2019"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/17938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=17938"}],"version-history":[{"count":15,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/17938\/revisions"}],"predecessor-version":[{"id":20724,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/17938\/revisions\/20724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/17952"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=17938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=17938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=17938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}