{"id":17934,"date":"2019-08-09T14:22:14","date_gmt":"2019-08-09T12:22:14","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=17934"},"modified":"2022-01-20T15:14:00","modified_gmt":"2022-01-20T14:14:00","slug":"francoforte-dove-mangiare","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/08\/09\/francoforte-dove-mangiare\/","title":{"rendered":"Francoforte: dove mangiare"},"content":{"rendered":"<p style=\"text-align: justify;\">Il dove mangiare a Francoforte non e&#8217; un problema per molti.<br \/>\nDiciamo che si mangia ovunque e si puo&#8217; spendere da pochi Euro a molti di piu&#8217;.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Noi ci siamo accontentati di andare nei seguenti locali, sia per fare veloce (il primo) che per assaporare la cucina tedesca di questa zona, con le sue piu&#8217; famose specialita&#8217; gastronomiche.<\/p>\n<p><strong>Nefis Kebap Haus<\/strong><br \/>\nMuenchener Str. 51<br \/>\n60329 Frankfurt am Main, Hessen,<\/p>\n<p style=\"text-align: justify;\">Abbiamo preso un piattone di Kebab, come potete vedere dalla foto, e ce lo siamo mangiato in due&#8230;<\/p>\n<figure id=\"attachment_17936\" aria-describedby=\"caption-attachment-17936\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17936\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190808_193525-e1567083499536-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190808_193525-e1567083499536-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190808_193525-e1567083499536-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190808_193525-e1567083499536-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190808_193525-e1567083499536-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17936\" class=\"wp-caption-text\">Francoforte &#8211; Nefis Kebap Haus<\/figcaption><\/figure>\n<p>Veramento buono, servizio veloce e cordiale.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;altro locale tipico da noi testato e&#8217; stato<\/p>\n<p><a href=\"http:\/\/www.apfelwein-wagner.com\"><em><strong>Apfelwein Wagner<\/strong><\/em><\/a><br \/>\nSchweizer Stra\u00c3\u0178e 71<br \/>\n60594 Frankfurt am Main, Hessen<\/p>\n<p>dove ho voluto provare il famoso &#8221; <em><strong>Apfelwein<\/strong><\/em> &#8221; con &#8221; <em><strong>Handkaese mit Musik<\/strong><\/em> &#8221;<\/p>\n<figure id=\"attachment_18005\" aria-describedby=\"caption-attachment-18005\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-18005\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_130615-e1567093088716-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_130615-e1567093088716-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_130615-e1567093088716-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_130615-e1567093088716-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_130615-e1567093088716-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18005\" class=\"wp-caption-text\">Francoforte &#8211; Apfelwein Wagner &#8211; Apfelwein<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">L&#8217; <em>Apfelwein<\/em> non e&#8217; altro che una bibita alcolica prodotta con la fermentazione della mela, praticamente un sidro di mele.<br \/>\nOnestamente non mi e&#8217; assolutamente piaciuta.<br \/>\nNon so bene se e&#8217; effettivamente questo sapore ma, personalmente, sapeva molto di tappo, forse troppo.<\/p>\n<figure id=\"attachment_18006\" aria-describedby=\"caption-attachment-18006\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-18006\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_130707-e1567093097761-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_130707-e1567093097761-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_130707-e1567093097761-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_130707-e1567093097761-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_130707-e1567093097761-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18006\" class=\"wp-caption-text\">Francoforte &#8211; Apfelwein Wagner<\/figcaption><\/figure>\n<p>Questa e&#8217; la &#8220;carnina&#8221; che si e&#8217; scrofanato il ragazzo. Tutta&#8230;<\/p>\n<figure id=\"attachment_18007\" aria-describedby=\"caption-attachment-18007\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-18007\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_131549-e1567093104980-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_131549-e1567093104980-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_131549-e1567093104980-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_131549-e1567093104980-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_131549-e1567093104980-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18007\" class=\"wp-caption-text\">Francoforte &#8211; Apfelwein Wagner<\/figcaption><\/figure>\n<p>E questo il mio piatto &#8221; <em>Handk\u00c3\u00a4se mit Musik<\/em> &#8221; .<\/p>\n<p style=\"text-align: justify;\">Handk\u00c3\u00a4se (&#8220;formaggio a mano&#8221;) \u00c3\u00a8 un formaggio di latte acido regionale tedesco ed \u00c3\u00a8 una specialit\u00c3\u00a0 culinaria di Francoforte sul Meno.<br \/>\nPrende il nome dal modo tradizionale di produrlo: formandolo con le proprie mani.<br \/>\n\u00c3\u02c6 un formaggio piccolo, traslucido, giallo con un aroma pungente che alcune persone possono trovare sgradevoli. A volte \u00c3\u00a8 quadrata, ma pi\u00c3\u00b9 spesso di forma rotonda.<br \/>\nSpesso servito come antipasto o come spuntino con sidro, \u00c3\u00a8 tradizionalmente condito con cipolle tritate,\u00c2\u00a0 localmente noto come &#8220;formaggio a mano con musica&#8221;. Di solito viene mangiato con cumino.<br \/>\nLa &#8220;musica&#8221;?\u00c2\u00a0\u00c2\u00a0 Solitamente arriva dopo, a seguito delle cipolle crude&#8230;<\/p>\n<figure id=\"attachment_18008\" aria-describedby=\"caption-attachment-18008\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-18008\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_131553-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_131553-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_131553-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_131553-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_131553-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18008\" class=\"wp-caption-text\">Francoforte &#8211; Apfelwein Wagner &#8211; Handk\u00c3\u00a4se mit Musik<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Giusto perche&#8217; era domenica, e festa, c&#8217;e&#8217; stato spazio anche per un dolcino (a testa, altrimenti non avrei assaggiato nulla&#8230;).<br \/>\nUna piccola fettina di Strudel di Mele, caldo, con salsa alla vaniglia.<br \/>\nDelizioso!<\/p>\n<figure id=\"attachment_18009\" aria-describedby=\"caption-attachment-18009\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-18009\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_140036-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_140036-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_140036-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_140036-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_140036-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18009\" class=\"wp-caption-text\">Francoforte &#8211; Apfelwein Wagner &#8211; Warmer Apfelstrudel mit Vanilleso\u00c3\u0178e<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Dalle recensioni lette precedentemente la scelta del locale, si diceva che il personale e&#8217; molto scorbutico.<br \/>\nNoi ci siamo trovati bene, senza alcun problema (o forse evitiamo di farcene dall&#8217;inizio ed accettiamo cio&#8217; che troviamo?).<\/p>\n<p>Inutile chiedere birra, tanto non ne hanno&#8230; \ud83d\ude09<\/p>\n<figure id=\"attachment_18010\" aria-describedby=\"caption-attachment-18010\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-18010\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_140234-e1567093115526-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_140234-e1567093115526-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_140234-e1567093115526-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_140234-e1567093115526-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_140234-e1567093115526-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18010\" class=\"wp-caption-text\">Francoforte &#8211; Apfelwein Wagner<\/figcaption><\/figure>\n<p>La foto non rende giustizia alla grandezza del locale, con tante sale sia esterne che interne.<br \/>\nDecisamente tipico.<\/p>\n<figure id=\"attachment_18011\" aria-describedby=\"caption-attachment-18011\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-18011\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_142319-e1567093125295-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_142319-e1567093125295-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_142319-e1567093125295-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_142319-e1567093125295-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/08\/IMG_20190810_142319-e1567093125295-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-18011\" class=\"wp-caption-text\">Francoforte &#8211; Apfelwein Wagner<\/figcaption><\/figure>\n<p>Alla prossima esperienza!<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il dove mangiare a Francoforte non e&#8217; un problema per molti. Diciamo che si mangia ovunque e si puo&#8217; spendere da pochi Euro a molti di piu&#8217;.<\/p>\n","protected":false},"author":2,"featured_media":18009,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,24,21],"tags":[28,255],"class_list":["post-17934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-germania","category-travel","tag-dove_mangiare","tag-vacanze_2019"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/17934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=17934"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/17934\/revisions"}],"predecessor-version":[{"id":20723,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/17934\/revisions\/20723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/18009"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=17934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=17934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=17934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}