{"id":1779,"date":"2011-10-07T18:40:10","date_gmt":"2011-10-07T17:40:10","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/muffins-salati\/"},"modified":"2021-10-19T18:14:34","modified_gmt":"2021-10-19T16:14:34","slug":"muffins-salati","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2011\/10\/07\/muffins-salati\/","title":{"rendered":"Muffins salati"},"content":{"rendered":"<p style=\"text-align: justify;\">Che cosa fare con i fantastici ciuffi delle carote?<!--more--><\/p>\n<p style=\"text-align: justify;\">Cerca di qua.. cerca di la&#8217;, ecco un&#8217;idea originale.<\/p>\n<figure id=\"attachment_7765\" aria-describedby=\"caption-attachment-7765\" style=\"width: 188px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7765\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/c-3.jpg\" alt=\"\" width=\"188\" height=\"268\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/c-3.jpg 188w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/c-3-105x150.jpg 105w\" sizes=\"auto, (max-width: 188px) 100vw, 188px\" \/><figcaption id=\"caption-attachment-7765\" class=\"wp-caption-text\">Presa da Internet<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Solitamente preparo i muffins dolci, non penso mai alla possibile opzione di farli salati.<\/p>\n<p style=\"text-align: justify;\">Cosi&#8217; escono tanti &#8220;bocconcini&#8221; salati ma gustosi che accompagnano una cena all&#8217;ultimo momento.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; <em><a href=\"https:\/\/www.elisabettativeron.com\/2009\/05\/100-carote.html\">Mini cakes (100 %) carote e gorgonzola<\/a><\/em> &#8211; per 6 pezzi:<\/strong><\/p>\n<pre>2 carote con i loro ciuffi\r\n100 gr di farina oo\r\n100 gr di gorgonzola\r\n1 uovo\r\n4 cucchiai di olio e.v.o. (+ 2 cucchiai per le carote)\r\nlatte q.b.\r\n1 cucchiaino raso di cremortartaro (o di lievito per torte salate)<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Pulite le carote e tagliatele a cubetti; lavate, asciugate bene e tritate i ciuffi.<\/p>\n<p style=\"text-align: justify;\">In una padella scaldate i due cucchiai di olio e fate rosolare la verdura, salate, coprite e fate cuocere per circa 20 minuti.<br \/>\nFate intiepidire.<\/p>\n<p style=\"text-align: justify;\">Portate il forno a 180\u00c2\u00b0.<\/p>\n<p style=\"text-align: justify;\">In una ciotola mescolate bene tutti gli ingredienti (incluse le carote), stemperando con poco latte se il composto risultasse troppo compatto.<\/p>\n<p style=\"text-align: justify;\">Il formaggio va tagliato a pezzetti in modo da farlo amalgamare pi\u00c3\u00b9 facilmente.<\/p>\n<p style=\"text-align: justify;\">Con questo composto riempite 6 pirottini per muffins e poneteli nell&#8217;apposito stampo.<\/p>\n<p style=\"text-align: justify;\">Infornate per 20 minuti, quindi sfornate e fate raffreddare su una gratella.<\/p>\n<p style=\"text-align: justify;\">Non avendo il gorgonzola, mi sono adeguata con mix tra philadelphia e emmentaler.<br \/>\nMa non sono stati assolutamente malvagi.<\/p>\n<p style=\"text-align: justify;\">Tanto che non sono riuscita neppure a fotografarli.. o meglio, ne avevo lasciati due per il giorno dopo ma quando sono andata a vedere erano spariti \ud83d\ude41<\/p>\n<p style=\"text-align: justify;\">E dallo stesso sito ho avuto un&#8217;altra ispirazione su come utilizzare degli altri &#8220;ciuffi&#8221; di carota.<\/p>\n<p>Perche&#8217;?<br \/>\nPerche&#8217; in cucina non si spreca nulla<\/p>\n<p>&nbsp;<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Che cosa fare con i fantastici ciuffi delle carote?<\/p>\n","protected":false},"author":2,"featured_media":7765,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[148,22],"tags":[],"class_list":["post-1779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antipasti","category-food"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1779"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1779\/revisions"}],"predecessor-version":[{"id":33694,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1779\/revisions\/33694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/7765"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}