{"id":1770,"date":"2011-10-27T18:40:09","date_gmt":"2011-10-27T17:40:09","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/nuovo-tag\/"},"modified":"2018-11-10T18:10:11","modified_gmt":"2018-11-10T17:10:11","slug":"nuovo-tag","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2011\/10\/27\/nuovo-tag\/","title":{"rendered":"Nuovo TAG"},"content":{"rendered":"<p style=\"text-align: justify;\">Dopo un anno di lavoro, prevalentemente svolto a casa, ho deciso di creare un nuovo tag &#8220;veloce&#8221; per tutti i cibi pre-cotti, pre-pronti, pre-fatti, pre-cucinati (da altri) che non aspettano altro di essere riscaldati (utilizzando varie fonti di calore: micro, fornello, forno).<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Lo so, sono delle &#8220;porcherie&#8221; ma molto spesso velocizzano i tempi.<br \/>\nSe riesco preparo qualche cosa in piu&#8217; (almeno un piatto) alla sera per il mezzogiorno successivo.<\/p>\n<p style=\"text-align: justify;\">Ma non sempre riesco a &#8220;salvare&#8221; questo pasto.<br \/>\nCapita che Stephan se lo faccia fuori lui&#8230;<br \/>\ned io ripiego sempre sul &#8220;veloce&#8221;&#8230; che non mi manca mai.<\/p>\n<p style=\"text-align: justify;\">E come potrebbe?<br \/>\nMi faccio affascinare e catturare dalle confezioni\u00c2\u00a0 \ud83d\ude09<\/p>\n<p>A breve altre preparazioni &#8220;veloci&#8221; e, a tempo, anche i post vecchi re-taggati<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo un anno di lavoro, prevalentemente svolto a casa, ho deciso di creare un nuovo tag &#8220;veloce&#8221; per tutti i cibi pre-cotti, pre-pronti, pre-fatti, pre-cucinati (da altri) che non aspettano altro di essere riscaldati (utilizzando varie fonti di calore: micro, fornello, forno).<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1770","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1770"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1770\/revisions"}],"predecessor-version":[{"id":13779,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1770\/revisions\/13779"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}