{"id":1755,"date":"2011-11-26T18:40:09","date_gmt":"2011-11-26T17:40:09","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/buillon-pur-knorr\/"},"modified":"2018-11-10T18:32:38","modified_gmt":"2018-11-10T17:32:38","slug":"buillon-pur-knorr","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2011\/11\/26\/buillon-pur-knorr\/","title":{"rendered":"Knorr: Buillon Pur"},"content":{"rendered":"<p style=\"text-align: justify;\">Ed ecco che cosa ho trovato per preparare, solitamente, la pastina a casa.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Tanto per sostituire il solito &#8220;dado o granulato&#8221; di carne o verdure.<\/p>\n<p style=\"text-align: justify;\">Si tratta di una confezione che contiene 6 piccoli contenitori monoporzione per preparare 500ml di brodo di verdure (nel mio caso).<\/p>\n<p style=\"text-align: justify;\">Che dire?<br \/>\nProbabilmente ho utilizzato meno acqua del previsto, ma il gusto al palato e&#8217; veramente salato.<\/p>\n<p style=\"text-align: justify;\">Si, si vedono delle minuscole (microscopiche) parti di vegetali (??) ma questo sono presenti anche nel dado granulato.<\/p>\n<p style=\"text-align: justify;\">Personalmente non vedo questa grossa differenza (ad eccezione del prezzo) con quello normale.<\/p>\n<p style=\"text-align: justify;\">Chiaro che, anche qui, si fa largo il glutammato di sodio che, personalmente, cerco di evitare il piu&#8217; possibile, per quanto possibile possa essere.<\/p>\n<figure id=\"attachment_13794\" aria-describedby=\"caption-attachment-13794\" style=\"width: 474px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13794\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/th-10.jpg\" alt=\"\" width=\"474\" height=\"474\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/th-10.jpg 474w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/th-10-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/th-10-300x300.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/th-10-100x100.jpg 100w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption id=\"caption-attachment-13794\" class=\"wp-caption-text\">Presa da Internet<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Per Informazioni (sito tedesco): provate a guardare <a href=\"https:\/\/www.knorr.com\/de\/home.html\"><em>qui<\/em><\/a>&#8230;<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ed ecco che cosa ho trovato per preparare, solitamente, la pastina a casa.<\/p>\n","protected":false},"author":2,"featured_media":13794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58,22],"tags":[],"class_list":["post-1755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosita","category-food"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1755"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1755\/revisions"}],"predecessor-version":[{"id":13795,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1755\/revisions\/13795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/13794"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}