{"id":1754,"date":"2011-11-28T18:40:09","date_gmt":"2011-11-28T17:40:09","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/wiener-schnitzel\/"},"modified":"2018-03-13T12:02:38","modified_gmt":"2018-03-13T11:02:38","slug":"wiener-schnitzel","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2011\/11\/28\/wiener-schnitzel\/","title":{"rendered":"Wiener schnitzel"},"content":{"rendered":"<p style=\"text-align: justify;\">Questo ricetta di &#8220;<strong>Wiener Schnitzel<\/strong>&#8221; e&#8217; appunto uno dei tanti segni che ho messo nel libro &#8220;<em>La parte piu&#8217; tenera<\/em>&#8221; &#8211; di Ruth Reichl -\u00c2\u00a0 ed ho voluto tentare nel cucinarla<\/p>\n<p style=\"text-align: justify;\"><!--more--><br \/>\nDa qualche parte bisogna iniziare, no?<\/p>\n<p style=\"text-align: justify;\">Questa e&#8217; la sua descrizione, cosi&#8217; come indicato dal libro, per 4 persone:<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong><\/p>\n<pre>700gr di cotolette di vitello disossate\r\n 50-60gr di farina\r\n 1 uovo\r\n sale, pepe\r\n 150gr di pangrattato molto fine\r\n 100gr di burro\r\n 1 limone<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Battete la carne tra 2 fogli di carta oleata finche&#8217; non sara&#8217; ben sottile<br \/>\nMettete la farina in un piatto fondo o in un vassoio abbastanza grande da contenere una cotoletta ben distesa.<br \/>\nIn un altro piatto fondo sbattete l&#8217;uovo.<br \/>\nIl pangrattato in un terzo piatto.<br \/>\nA ognuno di questi ingredienti mescolate sale e pepe.<\/p>\n<p style=\"text-align: justify;\">Una ad una, passate le cotolette nella farina, poi nell&#8217;uovo e da ultimo nel pangrattato finche&#8217; non saranno finemente ma completamente rivestite. Sistematele su un vassoio coperto da un foglio di carta oleata e mettete in frigo per circa un&#8217;ora.<\/p>\n<p style=\"text-align: justify;\">Fate sciogliere due terzi del burro in una grande padella.<br \/>\nQuando iniziera&#8217; a soffriggere, adagiatevi le cotolette e cuocetele per pochi minuti a fuoco vivace, facendole ben dorare su entrambi i lati, quindi accomodatele su un piatto da portata.<\/p>\n<p style=\"text-align: justify;\">Sciogliete il resto del burro nella stessa padella.<br \/>\nAggiungete al burro fuso il succo spremuto del limone e mescolate qualche istante, versate la salsa cosi&#8217; ottenuto sulle cotolette e servite<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questo ricetta di &#8220;Wiener Schnitzel&#8221; e&#8217; appunto uno dei tanti segni che ho messo nel libro &#8220;La parte piu&#8217; tenera&#8221; &#8211; di Ruth Reichl -\u00c2\u00a0 ed ho voluto tentare nel cucinarla<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,60],"tags":[],"class_list":["post-1754","post","type-post","status-publish","format-standard","hentry","category-carne","category-food","category-secondi_piatti"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1754"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1754\/revisions"}],"predecessor-version":[{"id":7935,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1754\/revisions\/7935"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}