{"id":17384,"date":"2019-07-11T13:14:09","date_gmt":"2019-07-11T12:14:09","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=17384"},"modified":"2019-07-26T13:47:52","modified_gmt":"2019-07-26T12:47:52","slug":"haar-aspettando","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/07\/11\/haar-aspettando\/","title":{"rendered":"Haar: Aspettando.."},"content":{"rendered":"<p style=\"text-align: justify;\">Haar \u00c3\u00a8 un comune tedesco con circa 20.0000 abitanti, situato nel Land della Baviera, e si trova vicino al mio Paesello.<br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\">Il comune \u00c3\u00a8 gemellato, dal 1983, con il comune italiano di Valle Aurina (Ahrntal) in provincia di Bolzano, Italia.<\/p>\n<p style=\"text-align: justify;\">Qui alcune foto mostrano il meraviglioso cielo bavarese (blue e bianco), durante l&#8217;attesa di Stephan&#8230;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17386\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120301-e1561575419199-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120301-e1561575419199-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120301-e1561575419199-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120301-e1561575419199-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120301-e1561575419199-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17391\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120521-e1561575452159-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120521-e1561575452159-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120521-e1561575452159-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120521-e1561575452159-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120521-e1561575452159-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Nelle vicinanze della VHS (la mia corrente scuola di tedesco), c&#8217;e&#8217; una piccola stanza chiusa, possiamo anche definirla &#8220;cripta&#8221; con questo oggetto al suo interno.<br \/>\nPenso sia stato dato\/offerto\/publicizzato (?) dallo Studio di Luci\/Illuminazione che si trova proprio al fianco di questa costruzione.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17388\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120337-e1561575433915-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120337-e1561575433915-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120337-e1561575433915-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120337-e1561575433915-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120337-e1561575433915-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17389\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120359-e1561575442391-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120359-e1561575442391-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120359-e1561575442391-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120359-e1561575442391-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190624_120359-e1561575442391-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Beh, al momento non so ancora di cosa si tratta veramente.<\/p>\n<p>Se qualcuno ha qualche idea&#8230;<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Haar \u00c3\u00a8 un comune tedesco con circa 20.0000 abitanti, situato nel Land della Baviera, e si trova vicino al mio Paesello.<\/p>\n","protected":false},"author":2,"featured_media":17385,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162,110],"tags":[],"class_list":["post-17384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dintorni","category-monaco"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/17384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=17384"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/17384\/revisions"}],"predecessor-version":[{"id":26981,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/17384\/revisions\/26981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/17385"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=17384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=17384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=17384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}