{"id":17364,"date":"2019-06-18T23:28:35","date_gmt":"2019-06-18T21:28:35","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=17364"},"modified":"2021-05-02T11:06:21","modified_gmt":"2021-05-02T09:06:21","slug":"garbagnate-pedrieu","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/06\/18\/garbagnate-pedrieu\/","title":{"rendered":"Garbagnate Mil.se: Pedrieu"},"content":{"rendered":"<p style=\"text-align: justify;\">Oggi e&#8217; il compleanno Nonno&#8230; e dei suoi 80 anni.<br \/>\nCome festeggiarlo al meglio?<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Sicuramente con un incontro con la famiglia che, per l&#8217;occasione, e&#8217; giunta da ogni parte per festeggiarlo.<\/p>\n<p style=\"text-align: justify;\">Abbiamo iniziato con una veloce colazione a base di brioches fresche, giusto per tenerci preparati alla cena (abbondante).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17581\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/07\/IMG_20190618_083356-e1562956823428-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/07\/IMG_20190618_083356-e1562956823428-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/07\/IMG_20190618_083356-e1562956823428-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/07\/IMG_20190618_083356-e1562956823428-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/07\/IMG_20190618_083356-e1562956823428-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Alla sera abbiamo portato il Nonno nel ristorante stabilito al &#8220;<em><strong>Pedrieu<\/strong><\/em>&#8221; ( <em>Imbuto<\/em> in dialetto milanese ) a Garbagnate Milanese.<br \/>\nIl significato viene anche simbolicamente indicato sul loro biglietto..decisamente in maniera molto originale..<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17674\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190720_161021-e1563631905747-1024x1024.jpg\" alt=\"\" width=\"525\" height=\"525\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190720_161021-e1563631905747-1024x1024.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190720_161021-e1563631905747-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190720_161021-e1563631905747-300x300.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190720_161021-e1563631905747-768x768.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190720_161021-e1563631905747-100x100.jpg 100w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">La scelta del posto era stata demandata a Roberto\/Olja che, nei mesi precedenti, si sono dovuti sacrificare nel testare diversi posti, prima di arrivare a questa soluzione.<\/p>\n<figure id=\"attachment_17478\" aria-describedby=\"caption-attachment-17478\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17478\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_193927-e1562264997239-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_193927-e1562264997239-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_193927-e1562264997239-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_193927-e1562264997239-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_193927-e1562264997239-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17478\" class=\"wp-caption-text\">Garbagnate: Pedrieu<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Il Nonno e&#8217; stato portato praticamente all&#8217;oscuro della destinazione, tanto che pensava di andare a mangiare al ristorante cinese&#8230; \ud83d\ude42<\/p>\n<p style=\"text-align: justify;\">Che cosa dire del posto?<br \/>\nLocation fantastica, il locale non e&#8217; molto grande, ma dispone di un&#8217;accogliente giardino interno che, con il caldo milanese, ci ha rinfrescato piacevolmente.<\/p>\n<p style=\"text-align: justify;\">Il cibo, ottimo, e&#8217; stato accompagnato da un vinello delizioso&#8230;<br \/>\nPer non parlare del personale, cordiale, disponibile e che ci ha &#8220;sopportato&#8221; sino alla fine&#8230; nonostante un bicchiere rotto (immediatamente appena seduti) e con tutte le nostre richieste particolari.<\/p>\n<p style=\"text-align: justify;\">L&#8217;atmosfera familiare ci ha resi ancora piu&#8217; ciarlieri e piu&#8217; In famiglia&#8221; di quanto potessimo essere di gia&#8217;.<\/p>\n<figure id=\"attachment_17479\" aria-describedby=\"caption-attachment-17479\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17479\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_201012-e1562264990899-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_201012-e1562264990899-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_201012-e1562264990899-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_201012-e1562264990899-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_201012-e1562264990899-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17479\" class=\"wp-caption-text\">Garbagnate: Pedrieu &#8211; tagliere misto<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ma ora, bando alle ciance, gustatevi questa carrellata di foto&#8230;<br \/>\nRoberto, se leggi, fammi sapere il nome dei piatti, cosi&#8217; da poterli descrivere meglio!<\/p>\n<figure id=\"attachment_17480\" aria-describedby=\"caption-attachment-17480\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17480\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_201229-e1562264981880-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_201229-e1562264981880-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_201229-e1562264981880-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_201229-e1562264981880-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_201229-e1562264981880-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17480\" class=\"wp-caption-text\">Garbagnate: Pedrieu<\/figcaption><\/figure>\n<figure id=\"attachment_17481\" aria-describedby=\"caption-attachment-17481\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17481\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_204819-e1562264957845-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_204819-e1562264957845-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_204819-e1562264957845-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_204819-e1562264957845-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_204819-e1562264957845-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17481\" class=\"wp-caption-text\">Garbagnate: Pedrieu<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Questa la nostra fiorentina&#8230; che ci siamo sbranati in 3, velocemente e senza troppi rimpianti..<\/p>\n<figure id=\"attachment_17482\" aria-describedby=\"caption-attachment-17482\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17482\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_204925-e1562264973351-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_204925-e1562264973351-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_204925-e1562264973351-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_204925-e1562264973351-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_204925-e1562264973351-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17482\" class=\"wp-caption-text\">Garbagnate: Pedrieu &#8211; fiorentina<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">E qui, potete vedere quanto rimasto della fiorentina, cotta alla brace sulla fiamma a vista<\/p>\n<figure id=\"attachment_17483\" aria-describedby=\"caption-attachment-17483\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17483\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_210629-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_210629-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_210629-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_210629-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_210629-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17483\" class=\"wp-caption-text\">Garbagnate: Pedrieu &#8211; fiorentina (quello che resta)<\/figcaption><\/figure>\n<figure id=\"attachment_17484\" aria-describedby=\"caption-attachment-17484\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17484\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_210652-e1562264945318-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_210652-e1562264945318-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_210652-e1562264945318-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_210652-e1562264945318-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_210652-e1562264945318-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17484\" class=\"wp-caption-text\">Garbagnate: Pedrieu<\/figcaption><\/figure>\n<figure id=\"attachment_17485\" aria-describedby=\"caption-attachment-17485\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17485\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_210735-e1562264938860-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_210735-e1562264938860-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_210735-e1562264938860-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_210735-e1562264938860-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_210735-e1562264938860-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17485\" class=\"wp-caption-text\">Garbagnate: Pedrieu<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">E&#8217; arrivato poi il momento dell&#8217;apertura dei regali e dei biglietti<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17486\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_214953-e1562264922250-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_214953-e1562264922250-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_214953-e1562264922250-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_214953-e1562264922250-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_214953-e1562264922250-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17487\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_215032-e1562264912224-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_215032-e1562264912224-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_215032-e1562264912224-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_215032-e1562264912224-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_215032-e1562264912224-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17488\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_215122-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_215122-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_215122-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_215122-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_215122-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Grazie <strong>Silvia<\/strong>, la &#8220;badante&#8221;, che ci ha permesso di rendere questa serata ancora piu&#8217; piacevole grazie al suo aiuto e simpatia.<\/p>\n<figure id=\"attachment_17489\" aria-describedby=\"caption-attachment-17489\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17489\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_215659-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_215659-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_215659-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_215659-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_215659-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17489\" class=\"wp-caption-text\">Garbagnate: Pedrieu<\/figcaption><\/figure>\n<figure id=\"attachment_17490\" aria-describedby=\"caption-attachment-17490\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17490\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_220308-e1562264876710-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_220308-e1562264876710-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_220308-e1562264876710-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_220308-e1562264876710-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_220308-e1562264876710-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17490\" class=\"wp-caption-text\">Garbagnate: Pedrieu<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Nonostante il Ristorante abbia i dolci, noi abbiamo portato una torta preparata dalla &#8220;mitica&#8221;<strong> pasticceria di Via Mac Mahon<\/strong>.<br \/>\nDiciamocelo pure, una tra le migliori pasticcerie che abbia mai provato, e che mi ha accompagnato per tutta la mia giovinezza e fanciullezza.<\/p>\n<figure id=\"attachment_17491\" aria-describedby=\"caption-attachment-17491\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17491\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_220348-e1562264863611-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_220348-e1562264863611-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_220348-e1562264863611-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_220348-e1562264863611-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_220348-e1562264863611-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17491\" class=\"wp-caption-text\">Garbagnate: Pedrieu<\/figcaption><\/figure>\n<figure id=\"attachment_17492\" aria-describedby=\"caption-attachment-17492\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-17492\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_221019-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_221019-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_221019-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_221019-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/06\/IMG_20190618_221019-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-17492\" class=\"wp-caption-text\">Compleanno Nonno<\/figcaption><\/figure>\n<p>Che altro posso aggiungere?<br \/>\nSperiamo di replicare la cena un&#8217;altra volta, senza dover aspettare altri 80anni!<\/p>\n<p>Auguri ancora, Nonno!<\/p>\n<p><strong>Per Informazioni<\/strong><\/p>\n<p><strong>Pedrieu<\/strong><br \/>\nVia Conciliazione 17<br \/>\n20024 Garbagnate Milanese<br \/>\nItalia<\/p>\n<p><strong>Pasticceria MacMahon<\/strong><br \/>\nVia Dei Frassini 31 | ang. via Macmahon<br \/>\n20156 Milano<br \/>\nItalia<\/p>\n<p>&nbsp;<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi e&#8217; il compleanno Nonno&#8230; e dei suoi 80 anni. Come festeggiarlo al meglio?<\/p>\n","protected":false},"author":2,"featured_media":17492,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[36,28,47],"class_list":["post-17364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life","tag-compleanno","tag-dove_mangiare","tag-lombardia"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/17364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=17364"}],"version-history":[{"count":11,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/17364\/revisions"}],"predecessor-version":[{"id":31499,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/17364\/revisions\/31499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/17492"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=17364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=17364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=17364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}