{"id":1717,"date":"2012-03-17T18:40:08","date_gmt":"2012-03-17T17:40:08","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/focaccia-sorelle-simili\/"},"modified":"2021-03-23T11:21:00","modified_gmt":"2021-03-23T10:21:00","slug":"focaccia-sorelle-simili","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2012\/03\/17\/focaccia-sorelle-simili\/","title":{"rendered":"Sorelle Simili: Focaccia"},"content":{"rendered":"<p style=\"text-align: justify;\">Nello stesso libro &#8220;<strong>Pane e roba dolce<\/strong>&#8221; delle <strong>Sorelle Simili,<\/strong> dove ho trovato e preparato con discreto successo le mie pizze, ho preso anche la ricetta della focaccia.<!--more--><\/p>\n<p style=\"text-align: justify;\">Qui a Patatolandia la pizza, se la cerchi bene, la trovi.<br \/>\nEd e&#8217; anche buona.<br \/>\nMa la focaccia no, per quella ti devi affidare a quella pre-confezionata o fare dei giri nei negozi turchi.<\/p>\n<p style=\"text-align: justify;\">Cosi&#8217; ci ho tentato.<\/p>\n<p style=\"text-align: justify;\">Non so ancora bene dove abbia sbagliato, dato che le Sorelle spiegano il procedimento in una maniera cosi&#8217; semplice che e&#8217; impossibile incappare in qualche errore&#8230;<\/p>\n<p style=\"text-align: justify;\">Ma la sottoscritta c&#8217;e&#8217; riuscita nel toppare qualche cosa.<\/p>\n<p style=\"text-align: justify;\">E per ben due volte!<\/p>\n<p style=\"text-align: justify;\">Invece di ottenere e pregustarsi una focaccia alta e soffice, si e&#8217; trovata con una &#8220;schiaccia toscana&#8221;.<br \/>\nNon che mi sia dispiaciuto&#8230; ma la mia acquolina in bocca era orientata diversamente.<\/p>\n<p>Per entrambi i miei tentativi, ho usato mezza dose.<\/p>\n<figure id=\"attachment_8485\" aria-describedby=\"caption-attachment-8485\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-8485\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_3811-1024x768.jpg\" alt=\"\" width=\"525\" height=\"394\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_3811-1024x768.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_3811-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_3811-300x225.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_3811-768x576.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_3811.jpg 1600w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-8485\" class=\"wp-caption-text\">Focaccia.. Sorelle Simili<\/figcaption><\/figure>\n<p>Questa e&#8217; la ricetta originale delle Sorelle Simili<\/p>\n<p><strong>Ingredienti<\/strong><\/p>\n<pre>1kg farina 00\r\n550 g d'acqua\r\n20 g lievito di birra\r\n20 g sale\r\n2 cucchiai olio di oliva\r\n\r\n<strong>Per spennellare<\/strong>\r\n\r\n6 cucchiai olio\r\n6 cucchiai d'acqua<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">In una ciotola fondete il lievito con una parte dell&#8217;acqua, poi unite un poco di farina, 2 cucchiai d&#8217;olio d&#8217;oliva, sale e ancora la rimanente farina e acqua in due riprese alternandole e sempre battendo l&#8217;impasto.<\/p>\n<p style=\"text-align: justify;\">Mettete sul tavolo e lavorate battendo per 7-8 minuti, rimettete nella ciotola unta d&#8217;olio e fate raddoppiare<\/p>\n<p style=\"text-align: justify;\">Rovesciate di nuovo sul tavolo e formate due filoni, che verranno appoggiati su due teglie di cm 30X40.<br \/>\nFate riposare per altri 15 minuti poi spianate con un corto mattarello e con il palmo della mano sino a ricoprire quasi totalmente il fondo delle teglie.<\/p>\n<p style=\"text-align: justify;\">Se si vuole \u00c3\u00a8 possibile anche spianare i filoni subito messi nelle teglie ma, occorrer\u00c3\u00a0 uno sforzo maggiore nella pasta appena lavorata il glutine \u00c3\u00a8 pi\u00c3\u00b9 vivace e offre una maggior resistenza.<\/p>\n<p style=\"text-align: justify;\">Fare infine lievitare per 30 minuti.<\/p>\n<p>A questo punto non vi resta che infornare.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nello stesso libro &#8220;Pane e roba dolce&#8221; delle Sorelle Simili, dove ho trovato e preparato con discreto successo le mie pizze, ho preso anche la ricetta della focaccia.<\/p>\n","protected":false},"author":2,"featured_media":8485,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105,22,90],"tags":[116],"class_list":["post-1717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-focaccia","category-food","category-lievitati","tag-ldb"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1717"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1717\/revisions"}],"predecessor-version":[{"id":29650,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1717\/revisions\/29650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/8485"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}