{"id":1692,"date":"2012-04-24T18:40:07","date_gmt":"2012-04-24T17:40:07","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/nuovi-lavori\/"},"modified":"2018-09-01T20:34:30","modified_gmt":"2018-09-01T19:34:30","slug":"nuovi-lavori","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2012\/04\/24\/nuovi-lavori\/","title":{"rendered":"Nuovi lavori"},"content":{"rendered":"<p style=\"text-align: justify;\">Qui non si sta mai fermi.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Qui non ci si gratta la pancia neppure durante le ferie<br \/>\nQui ci si muove sempre.. chi maualmente e chi mentalmente (come la sottoscritta\u00c2\u00a0 ;)\u00c2\u00a0 )<\/p>\n<p style=\"text-align: justify;\">Questo e&#8217; un altro piccolo lavoro che era sulla lista e che ora e&#8217; quasi compiuto&#8230;. la messa in posa di alcune piastrelle in cantina, per evitare gli schizzi di acqua.<\/p>\n<p style=\"text-align: justify;\">\nChissa&#8217; che altro riusciro&#8217; ad estrarre dal cilindro magico???<\/p>\n<figure id=\"attachment_12442\" aria-describedby=\"caption-attachment-12442\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12442 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_4161.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_4161.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_4161-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_4161-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><figcaption id=\"caption-attachment-12442\" class=\"wp-caption-text\">Un dettaglio<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">\nDurante la costruzione della casa, ne avevamo fatto richiesta, ma ci avevano suggerito un lavandino normale.<br \/>\nE no, la sottoscritta si e&#8217; opposta (oltre a costare maggiormente, non era quello che voleva vedere e.. utilizzare).<\/p>\n<p>E&#8217; andata a finire che abbiamo acquistato un lavatoio in Italian e trafugato qui a Patatolandia.<\/p>\n<p style=\"text-align: justify;\">Cosi&#8217; ho spedito il Nonno all&#8217;acquisto del suddetto lavatoio e, durante un suo viaggio, lo ha portato sino a noi (senza contare la permanenza &#8220;forzata&#8221; del lavatoio a casa dei suoceri, dove ha sostato per parecchi mesi..).<\/p>\n<p style=\"text-align: justify;\">Poi e&#8217; stata la volta della ricerca dell&#8217;idraulico che lo installasse.<br \/>\nMi sono sentita un po&#8217; come Fede che porta i soldi in Svizzera per depositarli ed il _categorico_rifiuto_ delle banche.<br \/>\nEbbene, la sensazione e&#8217; stata la stessa quando chiedevo se qualche idraulico me avesse montato o installato.<br \/>\nAvrei ANCHE pagato la persona.<br \/>\nMa non c&#8217;e&#8217; stato nulla da fare.<br \/>\nCosi&#8217; il Povero Stephan lo ha fatto lui.<\/p>\n<figure id=\"attachment_12441\" aria-describedby=\"caption-attachment-12441\" style=\"width: 240px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12441 size-full\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_4154.jpg\" alt=\"\" width=\"240\" height=\"320\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_4154.jpg 240w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_4154-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_4154-225x300.jpg 225w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><figcaption id=\"caption-attachment-12441\" class=\"wp-caption-text\">Stephan mentre contempla il suo operato..<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Con mia grande fellicita&#8217; (anche se ha messo una piastrella storta non importa, la teniamo cosi&#8217; come &#8220;tocco personale&#8221;).<\/p>\n<p style=\"text-align: justify;\">Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qui non si sta mai fermi.<\/p>\n","protected":false},"author":2,"featured_media":12442,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150],"tags":[156],"class_list":["post-1692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","tag-lavori"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1692"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1692\/revisions"}],"predecessor-version":[{"id":12494,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1692\/revisions\/12494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/12442"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}