{"id":1683,"date":"2012-05-09T18:40:06","date_gmt":"2012-05-09T17:40:06","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/spadellata-di-verdure\/"},"modified":"2018-04-03T19:34:49","modified_gmt":"2018-04-03T18:34:49","slug":"spadellata-di-verdure","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2012\/05\/09\/spadellata-di-verdure\/","title":{"rendered":"Spadellata di verdure"},"content":{"rendered":"<p style=\"text-align: justify;\">Ecco un&#8217;idea veloce si avete delle verdure in frigo e non sapete come utilizzarle&#8230;<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Tagliate delle carote e saltatele per 3 minuti con goccio di olio (giusto per ammorbidirle).<\/p>\n<p style=\"text-align: justify;\">Aggiungete delle patate a tocchetti.<br \/>\nSfumate il tutto con brodo vegetale per 5 minuti.<br \/>\nAggiungete le cipolle ed i funghi tagliati a pettettini.<\/p>\n<p style=\"text-align: justify;\">Coprite con altro brodo vegetale, aggiustate di sale e pepe e lasciato cuocere circa 20-25 minuti<\/p>\n<p style=\"text-align: justify;\">A fine cottura, spolverare con prezzemolo (meglio fresco)<\/p>\n<p>&nbsp;<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ecco un&#8217;idea veloce si avete delle verdure in frigo e non sapete come utilizzarle&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,22],"tags":[49],"class_list":["post-1683","post","type-post","status-publish","format-standard","hentry","category-contorni","category-food","tag-ww"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1683"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1683\/revisions"}],"predecessor-version":[{"id":4581,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1683\/revisions\/4581"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}