{"id":16438,"date":"2020-02-12T13:42:00","date_gmt":"2020-02-12T12:42:00","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=16438"},"modified":"2020-02-08T18:42:29","modified_gmt":"2020-02-08T17:42:29","slug":"la-pupazza-di-frascati","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/02\/12\/la-pupazza-di-frascati\/","title":{"rendered":"La Pupazza di Frascati"},"content":{"rendered":"<p style=\"text-align: justify;\">Ecco la famosa &#8220;<strong>Pupazza<\/strong>&#8221; di Frascati, la &#8220;formosa&#8221; bonta&#8217; frascatena acquistata durante i miei giorni trascorsi a MontePorzio Catone (Roma) .<br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\">Ma di cosa si tratta?<br \/>\nSicuramente l&#8217;immagine e&#8217; decisamente curiosa, cosa ne pensate?<\/p>\n<p>La ricetta della bambolina al miele con tre seni \u00c3\u00a8 un vera istituzione della tradizione dei Castelli Romani ed evoca una curiosa leggenda del folklore locale.<\/p>\n<figure id=\"attachment_20594\" aria-describedby=\"caption-attachment-20594\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20594 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200208_135201-e1581183420373-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200208_135201-e1581183420373-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200208_135201-e1581183420373-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200208_135201-e1581183420373-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200208_135201-e1581183420373-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20594\" class=\"wp-caption-text\">La Pupazza di Frascati<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">\u00c3\u02c6 un semplice prodotto dolciario a base di miele millefiori dell\u00e2\u20ac\u2122Agro Pontino, farina tipo 00, olio extravergine di oliva e aroma distillato all\u00e2\u20ac\u2122arancia.<br \/>\nLa <strong>Pupazza frascatana<\/strong> \u00c3\u00a8 un dolce tradizionale di <strong>Frascati<\/strong>, riconosciuto come Prodotto Agroalimentare Tradizionale laziale.<\/p>\n<p style=\"text-align: justify;\">In origine preparata a Natale, la Pupazza Frascatana \u00c3\u00a8 un biscotto dalle fattezze femminili, realizzato a stampo, con 3 seni scoperti e pronunciati.<br \/>\nLa sua storia inizia negli anni \u00e2\u20ac\u02dc60, quasi per gioco, ma nel giro di pochi anni \u00c3\u00a8 divenuto un vero e proprio simbolo di Frascati e dei <strong>Castelli Romani<\/strong> in genere. La donna rappresentata, o meglio la balia che, in passato, custodiva i bambini delle donne impegnate nella vendemmia, \u00c3\u00a8 una formosa castellana, con le braccia sui fianchi e le gambe incrociate, a mo\u00e2\u20ac\u2122 di ballerina sulle punte. Qualcuno dice che, anticamente, i neonati della zona fossero allattati anche con il vino; altri trovano che la pupazza voglia rievocare la dea dell\u00e2\u20ac\u2122abbondanza.<br \/>\nL\u00e2\u20ac\u2122unica verit\u00c3\u00a0 certa \u00c3\u00a8 che i tre seni, due per il latte e uno per il vino, sottolineano il ruolo centrale del vino nei Castelli Romani.<\/p>\n<figure id=\"attachment_20595\" aria-describedby=\"caption-attachment-20595\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20595 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200208_135228-e1581183427909-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200208_135228-e1581183427909-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200208_135228-e1581183427909-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200208_135228-e1581183427909-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200208_135228-e1581183427909-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20595\" class=\"wp-caption-text\">La Pupazza di Frascati<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Si tratta di un biscottone tipico dell&#8217;area dei Castelli Romani e della citt\u00c3\u00a0 di Frascati, in particolare, dove lo si pu\u00c3\u00b2 trovare in vendita in alcuni forni ed in qualche bar pasticceria, oltre che presso lo storico Bar degli Specchi, sul corso principale della citt\u00c3\u00a0, che ne vende versioni fatte anche di ceramica.<br \/>\nLa &#8220;pupazza&#8221;, nel corso degli anni, \u00c3\u00a8 diventato un vero e proprio simbolo di Frascati e della ricchezza del suo territorio, in particolare dei suoi vigneti, che danno uve con cui vengono prodotti vini famosi in tutto il mondo. Per questo la donnina-mostacciolo \u00c3\u00a8 rappresentata con tre mammelle: due per il latte ed una per il vino!<br \/>\nEssendo praticamente un mostacciolo, la &#8220;pupazza&#8221; si conserva benissimo per diverso tempo, ed incartata in fogli di cellophane pu\u00c3\u00b2 trasformarsi in un simpatico dono. La presenza del miele fa s\u00c3\u00ac che il biscotto appena fatto sia molto duro: non preoccupatevi, si ammorbidir\u00c3\u00a0 poi nei giorni successivi.<\/p>\n<p style=\"text-align: justify;\">Sebbene il nome pi\u00c3\u00b9 accreditato sia Pupazza Frascatana, c\u00e2\u20ac\u2122\u00c3\u00a8 anche chi la chiama Pupazza a Tre Seni di Frascati, chi \u00e2\u20ac\u02dcA Pupazza de M\u00c3\u00a8l&#8217; o chi, pi\u00c3\u00b9 semplicemente, Miss Frascati.<\/p>\n<p style=\"text-align: justify;\">Questa deliziosa e procace donnina si \u00c3\u00a8 trasformata negli anni in un prodotto particolarmente rappresentativo della cittadina che si affaccia su Roma. Tanto che, alcuni artigiani della zona ne hanno realizzato varianti \u00e2\u20ac\u0153non commestibili\u00e2\u20ac\u009d in metallo e ceramica da conservare come ricordo.<\/p>\n<figure id=\"attachment_20596\" aria-describedby=\"caption-attachment-20596\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20596 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200208_135244-1024x1024.jpg\" alt=\"\" width=\"525\" height=\"525\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200208_135244-1024x1024.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200208_135244-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200208_135244-300x300.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200208_135244-768x768.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200208_135244-100x100.jpg 100w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-20596\" class=\"wp-caption-text\">La Pupazza di Frascati<\/figcaption><\/figure>\n<p>{ si tratta di un vecchio post, che non so come era rimasto in archivio e non pubblicato }<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ecco la famosa &#8220;Pupazza&#8221; di Frascati, la &#8220;formosa&#8221; bonta&#8217; frascatena acquistata durante i miei giorni trascorsi a MontePorzio Catone (Roma) .<\/p>\n","protected":false},"author":2,"featured_media":20596,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78,58,22,25],"tags":[133],"class_list":["post-16438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biscotti","category-curiosita","category-food","category-italia","tag-lazio"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/16438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=16438"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/16438\/revisions"}],"predecessor-version":[{"id":20599,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/16438\/revisions\/20599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/20596"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=16438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=16438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=16438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}