{"id":1637,"date":"2012-08-03T18:40:05","date_gmt":"2012-08-03T17:40:05","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/schupfnudeln\/"},"modified":"2024-09-21T17:28:17","modified_gmt":"2024-09-21T15:28:17","slug":"schupfnudeln","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2012\/08\/03\/schupfnudeln\/","title":{"rendered":"Schupfnudeln: pasta di patate"},"content":{"rendered":"<p style=\"text-align: justify;\">Non i soliti gnocchi questa volta!<\/p>\n<p style=\"text-align: justify;\"><!--more--><br \/>\nMa qualche prodotto fresco dalla diversa forma&#8230;. ecco gli<\/p>\n<p style=\"text-align: center;\"><strong> Schupfnudel<\/strong>!<\/p>\n<figure id=\"attachment_8238\" aria-describedby=\"caption-attachment-8238\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8238\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5127.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5127.jpg 640w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5127-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5127-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-8238\" class=\"wp-caption-text\">Schupfnudeln<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Naturalmente per questa volta li ho acquistati gia&#8217; pronti, solo da cuocere.<br \/>\nMagari un giorno provero&#8217;\u00c2\u00a0 a farli a casa, scovando la ricetta in qualche archivio Patatolese.<\/p>\n<figure id=\"attachment_8237\" aria-describedby=\"caption-attachment-8237\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8237\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5126.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5126.jpg 640w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5126-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5126-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-8237\" class=\"wp-caption-text\">Schupfnudeln<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ma cosa sono, effettivamente, questi &#8220;Schupfnudeln&#8221;?<\/p>\n<p style=\"text-align: justify;\">Da http:\/\/www.bavieraturismo.it si legge..<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Dalle patate lessate e schiacciate nasce una pasta a forma di dito, che, con l\u00e2\u20ac\u2122aggiunta di noce moscata, uova e spezie, si trasforma in una prelibata specialit\u00c3\u00a0 sveva: le Schupfnudeln.<br \/>\nQuesto piatto dall\u00e2\u20ac\u2122origine contadina pu\u00c3\u00b2 accompagnarsi alla selvaggina o essere servito da solo, insieme a crauti e insalata.<br \/>\nLa versione dessert, invece, con aggiunta di pur\u00c3\u00a8 di mele, chiude un pasto in dolcezza.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Ma la mitica Wikipedia fornisce maggiori informazioni a riguardo.<\/p>\n<p style=\"text-align: justify;\">Ed io, cosa ho preparato?<br \/>\nAnche se la parte principale del piatto riguarda il condimento, io li ho cucinati veramente in modo molto semplice: saltati direttamente in padella ed aromatizzati con burro (poco!) e salvia.<br \/>\nProprio alla versione &#8220;italiana&#8221;, vista come piatto unico.<br \/>\nE non come accompagnamento<\/p>\n<figure id=\"attachment_8236\" aria-describedby=\"caption-attachment-8236\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8236\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5128.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5128.jpg 640w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5128-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5128-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-8236\" class=\"wp-caption-text\">Schupfnudeln<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Potete ancora vedere le foglioline decorative ,)<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non i soliti gnocchi questa volta!<\/p>\n","protected":false},"author":2,"featured_media":8236,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,76,51],"tags":[],"class_list":["post-1637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pasta","category-primi_piatti"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1637"}],"version-history":[{"count":7,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1637\/revisions"}],"predecessor-version":[{"id":46232,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1637\/revisions\/46232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/8236"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}