{"id":1603,"date":"2012-09-28T18:40:04","date_gmt":"2012-09-28T17:40:04","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/il-pane-piu-buono-del-mondo\/"},"modified":"2018-11-15T18:06:14","modified_gmt":"2018-11-15T17:06:14","slug":"il-pane-piu-buono-del-mondo","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2012\/09\/28\/il-pane-piu-buono-del-mondo\/","title":{"rendered":"&#8220;Il pane piu&#8217; buono del mondo&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\">cosi&#8217; e&#8217; stato definito da Tobias sia in fase di preparazione che nella post-cottura&#8230;<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\"><strong>il pane piu&#8217; buono del Mondo.<\/strong><\/p>\n<p style=\"text-align: justify;\">E dire che lui non ne mangia mai!<\/p>\n<p style=\"text-align: justify;\">Ho voluto utilizzare la restante farina che avevo gia&#8217; utilizzato <em><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2012\/09\/10\/focaccia-rustica\/\">qui<\/a><\/em> (&#8220;<strong>Molino Spadoni &#8211; Pane Nero ai Cereali<\/strong>&#8220;).<\/p>\n<p style=\"text-align: justify;\">Non avendo due forme simili, ho messo l&#8217;impasto lievitato direttamente in una forma di torta, cosi&#8217; e&#8217; stato poi facile la sua estrazione.<br \/>\nE non ho avuto ulteriori problemi con il calcolo della cottura, essendo in una singola infornata.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14154\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5440.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5440.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5440-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_5440-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p style=\"text-align: justify;\">Che dire?<br \/>\nMio figlio mi ha commosso!<\/p>\n<p style=\"text-align: justify;\">ma sicuramente acquistero&#8217; nuovamente questa farina!!<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>cosi&#8217; e&#8217; stato definito da Tobias sia in fase di preparazione che nella post-cottura&#8230;<\/p>\n","protected":false},"author":2,"featured_media":14154,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,90,91],"tags":[],"class_list":["post-1603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-lievitati","category-pane"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1603"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1603\/revisions"}],"predecessor-version":[{"id":14155,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1603\/revisions\/14155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/14154"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}