{"id":1597,"date":"2012-10-06T18:40:04","date_gmt":"2012-10-06T17:40:04","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/knorr-activ-broccolicreme-suppe\/"},"modified":"2018-02-23T14:43:32","modified_gmt":"2018-02-23T13:43:32","slug":"knorr-activ-broccolicreme-suppe","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2012\/10\/06\/knorr-activ-broccolicreme-suppe\/","title":{"rendered":"Knorr Activ &#8211; Broccolicreme Suppe"},"content":{"rendered":"<p>ok, lo ammetto.<\/p>\n<p><!--more--><\/p>\n<p>Voglia di cucinare &#8220;saltami addosso&#8221;.<br \/>\nSoprattutto in questo periodo,\u00c2\u00a0 con Tobias che non ha intenzione di mangiare molto (sorpresa..sorpresa.. e quando mai)?<\/p>\n<p>Abbiamo appena passato la fase gnocchi-al-pesto, ritornando alla pasta-al-pomodoro.<\/p>\n<p>Perche&#8217; dunque sbattermi piu&#8217; di tanto?<\/p>\n<p>Almeno per me, a pranzo, risolvo il dilemma con le innumerevoli schifezze disponibili:\u00c2\u00a0 precotte, liofilizzate, di facile preparazione, subito pronte, pulizia degli utensili veloce!<\/p>\n<p>In questo particolare caso, ho provato la &#8220;Knorr Activ &#8211; BroccolicremeSuppe&#8221;.<br \/>\nNon e&#8217; proprio cosi&#8217; terribile..<\/p>\n<p>Sono un genio, le conosco TUTTE!!!<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ok, lo ammetto.<\/p>\n","protected":false},"author":2,"featured_media":3675,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,51,57],"tags":[],"class_list":["post-1597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-primi_piatti","category-zuppa"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=1597"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1597\/revisions"}],"predecessor-version":[{"id":3677,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/1597\/revisions\/3677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/3675"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=1597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=1597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=1597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}